{"id":493,"date":"2018-09-19T11:35:14","date_gmt":"2018-09-19T09:35:14","guid":{"rendered":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?p=493"},"modified":"2023-02-02T15:44:39","modified_gmt":"2023-02-02T14:44:39","slug":"visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/","title":{"rendered":"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto."},"content":{"rendered":"<p>Il truck dell\u2019Asl in Piazza Generale Branco.<br \/>\nFino alle 18:00 i medici dell\u2019 azienda sanitaria locale effettueranno visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto.<\/p>\n<div class=\"video-embed\"><iframe loading=\"lazy\" title=\"Prevenzione\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/tWZxCGEOqRg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-494\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/063C934E-3D70-4DE0-AED3-F0DE51E3AB48-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/063C934E-3D70-4DE0-AED3-F0DE51E3AB48-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/063C934E-3D70-4DE0-AED3-F0DE51E3AB48-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/063C934E-3D70-4DE0-AED3-F0DE51E3AB48-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/063C934E-3D70-4DE0-AED3-F0DE51E3AB48-680x510.jpeg 680w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/063C934E-3D70-4DE0-AED3-F0DE51E3AB48.jpeg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-495\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/E36D5300-9A6D-43FD-84FB-EFBA50D543D7-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/E36D5300-9A6D-43FD-84FB-EFBA50D543D7-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/E36D5300-9A6D-43FD-84FB-EFBA50D543D7-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/E36D5300-9A6D-43FD-84FB-EFBA50D543D7-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/E36D5300-9A6D-43FD-84FB-EFBA50D543D7-680x510.jpeg 680w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/E36D5300-9A6D-43FD-84FB-EFBA50D543D7.jpeg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-496\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/C79407D0-4694-4481-9BA7-414F851CE563-300x201.jpeg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/C79407D0-4694-4481-9BA7-414F851CE563-300x201.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/C79407D0-4694-4481-9BA7-414F851CE563-768x515.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/C79407D0-4694-4481-9BA7-414F851CE563-1024x686.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/C79407D0-4694-4481-9BA7-414F851CE563-680x456.jpeg 680w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/C79407D0-4694-4481-9BA7-414F851CE563.jpeg 1194w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-497\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/F457B579-3090-4824-984D-2AD6E14E60E5-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/F457B579-3090-4824-984D-2AD6E14E60E5-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/F457B579-3090-4824-984D-2AD6E14E60E5-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/F457B579-3090-4824-984D-2AD6E14E60E5-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/F457B579-3090-4824-984D-2AD6E14E60E5-680x510.jpeg 680w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/F457B579-3090-4824-984D-2AD6E14E60E5.jpeg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-498\" src=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1-300x225.jpeg 300w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1-768x576.jpeg 768w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1-680x510.jpeg 680w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1-800x600.jpeg 800w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1-600x450.jpeg 600w, https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg 1067w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il truck dell\u2019Asl in Piazza Generale Branco. Fino alle 18:00 i medici dell\u2019 azienda sanitaria locale effettueranno visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e [&hellip;]<\/p>\n","protected":false},"author":398,"featured_media":498,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto. - Cancello ed Arnone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto. - Cancello ed Arnone\" \/>\n<meta property=\"og:description\" content=\"Il truck dell\u2019Asl in Piazza Generale Branco. Fino alle 18:00 i medici dell\u2019 azienda sanitaria locale effettueranno visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/\" \/>\n<meta property=\"og:site_name\" content=\"Cancello ed Arnone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-19T09:35:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T14:44:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin_E\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin_E\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/\"},\"author\":{\"name\":\"Admin_E\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"headline\":\"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto.\",\"datePublished\":\"2018-09-19T09:35:14+00:00\",\"dateModified\":\"2023-02-02T14:44:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/\"},\"wordCount\":54,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2018\\\/09\\\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/\",\"name\":\"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto. - Cancello ed Arnone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2018\\\/09\\\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg\",\"datePublished\":\"2018-09-19T09:35:14+00:00\",\"dateModified\":\"2023-02-02T14:44:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2018\\\/09\\\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2018\\\/09\\\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg\",\"width\":1067,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/2018\\\/09\\\/19\\\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/\",\"name\":\"Cancello ed Arnone\",\"description\":\"ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/#\\\/schema\\\/person\\\/eaea9f1aebcbd61eb9878e6232bd2a03\",\"name\":\"Admin_E\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g\",\"caption\":\"Admin_E\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/cancello-ed-arnone\\\/author\\\/oollppcancelloarnone\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto. - Cancello ed Arnone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/","og_locale":"it_IT","og_type":"article","og_title":"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto. - Cancello ed Arnone","og_description":"Il truck dell\u2019Asl in Piazza Generale Branco. Fino alle 18:00 i medici dell\u2019 azienda sanitaria locale effettueranno visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e [&hellip;]","og_url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/","og_site_name":"Cancello ed Arnone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-09-19T09:35:14+00:00","article_modified_time":"2023-02-02T14:44:39+00:00","og_image":[{"width":1067,"height":800,"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg","type":"image\/jpeg"}],"author":"Admin_E","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Admin_E"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/"},"author":{"name":"Admin_E","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"headline":"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto.","datePublished":"2018-09-19T09:35:14+00:00","dateModified":"2023-02-02T14:44:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/"},"wordCount":54,"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/","name":"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto. - Cancello ed Arnone","isPartOf":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg","datePublished":"2018-09-19T09:35:14+00:00","dateModified":"2023-02-02T14:44:39+00:00","author":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/#primaryimage","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg","contentUrl":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-content\/uploads\/sites\/28\/2018\/09\/160D7C57-4343-42D5-AA50-D848AFB7B1F1.jpeg","width":1067,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/2018\/09\/19\/visite-gratuite-per-la-prevenzione-al-carcinoma-alla-mammella-alla-cervice-uterina-e-al-colon-retto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cancello-ed-arnone\/"},{"@type":"ListItem","position":2,"name":"Visite gratuite per la prevenzione al carcinoma alla mammella, alla cervice uterina e al colon retto."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#website","url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/","name":"Cancello ed Arnone","description":"ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cancello-ed-arnone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cancello-ed-arnone\/#\/schema\/person\/eaea9f1aebcbd61eb9878e6232bd2a03","name":"Admin_E","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1eb418f243a360a5c118e205c4f1d666c009a9fac37301044747eacb4938b467?s=96&d=mm&r=g","caption":"Admin_E"},"url":"https:\/\/comunicacity.net\/cancello-ed-arnone\/author\/oollppcancelloarnone\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/users\/398"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/comments?post=493"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/493\/revisions"}],"predecessor-version":[{"id":499,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/posts\/493\/revisions\/499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media\/498"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/media?parent=493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/categories?post=493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cancello-ed-arnone\/wp-json\/wp\/v2\/tags?post=493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}