{"id":109,"date":"2017-02-07T14:52:28","date_gmt":"2017-02-07T13:52:28","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=109"},"modified":"2017-02-07T14:52:28","modified_gmt":"2017-02-07T13:52:28","slug":"gipsy-telesoccorso-e-teleassistenza-per-gli-anziani","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/","title":{"rendered":"GIPSY &#8211; TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI"},"content":{"rendered":"<p>Il Comune di Capranica, a seguito di una serie di azioni mirate che rientrano in una pi\u00f9 ampia indagine sociale, ha individuato otto situazioni cosiddette a rischio nella popolazione anziana. Per determinare questi casi si \u00e8 fatto ricorso ad alcuni parametri. I soggetti interessati sono anziani soli, non autonomi negli spostamenti, con patologie importanti e con basso reddito.<\/p>\n<p><strong>Queste persone, a partire dai primi giorni di gennaio 2017, grazie ad una convenzione stipulata con <a href=\"http:\/\/www.lineaperta.com\/\">LINEAPERTA srl<\/a>, sono state dotate di un apparecchio di <em>Teleassistenza<\/em>, da tenere al collo o in tasca, che permette loro di attivare una chiamata di <em>Telesoccorso<\/em>. Lo strumento \u00e8 dotato anche di geolocalizzatore.<\/strong><\/p>\n<p>Il dispositivo fornito \u00e8 in grado di connettersi a una <strong>Centrale Operativa, attiva 24 ore su 24, 365 giorni l\u2019anno, semplicemente premendo un pulsante.<\/strong> Qui il segnale viene immediatamente identificato cosicch\u00e9 il personale qualificato possa entrare subito in azione.<\/p>\n<p>Infine l\u2019assistenza prevede un contatto costante con l\u2019anziano il quale riceve settimanalmente, dallo stesso operatore, una \u201ctelefonata di compagnia\u201d. L\u2019addetto si accerta delle condizioni di salute del soggetto ricordandogli le modalit\u00e0 di utilizzo dell\u2019apparecchio stesso. Tutto ci\u00f2 attiva un rapporto di fiducia e aumenta la famigliarit\u00e0 dell\u2019anziano con il dispositivo, garantendone un efficace utilizzo in caso di effettiva necessit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Capranica, a seguito di una serie di azioni mirate che rientrano in una pi\u00f9 ampia indagine sociale, ha individuato otto situazioni cosiddette a rischio nella popolazione anziana. [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":110,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GIPSY - TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GIPSY - TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI - Capranica\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Capranica, a seguito di una serie di azioni mirate che rientrano in una pi\u00f9 ampia indagine sociale, ha individuato otto situazioni cosiddette a rischio nella popolazione anziana. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-07T13:52:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/COVER-ANZIANI.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"GIPSY &#8211; TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI\",\"datePublished\":\"2017-02-07T13:52:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/\"},\"wordCount\":212,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/COVER-ANZIANI.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/\",\"name\":\"GIPSY - TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/COVER-ANZIANI.jpg\",\"datePublished\":\"2017-02-07T13:52:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/COVER-ANZIANI.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/COVER-ANZIANI.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/02\\\/07\\\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GIPSY &#8211; TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIPSY - TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/","og_locale":"it_IT","og_type":"article","og_title":"GIPSY - TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI - Capranica","og_description":"Il Comune di Capranica, a seguito di una serie di azioni mirate che rientrano in una pi\u00f9 ampia indagine sociale, ha individuato otto situazioni cosiddette a rischio nella popolazione anziana. [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-02-07T13:52:28+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/COVER-ANZIANI.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"GIPSY &#8211; TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI","datePublished":"2017-02-07T13:52:28+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/"},"wordCount":212,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/COVER-ANZIANI.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/","url":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/","name":"GIPSY - TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/COVER-ANZIANI.jpg","datePublished":"2017-02-07T13:52:28+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/COVER-ANZIANI.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/COVER-ANZIANI.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2017\/02\/07\/gipsy-telesoccorso-e-teleassistenza-per-gli-anziani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"GIPSY &#8211; TELESOCCORSO E TELEASSISTENZA PER GLI ANZIANI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=109"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/109\/revisions"}],"predecessor-version":[{"id":111,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/109\/revisions\/111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/110"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}