{"id":1263,"date":"2017-11-27T17:00:56","date_gmt":"2017-11-27T16:00:56","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=1263"},"modified":"2017-11-27T14:41:40","modified_gmt":"2017-11-27T13:41:40","slug":"bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/","title":{"rendered":"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL&#8217;IMPOSTA SULLE PUBBLICIT\u00c0"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Il Comune di Capranica ha pubblicato il <strong>bando di gara <\/strong>per l\u2019<strong>affidamento in concessione del servizio di accertamento e riscossione dell\u2019imposta comunale sulla pubblicit\u00e0 e del servizio di pubbliche affissioni<\/strong> dal 1 gennaio 2018 al 31 dicembre 2020.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Le domande dovranno pervenire <strong>entro le ore 12:00 del 1 dicembre 2017<\/strong>.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Per tutte le informazioni visita il <a href=\"http:\/\/www.comune.capranica.vt.it\/interna.asp?idPag=701\">sito del Comune di Capranica<\/a>.<\/span><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1265\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/11\/bando-affissioni.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/11\/bando-affissioni.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Bando Affissioni<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Capranica ha pubblicato il bando di gara per l\u2019affidamento in concessione del servizio di accertamento e riscossione dell\u2019imposta comunale sulla pubblicit\u00e0 e del servizio di pubbliche affissioni [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":1264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL&#039;IMPOSTA SULLE PUBBLICIT\u00c0 - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL&#039;IMPOSTA SULLE PUBBLICIT\u00c0 - Capranica\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Capranica ha pubblicato il bando di gara per l\u2019affidamento in concessione del servizio di accertamento e riscossione dell\u2019imposta comunale sulla pubblicit\u00e0 e del servizio di pubbliche affissioni [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-27T16:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/11\/COPERTINA-BANDO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL&#8217;IMPOSTA SULLE PUBBLICIT\u00c0\",\"datePublished\":\"2017-11-27T16:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/\"},\"wordCount\":70,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/11\\\/COPERTINA-BANDO.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/\",\"name\":\"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL'IMPOSTA SULLE PUBBLICIT\u00c0 - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/11\\\/COPERTINA-BANDO.jpg\",\"datePublished\":\"2017-11-27T16:00:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/11\\\/COPERTINA-BANDO.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/11\\\/COPERTINA-BANDO.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/11\\\/27\\\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL&#8217;IMPOSTA SULLE PUBBLICIT\u00c0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL'IMPOSTA SULLE PUBBLICIT\u00c0 - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/","og_locale":"it_IT","og_type":"article","og_title":"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL'IMPOSTA SULLE PUBBLICIT\u00c0 - Capranica","og_description":"Il Comune di Capranica ha pubblicato il bando di gara per l\u2019affidamento in concessione del servizio di accertamento e riscossione dell\u2019imposta comunale sulla pubblicit\u00e0 e del servizio di pubbliche affissioni [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-11-27T16:00:56+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/11\/COPERTINA-BANDO.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL&#8217;IMPOSTA SULLE PUBBLICIT\u00c0","datePublished":"2017-11-27T16:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/"},"wordCount":70,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/11\/COPERTINA-BANDO.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/","url":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/","name":"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL'IMPOSTA SULLE PUBBLICIT\u00c0 - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/11\/COPERTINA-BANDO.jpg","datePublished":"2017-11-27T16:00:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/11\/COPERTINA-BANDO.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/11\/COPERTINA-BANDO.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2017\/11\/27\/bando-di-gara-per-affidamento-del-servizio-di-accertamento-e-riscossione-dellimposta-sulle-pubblicita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"BANDO DI GARA PER AFFIDAMENTO DEL SERVIZIO DI ACCERTAMENTO E RISCOSSIONE DELL&#8217;IMPOSTA SULLE PUBBLICIT\u00c0"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/1263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=1263"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/1263\/revisions"}],"predecessor-version":[{"id":1266,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/1263\/revisions\/1266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/1264"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=1263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=1263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=1263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}