{"id":19203,"date":"2022-07-16T10:37:12","date_gmt":"2022-07-16T08:37:12","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=19203"},"modified":"2022-07-16T10:45:30","modified_gmt":"2022-07-16T08:45:30","slug":"avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/","title":{"rendered":"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA"},"content":{"rendered":"<p>Con il presente avviso pubblico sono avviate le procedure finalizzate all\u2019individuazione di potenziali sottoscrittori del Patto per la lettura di Capranica;<\/p>\n<p>Le domande dei richiedenti possono essere presentate al Comune a partire dalla data di pubblicazione del presente bando ed entro il termine del 23.07.2022 ore 13,00 . Successivamente a tale data, le istanze pervenute saranno valutate con cadenza periodica.<\/p>\n<p>REQUISITI<\/p>\n<p>Sono ammesse alla valutazione della Giunta Comunale le istanze avanzate da soggetti pubblici e privati che hanno sede e\/o operano sul territorio comunale nelle attivit\u00e0 di promozione<\/p>\n<p>della lettura (a titolo esemplificativo: istituzioni pubbliche, biblioteche, case editrici, librerie, autori e lettori organizzati in gruppi e associazioni, scuole e universit\u00e0, imprese private, associazioni culturali e di volontariato, fondazioni bancarie) e da tutti coloro che condividono l&#8217;idea che la lettura, declinata in tutte le sue forme, sia un bene comune su cui investire per la crescita culturale dell&#8217;individuo e della societ\u00e0, uno strumento per l&#8217;innovazione e lo sviluppo economico e sociale del territorio.<\/p>\n<p>DOMANDA DI PARTECIPAZIONE<\/p>\n<p>Il richiedente palesa la volont\u00e0 di aderire al Patto per la lettura di Capranica utilizzando apposito modello fornito dal Comune nel quale dichiara:<\/p>\n<p>&#8211; di aver preso visione del Patto per la Lettura di Capranica;<\/p>\n<p>&#8211; di aderire al Patto per la Lettura di Capranica;<\/p>\n<p>&#8211; di impegnarsi a condividere e fare propri gli obiettivi del Patto e le azioni ad esso collegate e ad assumere gli impegni previsti dal Patto.<\/p>\n<p>Alla richiesta deve necessariamente essere allegato un documento di identit\u00e0 del sottoscrittore in corso di validit\u00e0.<\/p>\n<p>TERMINI E MODALITA&#8217; DI PRESENTAZIONE DELLA DOMANDA<\/p>\n<p>La domanda di partecipazione all&#8217;avviso dovr\u00e0 essere compilata esclusivamente sul modello messo a disposizione dal competente Ufficio comunale e dovr\u00e0 essere presentata entro e on oltre il termine del 23.07.2022 ore 13,00 attraverso una delle seguenti modalit\u00e0:<\/p>\n<p>&#8211; per Posta Elettronica all\u2019indirizzo: protocollo@comune.capranica.vt.it<\/p>\n<p>&#8211; per Posta Elettronica Certificata (PEC) all&#8217;indirizzo email: comunedicapranica@legalmail.it<\/p>\n<p>Far\u00e0 fede la data e l&#8217;ora di invio come risultante dalla mail\/PEC<\/p>\n<p>Le domande non sottoscritte non saranno ritenute valide ai fini della valutazione delle candidature;<\/p>\n<p>si proceder\u00e0 invece al soccorso istruttorio in caso di documentazione incompleta.<\/p>\n<p>Oltre il termine previsto sar\u00e0 comunque possibile, in ogni momento dell&#8217;anno presentare la propria candidatura e sottoporla alla valutazione periodica della Giunta Comunale.<\/p>\n<p>Per chiarimenti e\/o informazioni si invita a leggere la documentazione allegata al presente avviso oppure a contattare la Biblioteca Comunale (dott.ssa Gerardina Iannini, email: biblioteca.capranica@gmail.com tel. 07611790570).<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19210\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/modulistica-adesione-patto-lettura-1.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/modulistica-adesione-patto-lettura-1.docx', '_system'); return false;\"><i class='icon attachment'><\/i>modulistica-adesione-patto-lettura<\/a><\/li>\n<li><a id=\"wpba_attachment_list_19211\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/Patto-locale-per-la-lettura-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/Patto-locale-per-la-lettura-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Patto locale per la lettura<\/a><\/li>\n<li><a id=\"wpba_attachment_list_19212\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/avviso-patto-lettura-capranica-da-pubblicare-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/avviso-patto-lettura-capranica-da-pubblicare-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso patto lettura capranica-da pubblicare<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con il presente avviso pubblico sono avviate le procedure finalizzate all\u2019individuazione di potenziali sottoscrittori del Patto per la lettura di Capranica; Le domande dei richiedenti possono essere presentate al Comune [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":19209,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-19203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA - Capranica\" \/>\n<meta property=\"og:description\" content=\"Con il presente avviso pubblico sono avviate le procedure finalizzate all\u2019individuazione di potenziali sottoscrittori del Patto per la lettura di Capranica; Le domande dei richiedenti possono essere presentate al Comune [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-16T08:37:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-16T08:45:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/AVVISO-ALLA-CITTADINANZA-1152x864-1-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA\",\"datePublished\":\"2022-07-16T08:37:12+00:00\",\"dateModified\":\"2022-07-16T08:45:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/\"},\"wordCount\":419,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2022\\\/07\\\/AVVISO-ALLA-CITTADINANZA-1152x864-1-4.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/\",\"name\":\"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2022\\\/07\\\/AVVISO-ALLA-CITTADINANZA-1152x864-1-4.jpg\",\"datePublished\":\"2022-07-16T08:37:12+00:00\",\"dateModified\":\"2022-07-16T08:45:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2022\\\/07\\\/AVVISO-ALLA-CITTADINANZA-1152x864-1-4.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2022\\\/07\\\/AVVISO-ALLA-CITTADINANZA-1152x864-1-4.jpg\",\"width\":1152,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2022\\\/07\\\/16\\\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA - Capranica","og_description":"Con il presente avviso pubblico sono avviate le procedure finalizzate all\u2019individuazione di potenziali sottoscrittori del Patto per la lettura di Capranica; Le domande dei richiedenti possono essere presentate al Comune [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-07-16T08:37:12+00:00","article_modified_time":"2022-07-16T08:45:30+00:00","og_image":[{"width":1152,"height":864,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/AVVISO-ALLA-CITTADINANZA-1152x864-1-3.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA","datePublished":"2022-07-16T08:37:12+00:00","dateModified":"2022-07-16T08:45:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/"},"wordCount":419,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/AVVISO-ALLA-CITTADINANZA-1152x864-1-4.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/","url":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/","name":"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/AVVISO-ALLA-CITTADINANZA-1152x864-1-4.jpg","datePublished":"2022-07-16T08:37:12+00:00","dateModified":"2022-07-16T08:45:30+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/AVVISO-ALLA-CITTADINANZA-1152x864-1-4.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2022\/07\/AVVISO-ALLA-CITTADINANZA-1152x864-1-4.jpg","width":1152,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2022\/07\/16\/avviso-pubblico-adesione-al-patto-per-la-lettura-del-comune-di-capranica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"AVVISO PUBBLICO ADESIONE AL PATTO PER LA LETTURA DEL COMUNE DI CAPRANICA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"19429"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/19203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=19203"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/19203\/revisions"}],"predecessor-version":[{"id":19208,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/19203\/revisions\/19208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/19209"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=19203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=19203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=19203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}