{"id":22529,"date":"2025-07-29T13:19:26","date_gmt":"2025-07-29T11:19:26","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/"},"modified":"2025-07-29T13:19:26","modified_gmt":"2025-07-29T11:19:26","slug":"avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/","title":{"rendered":"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona"},"content":{"rendered":"<p><em>Tramite il Portale del Reclutamento della Pubblica Amministrazione InPA, \u00e8 possibile candidarsi e presentare domanda per il concorso bandito dal Comune di Capranica.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div class=\"gmail_default\">Concorso bandito dal Comune di Capranica, per il reclutamento di:<\/div>\n<div class=\"gmail_default\"><\/div>\n<div class=\"gmail_default\">&#8211;\u00a0<a href=\"https:\/\/www.inpa.gov.it\/bandi-e-avvisi\/dettaglio-bando-avviso\/?concorso_id=550eabb7441746d7ac0691b1e0131b35\" target=\"_blank\" rel=\"noopener\">n. 1 Istruttore Amministrativo a tempo determinato e parziale al 50,00% (18 ore settimanali), Area degli Istruttori di cui alla tabella B del CCNL Funzioni Locali 2019\/2021 (ex C1), da assegnare al Settore II \u2013 Servizi alla Persona,\u00a0del Comune di Capranica: durata dell\u2019incarico 12 mesi con facolt\u00e0 di rinnovo<\/a>.<\/div>\n<div class=\"gmail_default\"><\/div>\n<div class=\"gmail_default\"><a href=\"https:\/\/www.inpa.gov.it\/bandi-e-avvisi\/dettaglio-bando-avviso\/?concorso_id=550eabb7441746d7ac0691b1e0131b35\" target=\"_blank\" rel=\"noopener\">Per presentare la domanda<\/a> \u00e8 necessario:<\/div>\n<div class=\"gmail_default\">&#8211; SPID;<\/div>\n<div class=\"gmail_default\">&#8211; indirizzo PEC;<\/div>\n<div class=\"gmail_default\">&#8211; registrazione sul sito\u00a0<a href=\"http:\/\/www.inpa.it\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.inpa.it\/&amp;source=gmail&amp;ust=1753873716021000&amp;usg=AOvVaw1fuQKHNnId1tHYZI4KQ2gC\">www.inpa.it<\/a><\/div>\n<div class=\"gmail_default\"><\/div>\n<div class=\"gmail_default\">Tutti i dettagli del bando sono contenuti nell&#8217;allegato.<\/div>\n<div class=\"gmail_default\"><\/div>\n<div class=\"gmail_default\">Scadenza: <strong>entro le ore 23:30 di marted\u00ec 12 agosto 2025.<\/strong><\/div>\n<div>\n<div class=\"gmail_default\">Per informazioni:<\/div>\n<div class=\"gmail_default\">\n<div class=\"gmail_default\">Comune di Capranica<\/div>\n<div class=\"gmail_default\">Settore I &#8211; Servizio Personale (economico-giuridico)<\/div>\n<\/div>\n<div class=\"gmail_default\">&#8211; Dott. Fabio Ceccarini: 0761667927<br \/>\n&#8211; Istr. Amm.vo Rag. Lorena Ciucci: 0761667916<br \/>\nMail:\u00a0<a href=\"mailto:personale@comune.capranica.vt.it\" target=\"_blank\" rel=\"noopener\">personale@comune.capranica.vt.it<\/a><\/div>\n<\/div>\n<div class=\"gmail_default\"><\/div>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_22531\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2025\/07\/Bando-di-Concorso-per-n.1-Istruttore-Amministrativo-a-TD-CON-PROCEDURA-CARTACEA-ALBO-E-INPA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2025\/07\/Bando-di-Concorso-per-n.1-Istruttore-Amministrativo-a-TD-CON-PROCEDURA-CARTACEA-ALBO-E-INPA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Bando di Concorso per n.1 Istruttore Amministrativo a TD &#8211; CON PROCEDURA CARTACEA &#8211; ALBO E INPA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tramite il Portale del Reclutamento della Pubblica Amministrazione InPA, \u00e8 possibile candidarsi e presentare domanda per il concorso bandito dal Comune di Capranica.&nbsp; Descrizione&nbsp; Concorso bandito dal Comune di Capranica, [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":22530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-22529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona - Capranica\" \/>\n<meta property=\"og:description\" content=\"Tramite il Portale del Reclutamento della Pubblica Amministrazione InPA, \u00e8 possibile candidarsi e presentare domanda per il concorso bandito dal Comune di Capranica.&nbsp; Descrizione&nbsp; Concorso bandito dal Comune di Capranica, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T11:19:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2025\/07\/inpa_logo_0-4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona\",\"datePublished\":\"2025-07-29T11:19:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/\"},\"wordCount\":186,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2025\\\/07\\\/inpa_logo_0-4.jpeg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/\",\"name\":\"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2025\\\/07\\\/inpa_logo_0-4.jpeg\",\"datePublished\":\"2025-07-29T11:19:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2025\\\/07\\\/inpa_logo_0-4.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2025\\\/07\\\/inpa_logo_0-4.jpeg\",\"width\":1200,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2025\\\/07\\\/29\\\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona - Capranica","og_description":"Tramite il Portale del Reclutamento della Pubblica Amministrazione InPA, \u00e8 possibile candidarsi e presentare domanda per il concorso bandito dal Comune di Capranica.&nbsp; Descrizione&nbsp; Concorso bandito dal Comune di Capranica, [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-29T11:19:26+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2025\/07\/inpa_logo_0-4.jpeg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona","datePublished":"2025-07-29T11:19:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/"},"wordCount":186,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2025\/07\/inpa_logo_0-4.jpeg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/","url":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/","name":"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2025\/07\/inpa_logo_0-4.jpeg","datePublished":"2025-07-29T11:19:26+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2025\/07\/inpa_logo_0-4.jpeg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2025\/07\/inpa_logo_0-4.jpeg","width":1200,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2025\/07\/29\/avviso-pubblico-di-selezione-per-soli-esami-con-riserva-per-operatori-volontari-scu-per-la-copertura-di-n-1-posto-di-istruttore-amministrativo-area-degli-istruttori-ex-cat-c1-a-tempo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico di selezione, per soli esami, con riserva per operatori volontari SCU, per la copertura di n. 1 posto di istruttore amministrativo (area degli istruttori \u2013 ex cat. c1) a tempo determinato e parziale al 50% (18 ore settimanali) per le esigenze del Settore II \u2013 Servizi alla persona"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003716"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/22529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=22529"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/22529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/22530"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=22529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=22529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=22529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}