{"id":23051,"date":"2026-02-24T08:27:58","date_gmt":"2026-02-24T07:27:58","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/"},"modified":"2026-02-24T08:27:58","modified_gmt":"2026-02-24T07:27:58","slug":"sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/","title":{"rendered":"Sospensione erogazione idrica il 25\/02\/2026 dalle ore 13:00 alle ore 20:00"},"content":{"rendered":"<p><em>Sospensione servizio idrico in data 25\/02\/2026 &#8211; Utenze servite dal SERBATOIO PENSILE DEL SACRO CUORE<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Gli interventi previsti comportano la necessit\u00e0 di effettuare installazioni di misuratori di portata e pressione presso gli impianti a servizio dell&#8217;acquedotto, finalizzati al monitoraggio dei valori di portata e pressione in rete e alla modellazione delle reti stesse e dunque alla gestione e al contenimento delle perdite pi\u00f9 efficace.<br \/>\nPer i suddetti interventi sar\u00e0 necessaria l&#8217;interruzione del flusso idrico in alcuni giorni e per alcune ore che interesseranno le zone di seguito dettagliate: SERBATOIO SACRO CUORE PENSILE<br \/>\nZONE INTERESSATE:<br \/>\nSCUOLA MEDIA, SCUOLA MATERNA, ASILO NIDO, VILLA PAOLA, ZONA VALLE SANTI, ZONA STAZIONE, ZONA PAJANELLO 1, PAJANELLO 2,COLLE DEL PETRARCA, ZONA CANICOLE, VIALE LAURA, LOC. MONTARORE, VIA DEL SACRO CUORE, VIA ALCIDE DE GASPERI E ZONE LIMITROFE<br \/>\nORARIO DI CHIUSURA<br \/>\nDALLE ORE 13:00 ALLE ORE 20:00<\/p>\n<p>Inoltre, sar\u00e0 istituito servizio idrico alternativo tramite n. 1 autobotte per la scuola materna in Via della Mattonara.<br \/>\nL&#8217;orario indicato per la durata dell&#8217;interruzione deve intendersi al netto di imprevisti o cause di forza maggiore,<br \/>\nAl momento del ripristino del flusso idrico si potranno in ogni caso verificare temporanee anomalie di approvvigionamento e\/o torbidit\u00e0 dell&#8217;acqua,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sospensione servizio idrico in data 25\/02\/2026 &#8211; Utenze servite dal SERBATOIO PENSILE DEL SACRO CUORE&nbsp; Descrizione&nbsp; Gli interventi previsti comportano la necessit\u00e0 di effettuare installazioni di misuratori di portata e [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":23052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-23051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sospensione erogazione idrica il 25\/02\/2026 dalle ore 13:00 alle ore 20:00 - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sospensione erogazione idrica il 25\/02\/2026 dalle ore 13:00 alle ore 20:00 - Capranica\" \/>\n<meta property=\"og:description\" content=\"Sospensione servizio idrico in data 25\/02\/2026 &#8211; Utenze servite dal SERBATOIO PENSILE DEL SACRO CUORE&nbsp; Descrizione&nbsp; Gli interventi previsti comportano la necessit\u00e0 di effettuare installazioni di misuratori di portata e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-24T07:27:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2026\/02\/acqua-lavori-213124.660x368-1152x642-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"642\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"Sospensione erogazione idrica il 25\\\/02\\\/2026 dalle ore 13:00 alle ore 20:00\",\"datePublished\":\"2026-02-24T07:27:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/\"},\"wordCount\":202,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2026\\\/02\\\/acqua-lavori-213124.660x368-1152x642-1-1.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/\",\"name\":\"Sospensione erogazione idrica il 25\\\/02\\\/2026 dalle ore 13:00 alle ore 20:00 - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2026\\\/02\\\/acqua-lavori-213124.660x368-1152x642-1-1.jpg\",\"datePublished\":\"2026-02-24T07:27:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2026\\\/02\\\/acqua-lavori-213124.660x368-1152x642-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2026\\\/02\\\/acqua-lavori-213124.660x368-1152x642-1-1.jpg\",\"width\":1152,\"height\":642},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2026\\\/02\\\/24\\\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sospensione erogazione idrica il 25\\\/02\\\/2026 dalle ore 13:00 alle ore 20:00\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sospensione erogazione idrica il 25\/02\/2026 dalle ore 13:00 alle ore 20:00 - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/","og_locale":"it_IT","og_type":"article","og_title":"Sospensione erogazione idrica il 25\/02\/2026 dalle ore 13:00 alle ore 20:00 - Capranica","og_description":"Sospensione servizio idrico in data 25\/02\/2026 &#8211; Utenze servite dal SERBATOIO PENSILE DEL SACRO CUORE&nbsp; Descrizione&nbsp; Gli interventi previsti comportano la necessit\u00e0 di effettuare installazioni di misuratori di portata e [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-02-24T07:27:58+00:00","og_image":[{"width":1152,"height":642,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2026\/02\/acqua-lavori-213124.660x368-1152x642-1-1.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"Sospensione erogazione idrica il 25\/02\/2026 dalle ore 13:00 alle ore 20:00","datePublished":"2026-02-24T07:27:58+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/"},"wordCount":202,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2026\/02\/acqua-lavori-213124.660x368-1152x642-1-1.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/","url":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/","name":"Sospensione erogazione idrica il 25\/02\/2026 dalle ore 13:00 alle ore 20:00 - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2026\/02\/acqua-lavori-213124.660x368-1152x642-1-1.jpg","datePublished":"2026-02-24T07:27:58+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2026\/02\/acqua-lavori-213124.660x368-1152x642-1-1.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2026\/02\/acqua-lavori-213124.660x368-1152x642-1-1.jpg","width":1152,"height":642},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2026\/02\/24\/sospensione-erogazione-idrica-il-25-02-2026-dalle-ore-1300-alle-ore-2000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"Sospensione erogazione idrica il 25\/02\/2026 dalle ore 13:00 alle ore 20:00"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00004075"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/23051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=23051"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/23051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/23052"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=23051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=23051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=23051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}