{"id":3446,"date":"2019-06-15T14:48:51","date_gmt":"2019-06-15T12:48:51","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=3446"},"modified":"2019-06-15T14:49:57","modified_gmt":"2019-06-15T12:49:57","slug":"asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/","title":{"rendered":"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI"},"content":{"rendered":"<p>Prosegue il <strong>progetto di messa in sicurezza delle strade<\/strong>, gi\u00e0 avviato dall&#8217;Amministrazione comunale con i recenti lavori di asfaltatura effettuati.<\/p>\n<p>Gli interventi riguarderanno:<\/p>\n<ul>\n<li>Il <strong>completamento<\/strong> del rifacimento del manto stradale su <strong>Via Matteotti<\/strong> fino a Via degli Zuccari, comprendendo la zona della &#8220;Stazioncina&#8221;.<\/li>\n<li>L&#8217;avvio dei lavori di rifacimento dell<strong>&#8216;asfalto in localit\u00e0 Colle del Petrarca.<\/strong><\/li>\n<\/ul>\n<p>La partenza dei lavori \u00e8 prevista per <strong>luned\u00ec 24 giugno 2019<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Questi interventi si sommano ad i<strong> lavori di manutenzione straordinaria<\/strong> effettuati dalla <strong>Provincia di Viterbo<\/strong> sulle strade di competenza e che nelle prossime settimane andranno a\u00a0<strong>completare l&#8217;asfaltatura della SP Capranichese<\/strong> (&#8220;Strada Bianca&#8221;).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Nei prossimi giorni al fine di gestire al meglio i lavori sulle strade verranno emanate le ordinanze relative alla limitazione della circolazione.\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ci scusiamo per gli eventuali disagi che saranno arrecati, e ringraziamo anticipatamente la cittadinanza per la collaborazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prosegue il progetto di messa in sicurezza delle strade, gi\u00e0 avviato dall&#8217;Amministrazione comunale con i recenti lavori di asfaltatura effettuati. Gli interventi riguarderanno: Il completamento del rifacimento del manto stradale [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":3447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-3446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manutenzione-e-lavori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI - Capranica\" \/>\n<meta property=\"og:description\" content=\"Prosegue il progetto di messa in sicurezza delle strade, gi\u00e0 avviato dall&#8217;Amministrazione comunale con i recenti lavori di asfaltatura effettuati. Gli interventi riguarderanno: Il completamento del rifacimento del manto stradale [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-15T12:48:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-15T12:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2019\/06\/lavori-in-corso-big1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5000\" \/>\n\t<meta property=\"og:image:height\" content=\"3000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI\",\"datePublished\":\"2019-06-15T12:48:51+00:00\",\"dateModified\":\"2019-06-15T12:49:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/\"},\"wordCount\":149,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2019\\\/06\\\/lavori-in-corso-big1.jpg\",\"articleSection\":[\"Manutenzione e Lavori\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/\",\"name\":\"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2019\\\/06\\\/lavori-in-corso-big1.jpg\",\"datePublished\":\"2019-06-15T12:48:51+00:00\",\"dateModified\":\"2019-06-15T12:49:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2019\\\/06\\\/lavori-in-corso-big1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2019\\\/06\\\/lavori-in-corso-big1.jpg\",\"width\":5000,\"height\":3000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/06\\\/15\\\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/","og_locale":"it_IT","og_type":"article","og_title":"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI - Capranica","og_description":"Prosegue il progetto di messa in sicurezza delle strade, gi\u00e0 avviato dall&#8217;Amministrazione comunale con i recenti lavori di asfaltatura effettuati. Gli interventi riguarderanno: Il completamento del rifacimento del manto stradale [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-06-15T12:48:51+00:00","article_modified_time":"2019-06-15T12:49:57+00:00","og_image":[{"width":5000,"height":3000,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2019\/06\/lavori-in-corso-big1.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI","datePublished":"2019-06-15T12:48:51+00:00","dateModified":"2019-06-15T12:49:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/"},"wordCount":149,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2019\/06\/lavori-in-corso-big1.jpg","articleSection":["Manutenzione e Lavori"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/","url":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/","name":"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2019\/06\/lavori-in-corso-big1.jpg","datePublished":"2019-06-15T12:48:51+00:00","dateModified":"2019-06-15T12:49:57+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2019\/06\/lavori-in-corso-big1.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2019\/06\/lavori-in-corso-big1.jpg","width":5000,"height":3000},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2019\/06\/15\/asfalto-lavori-in-partenza-al-colle-del-petrarca-e-su-via-matteotti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"ASFALTO: LAVORI IN PARTENZA AL COLLE DEL PETRARCA E SU VIA MATTEOTTI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/3446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=3446"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/3446\/revisions"}],"predecessor-version":[{"id":3449,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/3446\/revisions\/3449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/3447"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=3446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=3446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=3446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}