{"id":361,"date":"2017-04-19T15:33:03","date_gmt":"2017-04-19T13:33:03","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=361"},"modified":"2017-04-19T15:34:58","modified_gmt":"2017-04-19T13:34:58","slug":"innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/","title":{"rendered":"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE"},"content":{"rendered":"<p>Dopo il successo delle prime due edizioni di <strong>\u201c<a href=\"http:\/\/www.biclazio.it\/it\/home\/innovazione-sostantivo-femminile-2017.bic\">Innovazione sostantivo femminile<\/a>\u201d<\/strong>, che hanno visto finanziati 83 progetti, anche quest\u2019anno la Regione Lazio intende promuovere la nascita e lo sviluppo di idee e iniziative imprenditoriali tutte al femminile. Le risorse regionali a disposizione per l\u2019anno 2017 ammontano a circa 2 milioni di euro, di cui 250 mila destinati alla provincia di Viterbo.<\/p>\n<p>Destinatarie dell\u2019iniziativa regionale sono sia le libere professioniste sia le imprese \u201cal femminile\u201d, anche se non ancora formate. I progetti presentati dovranno essere innovativi e riguardare la realizzazione di prodotti e servizi basati sulle nuove tecnologie applicabili a settori strategici quali l\u2019ambiente, la mobilit\u00e0 sostenibile, i beni culturali, la <a href=\"http:\/\/phifoundation.com\/cose-la-social-innovation\/\"><em>Social Innovation<\/em><\/a>.<\/p>\n<p>Il contributo a fondo perduto sar\u00e0 pari al 70% delle spese ammissibili, fino a un massimo di 30 mila euro a progetto. L\u2019assegnazione dei fondi avverr\u00e0 secondo la procedura \u201ca sportello\u201d, ossia in base all\u2019ordine cronologico di presentazione dei progetti ritenuti ammissibili, fino a esaurimento fondi.<\/p>\n<p>Le domande potranno essere presentate a partire dalle ore 9:00 del 2 maggio 2017, fino alle 17:00 del 31 ottobre 2017, esclusivamente per via telematica attraverso la piattaforma <a href=\"http:\/\/www.lazioinnova.it\/gecoweb\/\">GeCoWEB<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopo il successo delle prime due edizioni di \u201cInnovazione sostantivo femminile\u201d, che hanno visto finanziati 83 progetti, anche quest\u2019anno la Regione Lazio intende promuovere la nascita e lo sviluppo di [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE - Capranica\" \/>\n<meta property=\"og:description\" content=\"Dopo il successo delle prime due edizioni di \u201cInnovazione sostantivo femminile\u201d, che hanno visto finanziati 83 progetti, anche quest\u2019anno la Regione Lazio intende promuovere la nascita e lo sviluppo di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-19T13:33:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-19T13:34:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE\",\"datePublished\":\"2017-04-19T13:33:03+00:00\",\"dateModified\":\"2017-04-19T13:34:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/\"},\"wordCount\":194,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/04\\\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/\",\"name\":\"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/04\\\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg\",\"datePublished\":\"2017-04-19T13:33:03+00:00\",\"dateModified\":\"2017-04-19T13:34:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/04\\\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/04\\\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/04\\\/19\\\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/","og_locale":"it_IT","og_type":"article","og_title":"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE - Capranica","og_description":"Dopo il successo delle prime due edizioni di \u201cInnovazione sostantivo femminile\u201d, che hanno visto finanziati 83 progetti, anche quest\u2019anno la Regione Lazio intende promuovere la nascita e lo sviluppo di [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-04-19T13:33:03+00:00","article_modified_time":"2017-04-19T13:34:58+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE","datePublished":"2017-04-19T13:33:03+00:00","dateModified":"2017-04-19T13:34:58+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/"},"wordCount":194,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/","url":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/","name":"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg","datePublished":"2017-04-19T13:33:03+00:00","dateModified":"2017-04-19T13:34:58+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/COPERTINA-INNOVAZIONE-SOSTANTIVO-FEMMINILE.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2017\/04\/19\/innovazione-sostantivo-femminile-2017-la-regione-lazio-finanzia-le-idee-imprenditoriali-delle-donne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"\u201cINNOVAZIONE SOSTANTIVO FEMMINILE\u201d 2017: LA REGIONE LAZIO FINANZIA LE IDEE IMPRENDITORIALI DELLE DONNE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=361"}],"version-history":[{"count":4,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/361\/revisions"}],"predecessor-version":[{"id":365,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/361\/revisions\/365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/350"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}