{"id":3662,"date":"2019-08-23T22:18:35","date_gmt":"2019-08-23T20:18:35","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=3662"},"modified":"2019-08-23T22:17:39","modified_gmt":"2019-08-23T20:17:39","slug":"istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/","title":{"rendered":"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L&#8217;INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI"},"content":{"rendered":"<p>Si comunica che \u00e8 stato ripristinato il <strong>doppio senso di circolazione su Via Giacomo Matteotti nel tratto compreso tra l&#8217;uscita dell&#8217;intersezione di fronte al civico N.2 e Piazza della Libert\u00e0.<\/strong><\/p>\n<p>In Via Giacomo Matteotti sull&#8217;intersezione dell&#8217;uscita di fronte al civico N.2 \u00e8 istituito l&#8217;obbligo di fermarsi e dare precedenza (stop).<\/p>\n<p>In allegato \u00e8 possibile prendere visione dell\u2019ordinanza.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3666\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2019\/08\/ordinanza57_2019.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2019\/08\/ordinanza57_2019.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanza57_2019<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che \u00e8 stato ripristinato il doppio senso di circolazione su Via Giacomo Matteotti nel tratto compreso tra l&#8217;uscita dell&#8217;intersezione di fronte al civico N.2 e Piazza della Libert\u00e0. [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-3662","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L&#039;INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L&#039;INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI - Capranica\" \/>\n<meta property=\"og:description\" content=\"Si comunica che \u00e8 stato ripristinato il doppio senso di circolazione su Via Giacomo Matteotti nel tratto compreso tra l&#8217;uscita dell&#8217;intersezione di fronte al civico N.2 e Piazza della Libert\u00e0. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-23T20:18:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L&#8217;INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI\",\"datePublished\":\"2019-08-23T20:18:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/\"},\"wordCount\":77,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/\",\"name\":\"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L'INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"datePublished\":\"2019-08-23T20:18:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2019\\\/08\\\/23\\\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L&#8217;INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L'INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/","og_locale":"it_IT","og_type":"article","og_title":"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L'INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI - Capranica","og_description":"Si comunica che \u00e8 stato ripristinato il doppio senso di circolazione su Via Giacomo Matteotti nel tratto compreso tra l&#8217;uscita dell&#8217;intersezione di fronte al civico N.2 e Piazza della Libert\u00e0. [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-08-23T20:18:35+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L&#8217;INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI","datePublished":"2019-08-23T20:18:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/"},"wordCount":77,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/","url":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/","name":"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L'INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","datePublished":"2019-08-23T20:18:35+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2019\/08\/23\/istituzione-del-doppio-senso-di-circolazione-nel-tratto-compreso-tra-piazza-della-liberta-e-il-civico-x-di-via-matteotti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"RIPRISTINO DEL DOPPIO SENSO DI CIRCOLAZIONE NEL TRATTO COMPRESO TRA PIAZZA DELLA LIBERT\u00c0 E L&#8217;INCROCIO CON IL CIVICO N. 2 DI VIA MATTEOTTI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/3662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=3662"}],"version-history":[{"count":5,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/3662\/revisions"}],"predecessor-version":[{"id":3668,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/3662\/revisions\/3668"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/178"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=3662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=3662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=3662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}