{"id":4410,"date":"2020-01-03T11:14:46","date_gmt":"2020-01-03T10:14:46","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=4410"},"modified":"2020-01-03T11:14:46","modified_gmt":"2020-01-03T10:14:46","slug":"lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/","title":{"rendered":"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE"},"content":{"rendered":"<p>Si comunica che<strong> luned\u00ec 6 gennaio<\/strong>, in occasione della festivit\u00e0 dell&#8217;Epifania, <strong>la circolazione sar\u00e0 regolamentata nel seguente modo:<\/strong><\/p>\n<ul>\n<li><strong>divieto di sosta dalle ore 08.30 alle ore 13.30 in Piazza San Francesco e Corso F. Petrarca lungo il lato della chiesa di San Francesco<\/strong> (per 15 metri a partire dalla Chiesa);<\/li>\n<li><strong>istituzione del senso unico di marcia\u00a0dalle ore 10.00 alle ore 13.30 in Corso F. Petrarca<\/strong> nella direzione da Piazza Garibaldi verso la Via Romana.<\/li>\n<\/ul>\n<p>In allegato \u00e8 possibile prendere visione dell&#8217;ordinanza.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_4411\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/01\/ordinanzan.1del02.01.2020.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/01\/ordinanzan.1del02.01.2020.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanzan.1del02.01.2020<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che luned\u00ec 6 gennaio, in occasione della festivit\u00e0 dell&#8217;Epifania, la circolazione sar\u00e0 regolamentata nel seguente modo: divieto di sosta dalle ore 08.30 alle ore 13.30 in Piazza San [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-4410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE - Capranica\" \/>\n<meta property=\"og:description\" content=\"Si comunica che luned\u00ec 6 gennaio, in occasione della festivit\u00e0 dell&#8217;Epifania, la circolazione sar\u00e0 regolamentata nel seguente modo: divieto di sosta dalle ore 08.30 alle ore 13.30 in Piazza San [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-03T10:14:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE\",\"datePublished\":\"2020-01-03T10:14:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/\"},\"wordCount\":84,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/\",\"name\":\"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"datePublished\":\"2020-01-03T10:14:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/01\\\/03\\\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/","og_locale":"it_IT","og_type":"article","og_title":"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE - Capranica","og_description":"Si comunica che luned\u00ec 6 gennaio, in occasione della festivit\u00e0 dell&#8217;Epifania, la circolazione sar\u00e0 regolamentata nel seguente modo: divieto di sosta dalle ore 08.30 alle ore 13.30 in Piazza San [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-01-03T10:14:46+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE","datePublished":"2020-01-03T10:14:46+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/"},"wordCount":84,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/","url":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/","name":"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","datePublished":"2020-01-03T10:14:46+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2020\/01\/03\/lunedi-6-gennaio-regolamentazione-della-sosta-e-della-circolazione-veicolare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"LUNED\u00cc 6 GENNAIO: REGOLAMENTAZIONE DELLA SOSTA E DELLA CIRCOLAZIONE VEICOLARE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=4410"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4410\/revisions"}],"predecessor-version":[{"id":4412,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4410\/revisions\/4412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/178"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=4410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=4410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=4410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}