{"id":4660,"date":"2020-02-17T19:37:01","date_gmt":"2020-02-17T18:37:01","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=4660"},"modified":"2020-02-17T19:37:55","modified_gmt":"2020-02-17T18:37:55","slug":"piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/","title":{"rendered":"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA"},"content":{"rendered":"<p><strong>Installate sul territorio comunale le indicazioni relative alle aree di attesa e di accoglienza in caso di eventi calamitosi o fasi di allertamento che richiedano il raggruppamento delle persone in luoghi sicuri, dove poter fornire assistenza.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Le <strong>Aree di attesa<\/strong> identificate da <strong>cartellonistica verde<\/strong> e da utilizzarsi nell&#8217;immediato in caso di evento calamitoso sono cos\u00ec individuate:<\/p>\n<ol>\n<li>Piazzale delle Rimembranze (Cimitero);<\/li>\n<li>Via Martiri di Via Fani (Vallesanti);<\/li>\n<li>Piazzale della Madonna del Piano;<\/li>\n<li>Via della Poesia (Canicole);<\/li>\n<li>Viale Laura (Colle del Petrarca);<\/li>\n<li>Piazza Marconi (Stazione);<\/li>\n<li>Viale dei Castagni (Zona Artigianale).<\/li>\n<li><\/li>\n<\/ol>\n<p>Le <strong>Aree di accoglienza o di emergenza<\/strong> identificate da <strong>cartellonistica blu<\/strong> ed eventualmente idonee ad offrire servizi di assistenza, accogliere tendopoli e accampamenti provvisori sono cos\u00ec individuate:<\/p>\n<ol>\n<li>Via Madre Teresa di Calcutta;<\/li>\n<li>Via John Fitzgerald Kennedy;<\/li>\n<li>Area Verde Via Martiri di Via Fani<\/li>\n<li>Palestra comunale \u201cFiliberto Puccica\u201d<\/li>\n<li>Tensostruttura \u201cRosa Simeoni\u201d<\/li>\n<li><\/li>\n<\/ol>\n<p>\u00c8 inoltre individuata un\u2019<strong>area di ammassamento soccorritori<\/strong> nel parcheggio in Via A. de Gasperi, con <strong>cartellonistica marrone<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4661\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-1-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-1-225x300.jpeg 225w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-1-768x1023.jpeg 768w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-1-1153x1536.jpeg 1153w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-1-680x906.jpeg 680w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-1.jpeg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4662\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-2-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-2-225x300.jpeg 225w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-2-680x907.jpeg 680w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-2.jpeg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4663\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-225x300.jpeg 225w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-768x1023.jpeg 768w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-1153x1536.jpeg 1153w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06-680x906.jpeg 680w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.06.jpeg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4664\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.22-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.22-225x300.jpeg 225w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.22-768x1023.jpeg 768w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.22-1153x1536.jpeg 1153w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.22-680x906.jpeg 680w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/WhatsApp-Image-2020-02-17-at-12.06.22.jpeg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4665\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/1A-216x300.gif\" alt=\"\" width=\"216\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/1A-216x300.gif 216w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/1A-680x943.gif 680w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4666\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/2A-217x300.gif\" alt=\"\" width=\"217\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/2A-217x300.gif 217w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/2A-680x938.gif 680w\" sizes=\"auto, (max-width: 217px) 100vw, 217px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4667\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/3A-217x300.gif\" alt=\"\" width=\"217\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/3A-217x300.gif 217w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/3A-680x941.gif 680w\" sizes=\"auto, (max-width: 217px) 100vw, 217px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4668\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/4A-216x300.gif\" alt=\"\" width=\"216\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/4A-216x300.gif 216w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/4A-680x943.gif 680w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4669\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/5A-217x300.gif\" alt=\"\" width=\"217\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/5A-217x300.gif 217w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/5A-680x942.gif 680w\" sizes=\"auto, (max-width: 217px) 100vw, 217px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4670\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/6A-217x300.gif\" alt=\"\" width=\"217\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/6A-217x300.gif 217w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/6A-680x941.gif 680w\" sizes=\"auto, (max-width: 217px) 100vw, 217px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4671\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/7A-218x300.gif\" alt=\"\" width=\"218\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/7A-218x300.gif 218w, https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/7A-680x937.gif 680w\" sizes=\"auto, (max-width: 218px) 100vw, 218px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4672\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/1R-213x300.gif\" alt=\"\" width=\"213\" height=\"300\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4673\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/2R-213x300.gif\" alt=\"\" width=\"213\" height=\"300\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4674\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/3R-214x300.gif\" alt=\"\" width=\"214\" height=\"300\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4675\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/4R-214x300.gif\" alt=\"\" width=\"214\" height=\"300\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4676\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/5R-213x300.gif\" alt=\"\" width=\"213\" height=\"300\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4677\" src=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/1S-214x300.gif\" alt=\"\" width=\"214\" height=\"300\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Installate sul territorio comunale le indicazioni relative alle aree di attesa e di accoglienza in caso di eventi calamitosi o fasi di allertamento che richiedano il raggruppamento delle persone in [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":4678,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-4660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pubblica-sicurezza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA - Capranica\" \/>\n<meta property=\"og:description\" content=\"Installate sul territorio comunale le indicazioni relative alle aree di attesa e di accoglienza in caso di eventi calamitosi o fasi di allertamento che richiedano il raggruppamento delle persone in [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-17T18:37:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-17T18:37:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/ATTESA.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"1251\" \/>\n\t<meta property=\"og:image:height\" content=\"916\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA\",\"datePublished\":\"2020-02-17T18:37:01+00:00\",\"dateModified\":\"2020-02-17T18:37:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/\"},\"wordCount\":165,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2020\\\/02\\\/ATTESA.gif\",\"articleSection\":[\"Pubblica Sicurezza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/\",\"name\":\"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2020\\\/02\\\/ATTESA.gif\",\"datePublished\":\"2020-02-17T18:37:01+00:00\",\"dateModified\":\"2020-02-17T18:37:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2020\\\/02\\\/ATTESA.gif\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2020\\\/02\\\/ATTESA.gif\",\"width\":1251,\"height\":916},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/02\\\/17\\\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/","og_locale":"it_IT","og_type":"article","og_title":"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA - Capranica","og_description":"Installate sul territorio comunale le indicazioni relative alle aree di attesa e di accoglienza in caso di eventi calamitosi o fasi di allertamento che richiedano il raggruppamento delle persone in [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-02-17T18:37:01+00:00","article_modified_time":"2020-02-17T18:37:55+00:00","og_image":[{"width":1251,"height":916,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/ATTESA.gif","type":"image\/gif"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA","datePublished":"2020-02-17T18:37:01+00:00","dateModified":"2020-02-17T18:37:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/"},"wordCount":165,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/ATTESA.gif","articleSection":["Pubblica Sicurezza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/","url":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/","name":"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/ATTESA.gif","datePublished":"2020-02-17T18:37:01+00:00","dateModified":"2020-02-17T18:37:55+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/ATTESA.gif","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/02\/ATTESA.gif","width":1251,"height":916},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2020\/02\/17\/piano-emergenza-comunale-posizionata-la-cartellonistica-di-emergenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"PIANO EMERGENZA COMUNALE: POSIZIONATA LA CARTELLONISTICA DI EMERGENZA"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=4660"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4660\/revisions"}],"predecessor-version":[{"id":4680,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4660\/revisions\/4680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/4678"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=4660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=4660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=4660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}