{"id":4835,"date":"2020-03-10T09:19:02","date_gmt":"2020-03-10T08:19:02","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=4835"},"modified":"2020-03-14T09:46:50","modified_gmt":"2020-03-14T08:46:50","slug":"autocertificazione-nazionale-per-il-lavoro","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/","title":{"rendered":"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO"},"content":{"rendered":"<p>A seguito delle nuove disposizioni gli spostamenti sono limitati alle esigenze strettamente necessarie e di carattere lavorativo.<\/p>\n<p>In allegato l&#8217;autocertificazione nazionale da compilare e portare con s\u00e9 in caso di controllo.<\/p>\n<p>Per chi fosse impossibilitato a stampare pu\u00f2 rivolgersi al Comune.<\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_4846\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/03\/Autodichiarazione.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/03\/Autodichiarazione.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Autodichiarazione<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A seguito delle nuove disposizioni gli spostamenti sono limitati alle esigenze strettamente necessarie e di carattere lavorativo. In allegato l&#8217;autocertificazione nazionale da compilare e portare con s\u00e9 in caso di [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":4838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attivita-produttive"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO - Capranica\" \/>\n<meta property=\"og:description\" content=\"A seguito delle nuove disposizioni gli spostamenti sono limitati alle esigenze strettamente necessarie e di carattere lavorativo. In allegato l&#8217;autocertificazione nazionale da compilare e portare con s\u00e9 in caso di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-10T08:19:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-14T08:46:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/03\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO\",\"datePublished\":\"2020-03-10T08:19:02+00:00\",\"dateModified\":\"2020-03-14T08:46:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/\"},\"wordCount\":47,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2020\\\/03\\\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg\",\"articleSection\":[\"Attivit\u00e0 Produttive\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/\",\"name\":\"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2020\\\/03\\\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg\",\"datePublished\":\"2020-03-10T08:19:02+00:00\",\"dateModified\":\"2020-03-14T08:46:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2020\\\/03\\\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2020\\\/03\\\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/03\\\/10\\\/autocertificazione-nazionale-per-il-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/","og_locale":"it_IT","og_type":"article","og_title":"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO - Capranica","og_description":"A seguito delle nuove disposizioni gli spostamenti sono limitati alle esigenze strettamente necessarie e di carattere lavorativo. In allegato l&#8217;autocertificazione nazionale da compilare e portare con s\u00e9 in caso di [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-10T08:19:02+00:00","article_modified_time":"2020-03-14T08:46:50+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/03\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO","datePublished":"2020-03-10T08:19:02+00:00","dateModified":"2020-03-14T08:46:50+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/"},"wordCount":47,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/03\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg","articleSection":["Attivit\u00e0 Produttive"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/","url":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/","name":"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/03\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg","datePublished":"2020-03-10T08:19:02+00:00","dateModified":"2020-03-14T08:46:50+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/03\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/03\/doc_obb-k64C-U31701099291727EHI-656x492_Corriere-Web-Sezioni-1.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2020\/03\/10\/autocertificazione-nazionale-per-il-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"AUTOCERTIFICAZIONE NAZIONALE PER IL LAVORO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=4835"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4835\/revisions"}],"predecessor-version":[{"id":4839,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/4835\/revisions\/4839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/4838"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=4835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=4835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=4835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}