{"id":488,"date":"2017-05-17T09:00:24","date_gmt":"2017-05-17T07:00:24","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=488"},"modified":"2017-05-16T16:08:53","modified_gmt":"2017-05-16T14:08:53","slug":"active-space-active-summer-giornata-dello-sport-in-vista-dellestate","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/","title":{"rendered":"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE"},"content":{"rendered":"<p>L\u2019<a href=\"https:\/\/www.facebook.com\/ActiveSpace\/?ref=ts&amp;fref=ts\">Active Space<\/a> ha organizzato per il prossimo sabato 20 maggio una giornata interamente dedicata allo sport. In programma tante lezioni sia indoor che outdoor e presentazione dei programmi di allenamento e dimagrimento in vista dell\u2019estate. Nell\u2019occasione sar\u00e0 presentato il nuovo programma di allenamento \u201cDal divano alla prima gara\u201d.<\/p>\n<p>L\u2019evento si svolger\u00e0 presso la sede di Vetralla, via Cassia km 62, dalle ore 9:00 alle ore 19:00.<\/p>\n<p>Per info: 0761414763<\/p>\n<p>In allegato a questa notizia la locandina dell\u2019evento.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_490\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/ActiveSummer-Locandina.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/ActiveSummer-Locandina.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ActiveSummer Locandina<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Active Space ha organizzato per il prossimo sabato 20 maggio una giornata interamente dedicata allo sport. In programma tante lezioni sia indoor che outdoor e presentazione dei programmi di allenamento [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":491,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE - Capranica\" \/>\n<meta property=\"og:description\" content=\"L\u2019Active Space ha organizzato per il prossimo sabato 20 maggio una giornata interamente dedicata allo sport. In programma tante lezioni sia indoor che outdoor e presentazione dei programmi di allenamento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-17T07:00:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/ACTIVE-SPACE-COPERTINA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE\",\"datePublished\":\"2017-05-17T07:00:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/\"},\"wordCount\":88,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/05\\\/ACTIVE-SPACE-COPERTINA.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/\",\"name\":\"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/05\\\/ACTIVE-SPACE-COPERTINA.jpg\",\"datePublished\":\"2017-05-17T07:00:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/05\\\/ACTIVE-SPACE-COPERTINA.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/05\\\/ACTIVE-SPACE-COPERTINA.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/17\\\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/","og_locale":"it_IT","og_type":"article","og_title":"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE - Capranica","og_description":"L\u2019Active Space ha organizzato per il prossimo sabato 20 maggio una giornata interamente dedicata allo sport. In programma tante lezioni sia indoor che outdoor e presentazione dei programmi di allenamento [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-05-17T07:00:24+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/ACTIVE-SPACE-COPERTINA.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE","datePublished":"2017-05-17T07:00:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/"},"wordCount":88,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/ACTIVE-SPACE-COPERTINA.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/","url":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/","name":"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/ACTIVE-SPACE-COPERTINA.jpg","datePublished":"2017-05-17T07:00:24+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/ACTIVE-SPACE-COPERTINA.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/ACTIVE-SPACE-COPERTINA.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/17\/active-space-active-summer-giornata-dello-sport-in-vista-dellestate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"ACTIVE SPACE, ACTIVE SUMMER: GIORNATA DELLO SPORT IN VISTA DELL\u2019ESTATE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=488"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/488\/revisions"}],"predecessor-version":[{"id":492,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/488\/revisions\/492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/491"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}