{"id":5158,"date":"2020-05-05T10:14:52","date_gmt":"2020-05-05T08:14:52","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=5158"},"modified":"2020-05-05T10:14:52","modified_gmt":"2020-05-05T08:14:52","slug":"attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/","title":{"rendered":"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019"},"content":{"rendered":"<p><strong>Si comunica che \u00e8 possibile richiedere attraverso il portale della mensa scolastica, utilizzando le proprie credenziali, l&#8217;attestazione relativa alle spese sostenute per il servizio di refezione per l&#8217;anno 2019 utile ai fini della detrazione sulla dichiarazione dei redditi anno 2020, secondo quanto previsto dalla vigente normativa.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>I genitori registrati sul portale della mensa scolastica potranno scaricare esclusivamente dal proprio PC la suddetta attestazione utilizzando le istruzioni riportate nella GUIDA allegata.<\/p>\n<p>Per informazioni e chiarimenti \u00e8 possibile inviare una e-mail al seguente indirizzo di posta elettronica:<\/p>\n<p>mensacapranica@laroccaservices.it<\/p>\n<p>oppure contattare il numero 0761-667922<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_5159\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/05\/guida-attestazione-fiscale.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/05\/guida-attestazione-fiscale.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>guida-attestazione-fiscale<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che \u00e8 possibile richiedere attraverso il portale della mensa scolastica, utilizzando le proprie credenziali, l&#8217;attestazione relativa alle spese sostenute per il servizio di refezione per l&#8217;anno 2019 utile [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":178,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-5158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scuola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019 - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019 - Capranica\" \/>\n<meta property=\"og:description\" content=\"Si comunica che \u00e8 possibile richiedere attraverso il portale della mensa scolastica, utilizzando le proprie credenziali, l&#8217;attestazione relativa alle spese sostenute per il servizio di refezione per l&#8217;anno 2019 utile [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-05T08:14:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019\",\"datePublished\":\"2020-05-05T08:14:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/\"},\"wordCount\":101,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"articleSection\":[\"Scuola\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/\",\"name\":\"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019 - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"datePublished\":\"2020-05-05T08:14:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/02\\\/AVVISO-ALLA-CITTADINANZA.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/05\\\/05\\\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019 - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/","og_locale":"it_IT","og_type":"article","og_title":"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019 - Capranica","og_description":"Si comunica che \u00e8 possibile richiedere attraverso il portale della mensa scolastica, utilizzando le proprie credenziali, l&#8217;attestazione relativa alle spese sostenute per il servizio di refezione per l&#8217;anno 2019 utile [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-05-05T08:14:52+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019","datePublished":"2020-05-05T08:14:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/"},"wordCount":101,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","articleSection":["Scuola"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/","url":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/","name":"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019 - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","datePublished":"2020-05-05T08:14:52+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/02\/AVVISO-ALLA-CITTADINANZA.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2020\/05\/05\/attestazione-per-le-spese-sostenute-per-il-servizio-refezione-scolastica-anno-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"ATTESTAZIONE PER LE SPESE SOSTENUTE PER IL SERVIZIO REFEZIONE SCOLASTICA ANNO 2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/5158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=5158"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/5158\/revisions"}],"predecessor-version":[{"id":5160,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/5158\/revisions\/5160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/178"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=5158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=5158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=5158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}