{"id":5569,"date":"2020-07-14T12:50:49","date_gmt":"2020-07-14T10:50:49","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=5569"},"modified":"2020-07-14T12:50:49","modified_gmt":"2020-07-14T10:50:49","slug":"avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/","title":{"rendered":"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30"},"content":{"rendered":"<p>Si avvisa la cittadinanza che in data <strong>21 luglio 2020, dalle ore 8:30 alle ore 15:30<\/strong>, verr\u00e0 interrotta la fornitura dell&#8217;energia elettrica per lavori sugli impianti da parte di E-Distribuzione.<\/p>\n<p>Le <strong>vie interessate all&#8217;interruzione sono elencate all&#8217;interno della locandina allegata all&#8217;articolo<\/strong> e scaricabile e che \u00e8 gi\u00e0 stato effettuato il volantinaggio sulle vie interessate alla sospensione dell\u2019energia elettrica.<\/p>\n<p>Per informazioni sui lavori programmati o pi\u00f9 in generale sulle interruzioni del servizio potete consultare il sito e-distribuzione.it oppure inviare un SMS al numero 320.2041500 riportando il codice POD(IT001E&#8230;) presente in bolletta, oppure scaricare e consultare la App gratuita per Smartphone &#8220;Guasti e-distribuzione&#8221;.<br \/>\nPer segnalare un guasto potete invece rivolgervi al Numero Verde 803.500.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_5570\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/07\/avvisi-Capranica.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2020\/07\/avvisi-Capranica.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso Interruzione Energia Elettrica 21 luglio<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si avvisa la cittadinanza che in data 21 luglio 2020, dalle ore 8:30 alle ore 15:30, verr\u00e0 interrotta la fornitura dell&#8217;energia elettrica per lavori sugli impianti da parte di E-Distribuzione. [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-5569","post","type-post","status-publish","format-standard","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30 - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30 - Capranica\" \/>\n<meta property=\"og:description\" content=\"Si avvisa la cittadinanza che in data 21 luglio 2020, dalle ore 8:30 alle ore 15:30, verr\u00e0 interrotta la fornitura dell&#8217;energia elettrica per lavori sugli impianti da parte di E-Distribuzione. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-14T10:50:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/interruzione-di-servizio.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/07\\\/14\\\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/07\\\/14\\\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30\",\"datePublished\":\"2020-07-14T10:50:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/07\\\/14\\\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\\\/\"},\"wordCount\":118,\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/07\\\/14\\\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/07\\\/14\\\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\\\/\",\"name\":\"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30 - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"datePublished\":\"2020-07-14T10:50:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/07\\\/14\\\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/07\\\/14\\\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2020\\\/07\\\/14\\\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30 - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/","og_locale":"it_IT","og_type":"article","og_title":"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30 - Capranica","og_description":"Si avvisa la cittadinanza che in data 21 luglio 2020, dalle ore 8:30 alle ore 15:30, verr\u00e0 interrotta la fornitura dell&#8217;energia elettrica per lavori sugli impianti da parte di E-Distribuzione. [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-07-14T10:50:49+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/interruzione-di-servizio.png","height":600,"width":1200,"type":""}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30","datePublished":"2020-07-14T10:50:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/"},"wordCount":118,"articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/","url":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/","name":"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30 - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"datePublished":"2020-07-14T10:50:49+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2020\/07\/14\/avviso-interruzione-di-energia-elettrica-21-luglio-dalle-ore-830-alle-1530\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"AVVISO INTERRUZIONE DI ENERGIA ELETTRICA 21 LUGLIO DALLE ORE 8:30 ALLE 15:30"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/5569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=5569"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/5569\/revisions"}],"predecessor-version":[{"id":5571,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/5569\/revisions\/5571"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=5569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=5569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=5569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}