{"id":557,"date":"2017-05-29T19:50:48","date_gmt":"2017-05-29T17:50:48","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?p=557"},"modified":"2017-05-29T19:50:48","modified_gmt":"2017-05-29T17:50:48","slug":"associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/","title":{"rendered":"ASSOCIAZIONE \u201cCAPRALICA\u201d &#8211; ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO"},"content":{"rendered":"<p>L\u2019associazione culturale \u201cCapralica\u201d organizza per domenica prossima, 4 giugno, un\u2019escursione a Valle di Fosso Castello, Bomarzo, sulle orme degli antichi etruschi. Punti di interesse sul percorso: Torre di Chia (Castello di Pasolini), Cascate di Fosso Castello, vista panoramica sulla Valle del Tevere, area archeologica di Valle Cecilia e Piramide di Bomarzo, luoghi magici di grande valore storico-naturalistico.<\/p>\n<p><strong>Prenotazione obbligatoria entro gioved\u00ec 1 giugno al 3401481139<\/strong><\/p>\n<p>Per informazioni e orari consultare la locandina dell\u2019evento allegata a questa notizia.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_558\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/escursione-20170604.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/05\/escursione-20170604.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Locandina Escursione Valle di Fosso Castello<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019associazione culturale \u201cCapralica\u201d organizza per domenica prossima, 4 giugno, un\u2019escursione a Valle di Fosso Castello, Bomarzo, sulle orme degli antichi etruschi. Punti di interesse sul percorso: Torre di Chia (Castello [&hellip;]<\/p>\n","protected":false},"author":210,"featured_media":405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASSOCIAZIONE \u201cCAPRALICA\u201d - ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASSOCIAZIONE \u201cCAPRALICA\u201d - ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO - Capranica\" \/>\n<meta property=\"og:description\" content=\"L\u2019associazione culturale \u201cCapralica\u201d organizza per domenica prossima, 4 giugno, un\u2019escursione a Valle di Fosso Castello, Bomarzo, sulle orme degli antichi etruschi. Punti di interesse sul percorso: Torre di Chia (Castello [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-29T17:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/copertina-associazione-capralica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pnocchi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pnocchi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/\"},\"author\":{\"name\":\"pnocchi\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"headline\":\"ASSOCIAZIONE \u201cCAPRALICA\u201d &#8211; ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO\",\"datePublished\":\"2017-05-29T17:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/\"},\"wordCount\":91,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/04\\\/copertina-associazione-capralica.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/\",\"name\":\"ASSOCIAZIONE \u201cCAPRALICA\u201d - ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/04\\\/copertina-associazione-capralica.jpg\",\"datePublished\":\"2017-05-29T17:50:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/04\\\/copertina-associazione-capralica.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2017\\\/04\\\/copertina-associazione-capralica.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/2017\\\/05\\\/29\\\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASSOCIAZIONE \u201cCAPRALICA\u201d &#8211; ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#\\\/schema\\\/person\\\/e7370321f1820e23b7772e4edb7094f7\",\"name\":\"pnocchi\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g\",\"caption\":\"pnocchi\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/author\\\/pnocchi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASSOCIAZIONE \u201cCAPRALICA\u201d - ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/","og_locale":"it_IT","og_type":"article","og_title":"ASSOCIAZIONE \u201cCAPRALICA\u201d - ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO - Capranica","og_description":"L\u2019associazione culturale \u201cCapralica\u201d organizza per domenica prossima, 4 giugno, un\u2019escursione a Valle di Fosso Castello, Bomarzo, sulle orme degli antichi etruschi. Punti di interesse sul percorso: Torre di Chia (Castello [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2017-05-29T17:50:48+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/copertina-associazione-capralica.jpg","type":"image\/jpeg"}],"author":"pnocchi","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"pnocchi"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/"},"author":{"name":"pnocchi","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"headline":"ASSOCIAZIONE \u201cCAPRALICA\u201d &#8211; ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO","datePublished":"2017-05-29T17:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/"},"wordCount":91,"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/copertina-associazione-capralica.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/","url":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/","name":"ASSOCIAZIONE \u201cCAPRALICA\u201d - ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/copertina-associazione-capralica.jpg","datePublished":"2017-05-29T17:50:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/copertina-associazione-capralica.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2017\/04\/copertina-associazione-capralica.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/2017\/05\/29\/associazione-capralica-escursione-di-primavera-alla-scoperta-degli-etruschi-valle-di-fosso-castello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"ASSOCIAZIONE \u201cCAPRALICA\u201d &#8211; ESCURSIONE DI PRIMAVERA ALLA SCOPERTA DEGLI ETRUSCHI: VALLE DI FOSSO CASTELLO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/capranica\/#\/schema\/person\/e7370321f1820e23b7772e4edb7094f7","name":"pnocchi","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eb0f8dcac10a66dc7f4bd3af32201815b86f1b6fa7ac4fe9a21e65aca5dfc340?s=96&d=mm&r=g","caption":"pnocchi"},"url":"https:\/\/comunicacity.net\/capranica\/author\/pnocchi\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/comments?post=557"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/557\/revisions"}],"predecessor-version":[{"id":559,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/posts\/557\/revisions\/559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/405"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/categories?post=557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/tags?post=557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}