{"id":2282,"date":"2018-09-05T11:49:26","date_gmt":"2018-09-05T09:49:26","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?post_type=turismo&#038;p=2282"},"modified":"2018-09-10T13:18:56","modified_gmt":"2018-09-10T11:18:56","slug":"pizzeria-da-fefo","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/","title":{"rendered":"Pizzeria da Fefo"},"content":{"rendered":"<p><i class=\"fa fa-phone\"><\/i><a href=\"tel:0761 678934\"> 0761 678934<\/a><\/p>\n<p><i class=\"fa fa-phone\"><\/i><a href=\"3395394960\"> 3395394960<\/a><\/p>\n<p><i class=\"fa fa-envelope\"><\/i><a href=\"mailto:tonino.pellegrini@alice,it\"> tonino.pellegrini@alice,it<\/a><\/p>\n<p><i class=\"fa fa-facebook icon\"><\/i> <a href=\"https:\/\/www.facebook.com\/Pizzeria-da-Fefo-110224292382049\/\"> Pizzeria da Fefo<\/a><\/p>\n<p><i class=\"fa fa-clock-o\"><\/i>Tutti i giorni <span class=\"ccBold\"> 17:30 \u2013 24:00<\/span><\/p>\n<p><i class=\"map marker icon\"><\/i> Via dei Ruscelli,19<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2952.8753573727795!2d12.171347415701106!3d42.25983424941722!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x132f3685bd739f93%3A0x7dea1fd6d67cf98c!2sDa+Fefo!5e0!3m2!1sit!2sit!4v1536140694910\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>0761 678934 3395394960 tonino.pellegrini@alice,it Pizzeria da Fefo Tutti i giorni 17:30 \u2013 24:00 Via dei Ruscelli,19<\/p>\n","protected":false},"featured_media":2284,"parent":2130,"menu_order":0,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-2282","turismo","type-turismo","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pizzeria da Fefo - Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pizzeria da Fefo - Capranica\" \/>\n<meta property=\"og:description\" content=\"0761 678934 3395394960 tonino.pellegrini@alice,it Pizzeria da Fefo Tutti i giorni 17:30 \u2013 24:00 Via dei Ruscelli,19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-10T11:18:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2018\/09\/Pizzeria-da-Fefo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/pizzeria-da-fefo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/pizzeria-da-fefo\\\/\",\"name\":\"Pizzeria da Fefo - Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/pizzeria-da-fefo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/pizzeria-da-fefo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2018\\\/09\\\/Pizzeria-da-Fefo.jpg\",\"datePublished\":\"2018-09-05T09:49:26+00:00\",\"dateModified\":\"2018-09-10T11:18:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/pizzeria-da-fefo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/pizzeria-da-fefo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/pizzeria-da-fefo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2018\\\/09\\\/Pizzeria-da-Fefo.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/wp-content\\\/uploads\\\/sites\\\/68\\\/2018\\\/09\\\/Pizzeria-da-Fefo.jpg\",\"width\":500,\"height\":375},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/pizzeria-da-fefo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rete Capranica Francigena\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ristorazione\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/ristorazione\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pizzeria da Fefo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pizzeria da Fefo - Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/","og_locale":"it_IT","og_type":"article","og_title":"Pizzeria da Fefo - Capranica","og_description":"0761 678934 3395394960 tonino.pellegrini@alice,it Pizzeria da Fefo Tutti i giorni 17:30 \u2013 24:00 Via dei Ruscelli,19","og_url":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2018-09-10T11:18:56+00:00","og_image":[{"width":500,"height":375,"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2018\/09\/Pizzeria-da-Fefo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/","url":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/","name":"Pizzeria da Fefo - Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2018\/09\/Pizzeria-da-Fefo.jpg","datePublished":"2018-09-05T09:49:26+00:00","dateModified":"2018-09-10T11:18:56+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/#primaryimage","url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2018\/09\/Pizzeria-da-Fefo.jpg","contentUrl":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2018\/09\/Pizzeria-da-Fefo.jpg","width":500,"height":375},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/pizzeria-da-fefo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"Rete Capranica Francigena","item":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/"},{"@type":"ListItem","position":3,"name":"Ristorazione","item":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/ristorazione\/"},{"@type":"ListItem","position":4,"name":"Pizzeria da Fefo"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/turismo\/2282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/turismo\/2130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media\/2284"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=2282"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/plugin_turismo?post=2282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}