{"id":2466,"date":"2018-09-28T12:22:54","date_gmt":"2018-09-28T10:22:54","guid":{"rendered":"https:\/\/comunicacity.net\/capranica\/?post_type=turismo&#038;p=2466"},"modified":"2018-09-28T12:22:54","modified_gmt":"2018-09-28T10:22:54","slug":"2466-2","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/","title":{"rendered":""},"content":{"rendered":"<p>Salone per uomo e per donna che dal 1988 si prende cura del look dei propri clienti, accolti in un ambiente elegante e raffinato, con attrezzature moderne e prodotti per la cura dei capelli di alta qualit\u00e0.<\/p>\n<p><strong>I nostri brand:<\/strong> L\u2019Oreal Professionnel &amp; Ghd<\/p>\n<p>Il nostro salone offre :<\/p>\n<p>    -acconciature da sposa<br \/>\n    -colpi di sole<br \/>\n    &#8211; sfumature di colore<br \/>\n    &#8211; messa in piega con piastra<br \/>\n    &#8211; permanente<br \/>\n    &#8211; messa in piega<br \/>\n    &#8211; acconciature<br \/>\n    &#8211; taglio e piega<\/p>\n<p><i class=\"fa fa-phone\"><\/i><a href=\"tel:0761 678894\"> 0761 678894<\/a> <\/p>\n<p><i class=\"fa fa-facebook icon\"><\/i> <a href=\"https:\/\/www.facebook.com\/parrucchiere.domenico\/\"> Parrucchiere Domenico<\/a><\/p>\n<p><i class=\"fa fa-clock-o\"><\/i> Marted\u00ec &#8211; sabato <span class=\"ccBold\">9:00 \u2013 13:00<\/span> &#8211; <span class=\"ccBold\">15:00 \u2013 19:00<\/span><br \/>\nDal Martedi al Gioved\u00ec si riceve per appuntamento<br \/>\n<span class=\"ccBold\">Chiuso:<\/span> Luned\u00ec e Domenica<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Salone per uomo e per donna che dal 1988 si prende cura del look dei propri clienti, accolti in un ambiente elegante e raffinato, con attrezzature moderne e prodotti per [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":2132,"menu_order":0,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-2466","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>- Capranica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"- Capranica\" \/>\n<meta property=\"og:description\" content=\"Salone per uomo e per donna che dal 1988 si prende cura del look dei propri clienti, accolti in un ambiente elegante e raffinato, con attrezzature moderne e prodotti per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Capranica\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2016\/10\/capranica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/servizi-alla-persona\\\/2466-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/servizi-alla-persona\\\/2466-2\\\/\",\"name\":\"- Capranica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\"},\"datePublished\":\"2018-09-28T10:22:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/servizi-alla-persona\\\/2466-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/servizi-alla-persona\\\/2466-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/servizi-alla-persona\\\/2466-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rete Capranica Francigena\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Servizi alla persona\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/turismo\\\/aziende\\\/servizi-alla-persona\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/\",\"name\":\"Capranica\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/capranica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"- Capranica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/","og_locale":"it_IT","og_type":"article","og_title":"- Capranica","og_description":"Salone per uomo e per donna che dal 1988 si prende cura del look dei propri clienti, accolti in un ambiente elegante e raffinato, con attrezzature moderne e prodotti per [&hellip;]","og_url":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/","og_site_name":"Capranica","article_publisher":"http:\/\/facebook.com\/ComunicaCity","og_image":[{"url":"https:\/\/comunicacity.net\/capranica\/wp-content\/uploads\/sites\/68\/2016\/10\/capranica.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/","url":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/","name":"- Capranica","isPartOf":{"@id":"https:\/\/comunicacity.net\/capranica\/#website"},"datePublished":"2018-09-28T10:22:54+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/2466-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/capranica\/"},{"@type":"ListItem","position":2,"name":"Rete Capranica Francigena","item":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/"},{"@type":"ListItem","position":3,"name":"Servizi alla persona","item":"https:\/\/comunicacity.net\/capranica\/turismo\/aziende\/servizi-alla-persona\/"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/capranica\/#website","url":"https:\/\/comunicacity.net\/capranica\/","name":"Capranica","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/capranica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/turismo\/2466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/types\/turismo"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/turismo\/2132"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/media?parent=2466"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/capranica\/wp-json\/wp\/v2\/plugin_turismo?post=2466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}