{"id":126,"date":"2026-01-19T14:34:34","date_gmt":"2026-01-19T13:34:34","guid":{"rendered":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/"},"modified":"2026-01-20T15:52:52","modified_gmt":"2026-01-20T14:52:52","slug":"allerta-meteo-aggiornamento","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/","title":{"rendered":"ALLERTA METEO &#8211; Aggiornamento &#8211;  20-01-2026"},"content":{"rendered":"<p><em>Raccomandazioni di natura comportamentale generale, Interruzione attivit\u00e0<br \/>\ndidattiche del Plesso Scolastico Comunale, chiusura parco giochi comunale e<br \/>\ndivieto di utilizzo strutture sportive comunali per il giorno 20\/01\/2026 e 21\/01\/2026<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si informa la cittadinanza che per la giornata odierna permane il livello di ALLERTA METEO ROSSA, mentre per la giornata di domani \u00e8 stata diramata e confermata ALLERTA METEO ROSSA per rischio idrogeologico e idraulico.<\/p>\n<p>Alla luce delle condizioni meteorologiche previste, l\u2019Amministrazione Comunale dispone e raccomanda quanto segue:<\/p>\n<p>Per la giornata di domani \u00e8 disposta la chiusura di:<br \/>\n&#8211; tutte le scuole di ogni ordine e grado;<br \/>\n&#8211; il Parco e le Ville Comunali;<br \/>\n&#8211; gli impianti sportivi comunali;<br \/>\nnonch\u00e9 la chiusura al pubblico degli uffici comunali.<\/p>\n<p>\u00c8 altres\u00ec disposta la sospensione di tutti gli eventi pubblici e privati.<\/p>\n<ul>\n<li>Si raccomanda di limitare gli spostamenti esclusivamente ai casi di stretta necessit\u00e0.<\/li>\n<li>Evitare di percorrere e\/o sostare su strade, sottopassi, pontini (scatolari, ecc.) e in tutte le aree segnalate a rischio allagamento.<\/li>\n<li>Evitare di transitare o sostare in zone alberate.<\/li>\n<li>Segnalare tempestivamente agli uffici comunali qualsiasi situazione di reale pericolo.<\/li>\n<li>Mettere in sicurezza e fissare adeguatamente tutti gli oggetti presenti su balconi, davanzali, terrazzi e aree esterne (vasi, arredi, antenne, coperture o rivestimenti dei tetti) che potrebbero essere trasportati dal vento o dalle forti raffiche.<\/li>\n<\/ul>\n<p>Si invita la cittadinanza a seguire esclusivamente le comunicazioni ufficiali e a collaborare responsabilmente per la tutela della propria sicurezza e di quella collettiva.<\/p>\n<p>Ulteriori aggiornamenti saranno comunicati tempestivamente.<br \/>\nL\u2019Amministrazione Comunale<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_141\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/5_2026-allerta-meteo-Rossa-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/5_2026-allerta-meteo-Rossa-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>5_2026 allerta meteo Rossa<\/a><\/li>\n<li><a id=\"wpba_attachment_list_142\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/MAU-19012026-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/MAU-19012026-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MAU 19012026<\/a><\/li>\n<li><a id=\"wpba_attachment_list_143\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/MAU_20012026_EC.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/MAU_20012026_EC.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MAU_20012026_EC<\/a><\/li>\n<li><a id=\"wpba_attachment_list_144\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/6_2026-ordinanza-chiusura-scuole-allerta-meteo-Rossa.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/6_2026-ordinanza-chiusura-scuole-allerta-meteo-Rossa.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>6_2026 ordinanza chiusura scuole allerta meteo Rossa<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Raccomandazioni di natura comportamentale generale, Interruzione attivit\u00e0 didattiche del Plesso Scolastico Comunale, chiusura parco giochi comunale e divieto di utilizzo strutture sportive comunali per il giorno 20\/01\/2026 e 21\/01\/2026&nbsp; Descrizione&nbsp; [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":140,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALLERTA METEO - Aggiornamento - 20-01-2026 - Caraffa di Catanzaro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALLERTA METEO - Aggiornamento - 20-01-2026 - Caraffa di Catanzaro\" \/>\n<meta property=\"og:description\" content=\"Raccomandazioni di natura comportamentale generale, Interruzione attivit\u00e0 didattiche del Plesso Scolastico Comunale, chiusura parco giochi comunale e divieto di utilizzo strutture sportive comunali per il giorno 20\/01\/2026 e 21\/01\/2026&nbsp; Descrizione&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/\" \/>\n<meta property=\"og:site_name\" content=\"Caraffa di Catanzaro\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T13:34:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-20T14:52:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/Allerta-Meteo-Home-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"553\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"ALLERTA METEO &#8211; Aggiornamento &#8211; 20-01-2026\",\"datePublished\":\"2026-01-19T13:34:34+00:00\",\"dateModified\":\"2026-01-20T14:52:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/wp-content\\\/uploads\\\/sites\\\/222\\\/2026\\\/01\\\/Allerta-Meteo-Home-2.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/\",\"name\":\"ALLERTA METEO - Aggiornamento - 20-01-2026 - Caraffa di Catanzaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/wp-content\\\/uploads\\\/sites\\\/222\\\/2026\\\/01\\\/Allerta-Meteo-Home-2.png\",\"datePublished\":\"2026-01-19T13:34:34+00:00\",\"dateModified\":\"2026-01-20T14:52:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/wp-content\\\/uploads\\\/sites\\\/222\\\/2026\\\/01\\\/Allerta-Meteo-Home-2.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/wp-content\\\/uploads\\\/sites\\\/222\\\/2026\\\/01\\\/Allerta-Meteo-Home-2.png\",\"width\":553,\"height\":420},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/2026\\\/01\\\/19\\\/allerta-meteo-aggiornamento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLERTA METEO &#8211; Aggiornamento &#8211; 20-01-2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caraffadicatanzaro\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALLERTA METEO - Aggiornamento - 20-01-2026 - Caraffa di Catanzaro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/","og_locale":"it_IT","og_type":"article","og_title":"ALLERTA METEO - Aggiornamento - 20-01-2026 - Caraffa di Catanzaro","og_description":"Raccomandazioni di natura comportamentale generale, Interruzione attivit\u00e0 didattiche del Plesso Scolastico Comunale, chiusura parco giochi comunale e divieto di utilizzo strutture sportive comunali per il giorno 20\/01\/2026 e 21\/01\/2026&nbsp; Descrizione&nbsp; [&hellip;]","og_url":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/","og_site_name":"Caraffa di Catanzaro","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-19T13:34:34+00:00","article_modified_time":"2026-01-20T14:52:52+00:00","og_image":[{"width":553,"height":420,"url":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/Allerta-Meteo-Home-2.png","type":"image\/png"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"ALLERTA METEO &#8211; Aggiornamento &#8211; 20-01-2026","datePublished":"2026-01-19T13:34:34+00:00","dateModified":"2026-01-20T14:52:52+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/"},"wordCount":252,"publisher":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/Allerta-Meteo-Home-2.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/","url":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/","name":"ALLERTA METEO - Aggiornamento - 20-01-2026 - Caraffa di Catanzaro","isPartOf":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/Allerta-Meteo-Home-2.png","datePublished":"2026-01-19T13:34:34+00:00","dateModified":"2026-01-20T14:52:52+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/#primaryimage","url":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/Allerta-Meteo-Home-2.png","contentUrl":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-content\/uploads\/sites\/222\/2026\/01\/Allerta-Meteo-Home-2.png","width":553,"height":420},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/2026\/01\/19\/allerta-meteo-aggiornamento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/caraffadicatanzaro\/"},{"@type":"ListItem","position":2,"name":"ALLERTA METEO &#8211; Aggiornamento &#8211; 20-01-2026"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#website","url":"https:\/\/comunicacity.net\/caraffadicatanzaro\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/caraffadicatanzaro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/caraffadicatanzaro\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/caraffadicatanzaro\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000953"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/posts\/126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"predecessor-version":[{"id":139,"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/posts\/126\/revisions\/139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/media\/140"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/caraffadicatanzaro\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}