{"id":470,"date":"2025-05-16T08:59:33","date_gmt":"2025-05-16T06:59:33","guid":{"rendered":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/"},"modified":"2025-05-16T08:59:33","modified_gmt":"2025-05-16T06:59:33","slug":"gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/","title":{"rendered":"Gemellaggio con la comunit\u00e0 di Gottmadingen &#8211; Visita di una delegazione istituzionale del comune tedesco."},"content":{"rendered":"<p><em>Dal 30 maggio al 4 giugno una delegazione ufficiale del comune di Gottmadingen sar\u00e0 ospite del nostro comune per partecipare alle manifestazioni e attivit\u00e0 organizzate per le celebrazioni del 31^ anniversario del gemellaggio. <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Nel 1991, viene fondata in Gottmadingen (Germania), un\u2019associazione italo-tedesca. Sono principalmente i nostri concittadini emigranti a promuovere la costituzione di questa Associazione Onlus, confermando la piena integrazione sociale raggiunta, rafforzando i legami di amicizia e collaborazione fra italiani e tedeschi. dopo gli anni 50 a gottmadingen si \u00e8 concentrata la piu&#8217; importante emigrazione di nostri concittadini nel mondo.Fino agli anni 80-90 esisteva davvero una piccola stimata comunit\u00e0 casellese in Gottmadingen, che si era saputa affermare e apprezzare nella realt\u00e0 sociale del piccolo centro tedesco. Da questo stretto rapporto di convivenza civile, nasce l\u2019idea di un Gemellaggio fra le rispettive comunit\u00e0.<\/p>\n<p>Dopo i primi anni di interscambio socio-culturale, nel 1993 i due sindaci a Gottmadingen convengono di stringere un patto per il gemellaggio e nel 1994, a Caselle in Pittari, viene sottoscritto il patto di amicizia, fratellanza e solidariet\u00e0 (GIURAMENTO DI FRATERNITA\u2019) tra i comuni di Caselle in Pittari e Gottmadingen. Nasce ufficialmente e viene reso istituzionale il Gemellaggio fra queste due comunit\u00e0. Da quel momento si concretizzano ulteriori occasioni di scambi socio-culturali, con visite ufficiali ogni anno di delegazioni Comunali. Il gemellaggio istituzionale sar\u00e0 promotore anche di un gemellaggio scolastico fra gli studenti delle due comunit\u00e0.<\/p>\n<p>Nel corso delle varie manifestazioni annuali del gemellaggio a Gottmadingen, si segnala tra l\u2019altro, in qualche occasione, al seguito della delegazione casellese, la partecipazione della banda musicale \u201cG. Verdi\u201d, del coro polifonico e della compagnia teatrale.<\/p>\n<p>In occasione delle iniziative promosse a Caselle in Pittari, si ricorda tra l\u2019altro l\u2019intervento e partecipazione di consoli tedeschi in Napoli. Anche quest&#8217;anno in occasione delle celebrazioni per il gemellaggio \u00e8 previsto l&#8217;intervento del console onorario della germania.<\/p>\n<p>Dal 2021,le visite istituzionali sono a cadenza biennale.<\/p>\n<p>Dopo la visita di una delegazione del nostro comune a gottmadingen nel 2023, quest&#8217;anno a Caselle in Pittari si svolgeranno le iniziative per celebrare il 31^ anniversario del gemellaggio e sar\u00e0 ospite del nostro comune una delegazione tedesca guidata dal borgomastro di gottmadingen e il presidente altri membri dell&#8217;associazione italo-tedesca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 30 maggio al 4 giugno una delegazione ufficiale del comune di Gottmadingen sar\u00e0 ospite del nostro comune per partecipare alle manifestazioni e attivit\u00e0 organizzate per le celebrazioni del 31^ [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gemellaggio con la comunit\u00e0 di Gottmadingen - Visita di una delegazione istituzionale del comune tedesco. - Caselle in Pittari<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemellaggio con la comunit\u00e0 di Gottmadingen - Visita di una delegazione istituzionale del comune tedesco. - Caselle in Pittari\" \/>\n<meta property=\"og:description\" content=\"Dal 30 maggio al 4 giugno una delegazione ufficiale del comune di Gottmadingen sar\u00e0 ospite del nostro comune per partecipare alle manifestazioni e attivit\u00e0 organizzate per le celebrazioni del 31^ [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/\" \/>\n<meta property=\"og:site_name\" content=\"Caselle in Pittari\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-16T06:59:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/05\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"1755\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Gemellaggio con la comunit\u00e0 di Gottmadingen &#8211; Visita di una delegazione istituzionale del comune tedesco.\",\"datePublished\":\"2025-05-16T06:59:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/\"},\"wordCount\":374,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/05\\\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/\",\"name\":\"Gemellaggio con la comunit\u00e0 di Gottmadingen - Visita di una delegazione istituzionale del comune tedesco. - Caselle in Pittari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/05\\\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg\",\"datePublished\":\"2025-05-16T06:59:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/05\\\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/05\\\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg\",\"width\":1240,\"height\":1755},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/05\\\/16\\\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemellaggio con la comunit\u00e0 di Gottmadingen &#8211; Visita di una delegazione istituzionale del comune tedesco.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemellaggio con la comunit\u00e0 di Gottmadingen - Visita di una delegazione istituzionale del comune tedesco. - Caselle in Pittari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/","og_locale":"it_IT","og_type":"article","og_title":"Gemellaggio con la comunit\u00e0 di Gottmadingen - Visita di una delegazione istituzionale del comune tedesco. - Caselle in Pittari","og_description":"Dal 30 maggio al 4 giugno una delegazione ufficiale del comune di Gottmadingen sar\u00e0 ospite del nostro comune per partecipare alle manifestazioni e attivit\u00e0 organizzate per le celebrazioni del 31^ [&hellip;]","og_url":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/","og_site_name":"Caselle in Pittari","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-05-16T06:59:33+00:00","og_image":[{"width":1240,"height":1755,"url":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/05\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Gemellaggio con la comunit\u00e0 di Gottmadingen &#8211; Visita di una delegazione istituzionale del comune tedesco.","datePublished":"2025-05-16T06:59:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/"},"wordCount":374,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/05\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/","url":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/","name":"Gemellaggio con la comunit\u00e0 di Gottmadingen - Visita di una delegazione istituzionale del comune tedesco. - Caselle in Pittari","isPartOf":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/05\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg","datePublished":"2025-05-16T06:59:33+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/#primaryimage","url":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/05\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg","contentUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/05\/MANIFESTO-GEMELLAGGIO-CASELLE-GOTTMADINGEN-2025.jpg","width":1240,"height":1755},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/05\/16\/gemellaggio-con-la-comunita-di-gottmadingen-visita-di-una-delegazione-istituzionale-del-comune-tedesco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/caselleinpittari\/"},{"@type":"ListItem","position":2,"name":"Gemellaggio con la comunit\u00e0 di Gottmadingen &#8211; Visita di una delegazione istituzionale del comune tedesco."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#website","url":"https:\/\/comunicacity.net\/caselleinpittari\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/caselleinpittari\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/caselleinpittari\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001902"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/media\/471"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}