{"id":596,"date":"2025-08-09T09:49:51","date_gmt":"2025-08-09T07:49:51","guid":{"rendered":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/"},"modified":"2025-08-09T10:15:14","modified_gmt":"2025-08-09T08:15:14","slug":"manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/","title":{"rendered":"Manifestazione pubblica &#8220;RON IN CONCERTO&#8221; disciplina della circolazione stradale &#8211; Ordinanza Sindacale per divieto di transito e divieto di sosta"},"content":{"rendered":"<p><em>In occasione del concerto pubblico dell&#8217;artista Ron, con ordinanza sindacale n. 23\/2025, vengono istituiti divieti di transito e di sosta, per consentire l&#8217;ampliamento del palco in viale roma.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div class=\"x14z9mp xat24cr x1lziwak x1vvkbs xtlvy1s x126k92a\">\n<div dir=\"auto\">COMUNICAZIONE IMPORTANTE &#8211; URGENTE<\/div>\n<div dir=\"auto\">VISTA l\u2019autorizzazione temporanea di occupazione suolo pubblico,<\/div>\n<div dir=\"auto\">per lo svolgimento della manifestazione \u201cRON in concerto\u201d prevista per il 10 agosto 2025 in piazza olmo, viale Roma;<\/div>\n<div dir=\"auto\">CONISDERATO quindi che occorre ampliare l\u2019attuale palco gi\u00e0 installato e che la superficie che andr\u00e0 a coprire occuper\u00e0 tutta l\u2019area dell\u2019incrocio tra viale Roma (lato est), via Indipendenza e piazza Europa:<\/div>\n<div dir=\"auto\">con ordinanza n. 23\/2025 viene disposto quanto segue:<\/div>\n<div dir=\"auto\">Il DIVIETO DI TRANSITO su piazza Europa, su Via Indipendenza (lato Forgia) dalle ore 08.00 del 10 agosto 2025 fino alle ore 08.00 del giorno 11\/08\/2025;<\/div>\n<div dir=\"auto\">IL DIVIETO DI SOSTA, per tutti gli autoveicoli negli stalli di sosta sul Piazza Europa, su via Santa Lucia (Chiazzile), su via Indipendenza (lato Forgia) dalle ore 08.00 del 10 agosto 2025 fino alle ore 08.00 del giorno 11\/08\/2025.<\/div>\n<div dir=\"auto\">Per ogni altro ulteriore dettaglio si rimanda all&#8217;ordinanza sindacale (vedi allegato):<\/div>\n<div dir=\"auto\">https:\/\/www.halleyweb.com\/c065029\/mc\/mc_p_dettaglio.php?id_pubbl=10192<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione del concerto pubblico dell&#8217;artista Ron, con ordinanza sindacale n. 23\/2025, vengono istituiti divieti di transito e di sosta, per consentire l&#8217;ampliamento del palco in viale roma.&nbsp; Descrizione&nbsp; COMUNICAZIONE [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Manifestazione pubblica &quot;RON IN CONCERTO&quot; disciplina della circolazione stradale - Ordinanza Sindacale per divieto di transito e divieto di sosta - Caselle in Pittari<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manifestazione pubblica &quot;RON IN CONCERTO&quot; disciplina della circolazione stradale - Ordinanza Sindacale per divieto di transito e divieto di sosta - Caselle in Pittari\" \/>\n<meta property=\"og:description\" content=\"In occasione del concerto pubblico dell&#8217;artista Ron, con ordinanza sindacale n. 23\/2025, vengono istituiti divieti di transito e di sosta, per consentire l&#8217;ampliamento del palco in viale roma.&nbsp; Descrizione&nbsp; COMUNICAZIONE [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/\" \/>\n<meta property=\"og:site_name\" content=\"Caselle in Pittari\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-09T07:49:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-09T08:15:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/08\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"958\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Manifestazione pubblica &#8220;RON IN CONCERTO&#8221; disciplina della circolazione stradale &#8211; Ordinanza Sindacale per divieto di transito e divieto di sosta\",\"datePublished\":\"2025-08-09T07:49:51+00:00\",\"dateModified\":\"2025-08-09T08:15:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/\"},\"wordCount\":198,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/08\\\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/\",\"name\":\"Manifestazione pubblica \\\"RON IN CONCERTO\\\" disciplina della circolazione stradale - Ordinanza Sindacale per divieto di transito e divieto di sosta - Caselle in Pittari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/08\\\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg\",\"datePublished\":\"2025-08-09T07:49:51+00:00\",\"dateModified\":\"2025-08-09T08:15:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/08\\\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/08\\\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg\",\"width\":960,\"height\":958},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/08\\\/09\\\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manifestazione pubblica &#8220;RON IN CONCERTO&#8221; disciplina della circolazione stradale &#8211; Ordinanza Sindacale per divieto di transito e divieto di sosta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manifestazione pubblica \"RON IN CONCERTO\" disciplina della circolazione stradale - Ordinanza Sindacale per divieto di transito e divieto di sosta - Caselle in Pittari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/","og_locale":"it_IT","og_type":"article","og_title":"Manifestazione pubblica \"RON IN CONCERTO\" disciplina della circolazione stradale - Ordinanza Sindacale per divieto di transito e divieto di sosta - Caselle in Pittari","og_description":"In occasione del concerto pubblico dell&#8217;artista Ron, con ordinanza sindacale n. 23\/2025, vengono istituiti divieti di transito e di sosta, per consentire l&#8217;ampliamento del palco in viale roma.&nbsp; Descrizione&nbsp; COMUNICAZIONE [&hellip;]","og_url":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/","og_site_name":"Caselle in Pittari","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-08-09T07:49:51+00:00","article_modified_time":"2025-08-09T08:15:14+00:00","og_image":[{"width":960,"height":958,"url":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/08\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Manifestazione pubblica &#8220;RON IN CONCERTO&#8221; disciplina della circolazione stradale &#8211; Ordinanza Sindacale per divieto di transito e divieto di sosta","datePublished":"2025-08-09T07:49:51+00:00","dateModified":"2025-08-09T08:15:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/"},"wordCount":198,"publisher":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/08\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/","url":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/","name":"Manifestazione pubblica \"RON IN CONCERTO\" disciplina della circolazione stradale - Ordinanza Sindacale per divieto di transito e divieto di sosta - Caselle in Pittari","isPartOf":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/08\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg","datePublished":"2025-08-09T07:49:51+00:00","dateModified":"2025-08-09T08:15:14+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/#primaryimage","url":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/08\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/08\/WhatsApp-Image-2025-08-06-at-11.48.151-1.jpeg","width":960,"height":958},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/08\/09\/manifestazione-pubblica-ron-in-concerto-disciplina-della-circolazione-stradale-ordinanza-sindacale-per-divieto-di-transito-e-divieto-di-sosta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/caselleinpittari\/"},{"@type":"ListItem","position":2,"name":"Manifestazione pubblica &#8220;RON IN CONCERTO&#8221; disciplina della circolazione stradale &#8211; Ordinanza Sindacale per divieto di transito e divieto di sosta"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#website","url":"https:\/\/comunicacity.net\/caselleinpittari\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/caselleinpittari\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/caselleinpittari\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001964"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/comments?post=596"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/596\/revisions"}],"predecessor-version":[{"id":601,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/596\/revisions\/601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/media\/602"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/media?parent=596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/categories?post=596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/tags?post=596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}