{"id":645,"date":"2025-09-09T09:57:35","date_gmt":"2025-09-09T07:57:35","guid":{"rendered":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/"},"modified":"2025-09-09T09:57:35","modified_gmt":"2025-09-09T07:57:35","slug":"avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/","title":{"rendered":"Avviso pubblico utilizzo del servizio di mensa scolastica per l&#8217;anno 2025\/2026"},"content":{"rendered":"<p><em>Si rende noto che sono aperte le iscrizioni al servizio di mensa scolastica. Il servizio ripartir\u00e0 a decorrere da luned\u00ec 6 Ottobre 2025.La domanda di iscrizione  dovr\u00e0 essere presentata entro mercoled\u00ec 1 ottobre 2025.<br \/>\n <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>La domanda di iscrizione, corredata dalla relativa documentazione (ISEE in corso di validit\u00e0), dovr\u00e0 essere<br \/>\npresentata accedendo al seguente link tramite Spid o CNS:\u00a0 https:\/\/servizi.comune.caselleinpittari.sa.it\/serviziospecifico\/90<\/p>\n<p>SI PRECISA, CHE PER POTER RICHIEDERE L\u2019UTILIZZO DEL SERVIZIO PER L\u2019A.S. 2025\/2026 \u00c8 NECESSARIO ESSERE IN REGOLA CON I PAGAMENTI DEGLI ANNI PRECEDENTI.<\/p>\n<p>Coloro che non produrranno la certificazione del reddito ISEE in corso di validit\u00e0 verranno inseriti automaticamente nella fascia di reddito pi\u00f9 alta, con la relativa contribuzione per il costo del singolo pasto. Sull&#8217;allegato avviso sono riportate le tariffe in base alle varie fasce ISEE.<\/p>\n<p>E\u2019 GARANTITO IL SERVIZIO DI ASSISTENZA PER COLORO CHE RISCONTRANO DIFFICOLTA\u2019 NELLA COMPILAZIONE DELL\u2019ISTANZA, DAL LUNEDI\u2019 AL VENERD\u00cc, DALLE ORE 10:00 ALLE ORE 12:30, PRESSO L\u2019UFFICIO PROTOCOLLO DELL\u2019ENTE.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_647\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/09\/documento-avviso_mensa-scolastica-25_26.docx-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/09\/documento-avviso_mensa-scolastica-25_26.docx-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>documento-avviso_mensa-scolastica-25_26.docx-1<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si rende noto che sono aperte le iscrizioni al servizio di mensa scolastica. Il servizio ripartir\u00e0 a decorrere da luned\u00ec 6 Ottobre 2025.La domanda di iscrizione dovr\u00e0 essere presentata entro [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":646,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico utilizzo del servizio di mensa scolastica per l&#039;anno 2025\/2026 - Caselle in Pittari<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico utilizzo del servizio di mensa scolastica per l&#039;anno 2025\/2026 - Caselle in Pittari\" \/>\n<meta property=\"og:description\" content=\"Si rende noto che sono aperte le iscrizioni al servizio di mensa scolastica. Il servizio ripartir\u00e0 a decorrere da luned\u00ec 6 Ottobre 2025.La domanda di iscrizione dovr\u00e0 essere presentata entro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Caselle in Pittari\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-09T07:57:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/09\/mensa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"191\" \/>\n\t<meta property=\"og:image:height\" content=\"100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Avviso pubblico utilizzo del servizio di mensa scolastica per l&#8217;anno 2025\\\/2026\",\"datePublished\":\"2025-09-09T07:57:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/\"},\"wordCount\":172,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/09\\\/mensa.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/\",\"name\":\"Avviso pubblico utilizzo del servizio di mensa scolastica per l'anno 2025\\\/2026 - Caselle in Pittari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/09\\\/mensa.jpg\",\"datePublished\":\"2025-09-09T07:57:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/09\\\/mensa.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/09\\\/mensa.jpg\",\"width\":191,\"height\":100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/09\\\/09\\\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico utilizzo del servizio di mensa scolastica per l&#8217;anno 2025\\\/2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico utilizzo del servizio di mensa scolastica per l'anno 2025\/2026 - Caselle in Pittari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico utilizzo del servizio di mensa scolastica per l'anno 2025\/2026 - Caselle in Pittari","og_description":"Si rende noto che sono aperte le iscrizioni al servizio di mensa scolastica. Il servizio ripartir\u00e0 a decorrere da luned\u00ec 6 Ottobre 2025.La domanda di iscrizione dovr\u00e0 essere presentata entro [&hellip;]","og_url":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/","og_site_name":"Caselle in Pittari","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-09-09T07:57:35+00:00","og_image":[{"width":191,"height":100,"url":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/09\/mensa.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Avviso pubblico utilizzo del servizio di mensa scolastica per l&#8217;anno 2025\/2026","datePublished":"2025-09-09T07:57:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/"},"wordCount":172,"publisher":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/09\/mensa.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/","url":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/","name":"Avviso pubblico utilizzo del servizio di mensa scolastica per l'anno 2025\/2026 - Caselle in Pittari","isPartOf":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/09\/mensa.jpg","datePublished":"2025-09-09T07:57:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/#primaryimage","url":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/09\/mensa.jpg","contentUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/09\/mensa.jpg","width":191,"height":100},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/09\/09\/avviso-pubblico-utilizzo-del-servizio-di-mensa-scolastica-per-lanno-2025-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/caselleinpittari\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico utilizzo del servizio di mensa scolastica per l&#8217;anno 2025\/2026"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#website","url":"https:\/\/comunicacity.net\/caselleinpittari\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/caselleinpittari\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/caselleinpittari\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001988"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/comments?post=645"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/media\/646"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/media?parent=645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/categories?post=645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/tags?post=645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}