{"id":751,"date":"2025-10-27T11:13:56","date_gmt":"2025-10-27T10:13:56","guid":{"rendered":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/"},"modified":"2025-10-27T11:13:56","modified_gmt":"2025-10-27T10:13:56","slug":"elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/","title":{"rendered":"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali."},"content":{"rendered":"<p><em>In occasione delle elezioni regionali, il Ministero dell&#8217;Interno ha comunicato che gli elettori che si recheranno a votare nel proprio comune di scrizione elettorale potranno usufruire delle agevolazioni di viaggio.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Sono previste agevolazioni tariffarie per i viaggi ferroviari, via mare, autostradali e aerei, a favore degli elettori che si recheranno a votare nel comune di iscrizione elettorale per le elezioni regionali in Campania in programma domenica 23 novembre e luned\u00ec 24 novembre 2025. Le agevolazioni tariffarie per gli elettori non sono cumulabili con altre riduzioni e\/o promozioni.<\/p>\n<p><strong>Viaggi ferroviari:<\/strong> il viaggio di andata potr\u00e0 essere effettuato dal 14 novemebre 2025 e quello di ritorno non oltre il 4 dicembre 2025. In ogni caso il viaggio di andata deve essere completato entro l&#8217;orario di chiusura delle operazioni di votazione e quello di ritorno non pu\u00f2 avere inizio se non dopo l&#8217;apertura del seggio elettorale. Gli elettori, per poter usufruire dell&#8217;agevolazione, dovranno esibire al personale addetto al controllo a bordo del treno:<br \/>\n\u2022 nel viaggio di andata la propria tessera elettorale o una dichiarazione sostitutiva attestante che il biglietto agevolato \u00e8 stato acquistato per recarsi presso la localit\u00e0 di iscrizione elettorale, al fine di esercitare il diritto di voto;<br \/>\n\u2022 nel viaggio di ritorno la propria tessera elettorale recante l&#8217;attestazione dell&#8217;avvenuta votazione;<br \/>\n\u2022 gli elettori residenti in Italia, se sprovvisti della tessera elettorale, potranno produrre una dichiarazione sostitutiva.<\/p>\n<p><strong>Viaggi autostradali:<\/strong> La validit\u00e0 dell&#8217;agevolazione avr\u00e0 inizio, per il viaggio di andata, dalle ore 22 del quinto giorno precedente quello della consultazione e, per quello di rientro, dal giorno delle operazioni di voto fino alle ore 22 del quinto giorno successivo alla conclusione delle operazioni stesse. L&#8217;elettore, per poter usufruire dell&#8217;agevolazione, dovr\u00e0 esibire, per il viaggio di andata, la tessera elettorale o la cartolina-avviso inviatagli dal comune di iscrizione elettorale o l&#8217;attestazione rilasciata dal consolato della localit\u00e0 di residenza e, per il viaggio di ritorno, la tessera elettorale opportunamente vidimata dal presidente del seggio dove \u00e8 avvenuta la votazione.<\/p>\n<p><strong>Viaggi aerei:<\/strong> La Compagnia Italia Trasporto Aereo S.p.A. (ITA Airways) con riferimento alle elezioni del Presidente della Giunta e del Consiglio regionale della Campania, applicher\u00e0 uno sconto sul biglietto aereo per un volo nazionale, andata e ritorno, utilizzato per recarsi presso la sede del seggio elettorale di appartenenza per volare da tutta Italia verso Napoli e viceversa, dal 1 6 novembre al 1 \u00b0 dicembre 2025. L&#8217;offerta \u00e8 valida fino al 24 novembre 2025. Lo sconto applicabile \u00e8 pari a 40 euro per tariffe con importo pari o superiore a 4 1 euro e applicabile a tutti i brand tariffari, non si aggiunge ad altre agevolazioni o promozioni in corso e non si applica a tasse e supplementi.<\/p>\n<p><strong>Viaggi via mare:<\/strong> Il Ministero delle Infrastrutture e della mobilit\u00e0 sostenibili ha dato disposizioni alla Compagnia Italiana di Navigazione S.p.A., alla GNV S.p.A., alla Grimaldi Euromed S.p.A., alla Societ\u00e0 Navigazione Siciliana S.c.p.A. e alla NLG &#8211; Navigazione Libera del Golfo di applicare, agli elettori che si recheranno a votare nel comune di propria iscrizione, la tariffa agevolata che prevede la riduzione del 60% del nolo passeggeri della sola &#8220;tariffa ordinaria&#8221;; nel caso di elettori che abbiano diritto alla tariffa in qualit\u00e0 di residenti, si applicher\u00e0 la &#8220;tariffa residenti&#8221;, a eccezione dei casi in cui la tariffa &#8220;elettori&#8221; risultasse pi\u00f9 vantaggiosa. In particolare tali agevolazioni di viaggio saranno previste rispettivamente nelle<br \/>\nseguenti linee marittime:<br \/>\no Compagnia Italiana di Navigazione S.p.A.: linea Genova-Porto Torres e linea Civitavecchia-Olbia;<br \/>\no GNV S.p.A: linea Civitavecchia-Olbia;<br \/>\no Grimaldi Euromed S.p.A: linea Napoli-Cagliari-Palermo, linea CivitavecchiaArbatax- Cagliari e linea Civitavecchia-Olbia;<br \/>\no Societ\u00e0 Navigazione Siciliana S.c.p.A: collegamenti tra la Sicilia e le isole minori siciliane e linea Napoli-Isole Eolie-Milazzo;<br \/>\no NLG &#8211; Navigazione Libera del Golfo S.r.l: linea Termoli-Isole Tremiti.<\/p>\n<p><strong>Per ogni ulteriore dettaglio in merito si rimanda all&#8217;allegata circolare della Prefettura di Salerno che richiama la circolare del ministero dell&#8217;intero per le agevolazioni tariffarie.<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_753\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/10\/agevolazioni-tariffarie-elezioni2025.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/10\/agevolazioni-tariffarie-elezioni2025.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>agevolazioni tariffarie elezioni2025<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione delle elezioni regionali, il Ministero dell&#8217;Interno ha comunicato che gli elettori che si recheranno a votare nel proprio comune di scrizione elettorale potranno usufruire delle agevolazioni di viaggio.&nbsp; [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali. - Caselle in Pittari<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali. - Caselle in Pittari\" \/>\n<meta property=\"og:description\" content=\"In occasione delle elezioni regionali, il Ministero dell&#8217;Interno ha comunicato che gli elettori che si recheranno a votare nel proprio comune di scrizione elettorale potranno usufruire delle agevolazioni di viaggio.&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/\" \/>\n<meta property=\"og:site_name\" content=\"Caselle in Pittari\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T10:13:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/10\/elezioni_regionali_2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"198\" \/>\n\t<meta property=\"og:image:height\" content=\"129\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali.\",\"datePublished\":\"2025-10-27T10:13:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/\"},\"wordCount\":664,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/10\\\/elezioni_regionali_2025.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/\",\"name\":\"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali. - Caselle in Pittari\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/10\\\/elezioni_regionali_2025.jpg\",\"datePublished\":\"2025-10-27T10:13:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/10\\\/elezioni_regionali_2025.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/wp-content\\\/uploads\\\/sites\\\/227\\\/2025\\\/10\\\/elezioni_regionali_2025.jpg\",\"width\":198,\"height\":129},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/2025\\\/10\\\/27\\\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/caselleinpittari\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali. - Caselle in Pittari","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/","og_locale":"it_IT","og_type":"article","og_title":"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali. - Caselle in Pittari","og_description":"In occasione delle elezioni regionali, il Ministero dell&#8217;Interno ha comunicato che gli elettori che si recheranno a votare nel proprio comune di scrizione elettorale potranno usufruire delle agevolazioni di viaggio.&nbsp; [&hellip;]","og_url":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/","og_site_name":"Caselle in Pittari","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-10-27T10:13:56+00:00","og_image":[{"width":198,"height":129,"url":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/10\/elezioni_regionali_2025.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali.","datePublished":"2025-10-27T10:13:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/"},"wordCount":664,"publisher":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/10\/elezioni_regionali_2025.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/","url":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/","name":"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali. - Caselle in Pittari","isPartOf":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/10\/elezioni_regionali_2025.jpg","datePublished":"2025-10-27T10:13:56+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/#primaryimage","url":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/10\/elezioni_regionali_2025.jpg","contentUrl":"https:\/\/comunicacity.net\/caselleinpittari\/wp-content\/uploads\/sites\/227\/2025\/10\/elezioni_regionali_2025.jpg","width":198,"height":129},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/caselleinpittari\/2025\/10\/27\/elezioni-del-consiglio-regionale-e-del-presidente-della-giunta-regionale-della-campania-del-23-e-24-novembre-2025-agevolazioni-tariffarie-per-i-viaggi-ferroviari-aerei-via-mare-e-autostradali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/caselleinpittari\/"},{"@type":"ListItem","position":2,"name":"Elezioni del Consiglio regionale e del Presidente della Giunta regionale della Campania del 23 e 24 novembre 2025. Agevolazioni tariffarie per i viaggi ferroviari, aerei, via mare e autostradali."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#website","url":"https:\/\/comunicacity.net\/caselleinpittari\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/caselleinpittari\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/caselleinpittari\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/caselleinpittari\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002039"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/comments?post=751"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/posts\/751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/media\/752"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/media?parent=751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/categories?post=751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/caselleinpittari\/wp-json\/wp\/v2\/tags?post=751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}