{"id":1197,"date":"2015-02-16T15:26:30","date_gmt":"2015-02-16T14:26:30","guid":{"rendered":"https:\/\/comunicacity.net\/cassino\/?p=1197"},"modified":"2015-02-16T15:26:30","modified_gmt":"2015-02-16T14:26:30","slug":"consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/","title":{"rendered":"Consales  &#8211; Rifiuti Zero ed impianti a biogas alla consulta dell&#8217;ambiente di mercoled\u00ec"},"content":{"rendered":"<p><strong>Osservatorio strategia Rifiuti Zero ed impianti a biogas all&#8217;ODG della consulta dell&#8217;ambiente di mercoled\u00ec<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cImpianti a Biogas e costituzione dell\u2019Osservatorio Cassino Rifiuti Zero sono i due punti all\u2019ordine del giorno che verranno discussi mercoled\u00ec.\u201d A renderlo noto l\u2019assessore all\u2019ambiente del Comune di Cassino, Riccardo Consales, in merito ai due argomenti che verranno affrontati mercoled\u00ec, a partire dalle ore 17.30, all\u2019interno della Consulta dell\u2019Ambiente convocata in Sala Restagno.<\/p>\n<p style=\"text-align: justify;\">\u201cIl Comune di Cassino \u2013 ha continuato Consales \u2013 ha ricevuto in questi mesi richieste per autorizzare la realizzazione di impianti di biogas e biomassa sul proprio territorio comunale. Autorizzazione mai rilasciata dal Comune di Cassino che pi\u00f9 volte in passato ha provveduto a diffidare la societ\u00e0 che intende realizzare gli impianti.<\/p>\n<p style=\"text-align: justify;\">Tuttavia va fatto presente che in questi casi si devono fare i conti con le normative, sia regionali che nazionali, che consentono, sussistendone tutte le condizioni, la realizzazione, anche in zona agricola, di impianti di questo tipo. Il Comune \u00e8 vincolato anch\u2019esso al rispetto delle leggi in materia, ma \u00e8 allo stesso tempo ha il compito verificare che la societ\u00e0 disponga di tutti gli elementi necessari per concretizzare il proprio progetto.<\/p>\n<p style=\"text-align: justify;\">Nella verifica di tali requisiti il Comune sar\u00e0 rigoroso come la delicata materia richiede e la Consulta dell\u2019Ambiente di mercoled\u00ec \u00e8 uno strumento validissimo per coadiuvare l\u2019Ente in questa attivit\u00e0 di controllo. L\u2019altro punto all\u2019ordine del giorno riguarda la costituzione dell\u2019osservatorio Cassino Rifiuti Zero. Ormai \u00e8 noto che il Comune di Cassino con la Strategia Rifiuti Zero si impegna a migliorare e superare le attuali percentuali di raccolta differenziata, per tutto il 2014 prossime al 70%, con l\u2019obiettivo di arrivare entro il 2020 a quota 90%.<\/p>\n<p style=\"text-align: justify;\">Per fare in modo che questo si verifichi, cos\u00ec come previsto dalla delibera, fondamentale \u00e8 il ruolo dell\u2019osservatorio \u2018Rifiuti Zero\u2019 i cui membri saranno il professor Paul Connett, massimo esperto in materia, Rossano Ercolini, premio Nobel per l\u2019ambiente 2013, Enzo Favoino e rappresentanti delle associazioni ambientaliste del territorio.<\/p>\n<p style=\"text-align: justify;\">L\u2019osservatorio avr\u00e0 compiti di programmazione e verifica dello stato di avanzamento del progetto relativo alla strategia Rifiuti Zero. Sulla base delle migliori esperienze di altri Comuni verranno adottate buone pratiche per la riduzione dei rifiuti. La Strategia Rifiuti Zero ha lo scopo di diminuire al minimo il conferimento in discarica ed all\u2019inceneritore dei rifiuti.<\/p>\n<p style=\"text-align: justify;\">Il Comune di Cassino in questi anni ha gi\u00e0 messo in pratica diverse iniziative per intraprendere il percorso verso l\u2019attuazione Rifiuti Zero attraverso l\u2019avvio della raccolta differenziata \u2018porta a porta\u2019, l\u2019adozione dei distributori di acqua e latte alla spina ed il progetto del compostaggio domestico. Quello di mercoled\u00ec \u00e8 un altro passo importantissimo per una citt\u00e0 sempre pi\u00f9 in linea con i parametri della strategia Rifiuti Zero.\u201d<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1198\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/02\/Consulta-Ambiente-18-febbraio-2015.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/02\/Consulta-Ambiente-18-febbraio-2015.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Consulta Ambiente 18 febbraio 2015<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Osservatorio strategia Rifiuti Zero ed impianti a biogas all&#8217;ODG della consulta dell&#8217;ambiente di mercoled\u00ec \u201cImpianti a Biogas e costituzione dell\u2019Osservatorio Cassino Rifiuti Zero sono i due punti all\u2019ordine del giorno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":522,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consales - Rifiuti Zero ed impianti a biogas alla consulta dell&#039;ambiente di mercoled\u00ec - Cassino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consales - Rifiuti Zero ed impianti a biogas alla consulta dell&#039;ambiente di mercoled\u00ec - Cassino\" \/>\n<meta property=\"og:description\" content=\"Osservatorio strategia Rifiuti Zero ed impianti a biogas all&#8217;ODG della consulta dell&#8217;ambiente di mercoled\u00ec \u201cImpianti a Biogas e costituzione dell\u2019Osservatorio Cassino Rifiuti Zero sono i due punti all\u2019ordine del giorno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/\" \/>\n<meta property=\"og:site_name\" content=\"Cassino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CassinoComunica\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-16T14:26:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/consales_riccardo_bnr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"531\" \/>\n\t<meta property=\"og:image:height\" content=\"354\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Consales &#8211; Rifiuti Zero ed impianti a biogas alla consulta dell&#8217;ambiente di mercoled\u00ec\",\"datePublished\":\"2015-02-16T14:26:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/\"},\"wordCount\":464,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/consales_riccardo_bnr.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/\",\"name\":\"Consales - Rifiuti Zero ed impianti a biogas alla consulta dell'ambiente di mercoled\u00ec - Cassino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/consales_riccardo_bnr.jpg\",\"datePublished\":\"2015-02-16T14:26:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/consales_riccardo_bnr.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/consales_riccardo_bnr.jpg\",\"width\":531,\"height\":354},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/02\\\/16\\\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consales &#8211; Rifiuti Zero ed impianti a biogas alla consulta dell&#8217;ambiente di mercoled\u00ec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"name\":\"Cassino\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\",\"name\":\"Comune di Cassino\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"width\":300,\"height\":300,\"caption\":\"Comune di Cassino\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CassinoComunica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consales - Rifiuti Zero ed impianti a biogas alla consulta dell'ambiente di mercoled\u00ec - Cassino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/","og_locale":"it_IT","og_type":"article","og_title":"Consales - Rifiuti Zero ed impianti a biogas alla consulta dell'ambiente di mercoled\u00ec - Cassino","og_description":"Osservatorio strategia Rifiuti Zero ed impianti a biogas all&#8217;ODG della consulta dell&#8217;ambiente di mercoled\u00ec \u201cImpianti a Biogas e costituzione dell\u2019Osservatorio Cassino Rifiuti Zero sono i due punti all\u2019ordine del giorno [&hellip;]","og_url":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/","og_site_name":"Cassino","article_publisher":"https:\/\/www.facebook.com\/CassinoComunica\/","article_published_time":"2015-02-16T14:26:30+00:00","og_image":[{"width":531,"height":354,"url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/consales_riccardo_bnr.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Consales &#8211; Rifiuti Zero ed impianti a biogas alla consulta dell&#8217;ambiente di mercoled\u00ec","datePublished":"2015-02-16T14:26:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/"},"wordCount":464,"publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/consales_riccardo_bnr.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/","url":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/","name":"Consales - Rifiuti Zero ed impianti a biogas alla consulta dell'ambiente di mercoled\u00ec - Cassino","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/consales_riccardo_bnr.jpg","datePublished":"2015-02-16T14:26:30+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/#primaryimage","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/consales_riccardo_bnr.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/consales_riccardo_bnr.jpg","width":531,"height":354},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cassino\/2015\/02\/16\/consales-rifiuti-zero-ed-impianti-a-biogas-alla-consulta-dellambiente-di-mercoledi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cassino\/"},{"@type":"ListItem","position":2,"name":"Consales &#8211; Rifiuti Zero ed impianti a biogas alla consulta dell&#8217;ambiente di mercoled\u00ec"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cassino\/#website","url":"https:\/\/comunicacity.net\/cassino\/","name":"Cassino","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cassino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/cassino\/#organization","name":"Comune di Cassino","url":"https:\/\/comunicacity.net\/cassino\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","width":300,"height":300,"caption":"Comune di Cassino"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CassinoComunica\/"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/comments?post=1197"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1197\/revisions"}],"predecessor-version":[{"id":1199,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1197\/revisions\/1199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media\/522"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media?parent=1197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/categories?post=1197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/tags?post=1197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}