{"id":1978,"date":"2015-11-18T16:29:40","date_gmt":"2015-11-18T15:29:40","guid":{"rendered":"https:\/\/comunicacity.net\/cassino\/?p=1978"},"modified":"2015-11-18T16:29:40","modified_gmt":"2015-11-18T15:29:40","slug":"housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/","title":{"rendered":"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora"},"content":{"rendered":"<p style=\"text-align: justify;\">\u201cSono le sei le famiglie che, ricevuto lo sfratto esecutivo, hanno trovato alloggio grazie al progetto Housing Punto Zero realizzato dal Comune di Cassino. <!--more-->Un progetto sperimentale che in breve tempo \u00e8 riuscito a diventare un ottimo strumento di sostegno grazie alla struttura dello stesso che parte dall\u2019accoglienza abitativa transitoria, passa per l\u2019integrazione ed il reinserimento sociale e professionale sino al supporto nella ricerca di abitazioni autonome.<\/p>\n<p style=\"text-align: justify;\">Un ringraziamento lo rivolgiamo alla professionalit\u00e0 ed alla pazienza dimostrata dal responsabile e dai dipendenti della Cooperativa Arca impegnati in questo progetto. Un progetto di certo non semplice proprio perch\u00e9 nuovo, il Comune di Cassino \u00e8 stato il primo a pensarlo ed attuarlo, che si \u00e8 incanalato nel verso giusto grazie all\u2019impegno degli uffici del secondo settore e di quanti hanno lavorato per rendere realt\u00e0 un\u2019idea innovativa. Nelle piccole cose cos\u00ec come nelle grandi, quando si crede in un progetto, in particolare se mai attuato, \u00e8 fondamentale seguire ogni minima cosa che lo riguarda soprattutto all\u2019inizio.<\/p>\n<p style=\"text-align: justify;\">Allo stesso modo di come viene seguito un neonato che ha bisogno di attenzione quotidiana affinch\u00e9 riesca ad acquisire quell\u2019autonomia che gli permetta di crescere. Il progetto di co\u2013housing \u00e8 tutto questo: un neonato che \u00e8 stato seguito meticolosamente e che adesso, dopo aver raccolto i primi frutti, \u00e8 pronto a crescere sempre di pi\u00f9 e ad essere programmato su scala pi\u00f9 ampia per il prossimo anno.<\/p>\n<p style=\"text-align: justify;\">D\u2019altronde l\u2019impegno dell\u2019Amministrazione Petrarcone nel sociale \u00e8 testimoniato dai diversi interventi realizzati, dai tanti progetti messi in campo per far fronte alla situazione di disagio che riguarda, purtroppo, un numero di persone sempre maggiore. Un cammino iniziato 4 anni or sono grazie al quale \u00e8 stata abbandonata la strada dell\u2019assistenzialismo e si \u00e8 intrapreso un percorso che mette al centro la persona nella sua interezza.<\/p>\n<p style=\"text-align: justify;\">Il Progetto Housing Punto Zero \u00e8 un ulteriore passo in tal senso grazie al meccanismo allargato su cui si basa che prevede che un cittadino in condizione di sfratto esecutivo, una volta sottoposto a dovuti controlli, possa ricevere una casa sottoscrivendo un patto di servizio ed iscrivendosi al regolamento del volontariato, fornendo, pertanto, senza alcun contributo e con la sola copertura assicurativa, un servizio di poche ore settimanali di pubblica utilit\u00e0 per la cittadinanza.<\/p>\n<p style=\"text-align: justify;\">Un processo in cui l\u2019assegnazione della casa per un periodo transitorio di sei mesi- un anno \u00e8 coadiuvata da una serie di azioni precedenti di natura socio \u2013 educativa affinch\u00e9 quella famiglia ritrovi l\u2019equilibrio relazionale ed economico su cui poter costruire un recupero sociale che le consenta in futuro di potersi procurare un\u2019abitazione con proprie forze e risorse.<\/p>\n<p style=\"text-align: justify;\">Proprio per questo spiace aver dovuto constatare il rifiuto da parte di persone che avevano i requisiti per rientrare nel co\u2013housing, ma che non hanno voluto cogliere questa opportunit\u00e0, scegliendo e sottoscrivendo la propria scelta di continuare a vivere in condizioni di forte disagio abitativo.<\/p>\n<p style=\"text-align: justify;\">Se il dover condividere degli ampi spazi con altre persone o il dover saltuariamente svolgere dei lavori socialmente utili per la comunit\u00e0 oppure accettare l\u2019aiuto e la consulenza di un educatore familiare sono i motivi che portano alcuni a rinunciare a questo progetto significa che queste persone, poche per fortuna, rimangono molto distanti dal concetto di sociale di questa Amministrazione.<\/p>\n<p style=\"text-align: justify;\">Spiace, infine, constatare che quando c\u2019\u00e8 un problema irrisolto ne parlano tutti, quando, invece, i problemi si risolvono, come nel caso in questione, nessuno ne parla o meglio tutti lo considerano dovuta normalit\u00e0. Come dice un famoso proverbio: fa pi\u00f9 rumore un albero che cade che una foresta che cresce.<\/p>\n<p style=\"text-align: justify;\">Noi di alberi, che cresceranno e diventeranno foreste, ne stiamo piantando tanti.\u00a0A tal proposito, non stiamo ancora volutamente parlando della prossima realizzazione di nuovi alloggi Ater,, i cui fondi (milioni di euro) sono stati reperiti per merito di pochi addetti ai lavori. La cosa che possiamo dire che il numero di 16 alloggi previsti \u00e8 destinato ad aumentare.\u201d \u00c8 quanto emerge in una nota a firma dell\u2019assessore alle politiche sociali del Comune di Cassino Stefania Di Russo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSono le sei le famiglie che, ricevuto lo sfratto esecutivo, hanno trovato alloggio grazie al progetto Housing Punto Zero realizzato dal Comune di Cassino.<\/p>\n","protected":false},"author":1,"featured_media":53,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-1978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora - Cassino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora - Cassino\" \/>\n<meta property=\"og:description\" content=\"\u201cSono le sei le famiglie che, ricevuto lo sfratto esecutivo, hanno trovato alloggio grazie al progetto Housing Punto Zero realizzato dal Comune di Cassino.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/\" \/>\n<meta property=\"og:site_name\" content=\"Cassino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CassinoComunica\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-18T15:29:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/10\/di_russo_3-645x431.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora\",\"datePublished\":\"2015-11-18T15:29:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/\"},\"wordCount\":670,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/10\\\/di_russo_3-645x431.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/\",\"name\":\"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora - Cassino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/10\\\/di_russo_3-645x431.jpg\",\"datePublished\":\"2015-11-18T15:29:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/10\\\/di_russo_3-645x431.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/10\\\/di_russo_3-645x431.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/11\\\/18\\\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"name\":\"Cassino\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\",\"name\":\"Comune di Cassino\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"width\":300,\"height\":300,\"caption\":\"Comune di Cassino\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CassinoComunica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora - Cassino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/","og_locale":"it_IT","og_type":"article","og_title":"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora - Cassino","og_description":"\u201cSono le sei le famiglie che, ricevuto lo sfratto esecutivo, hanno trovato alloggio grazie al progetto Housing Punto Zero realizzato dal Comune di Cassino.","og_url":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/","og_site_name":"Cassino","article_publisher":"https:\/\/www.facebook.com\/CassinoComunica\/","article_published_time":"2015-11-18T15:29:40+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/10\/di_russo_3-645x431.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora","datePublished":"2015-11-18T15:29:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/"},"wordCount":670,"publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/10\/di_russo_3-645x431.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/","url":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/","name":"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora - Cassino","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/10\/di_russo_3-645x431.jpg","datePublished":"2015-11-18T15:29:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/#primaryimage","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/10\/di_russo_3-645x431.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/10\/di_russo_3-645x431.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cassino\/2015\/11\/18\/housing-punto-zero-6-le-famiglie-che-hanno-trovato-alloggio-finora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cassino\/"},{"@type":"ListItem","position":2,"name":"Housing Punto Zero: 6 le famiglie che hanno trovato alloggio finora"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cassino\/#website","url":"https:\/\/comunicacity.net\/cassino\/","name":"Cassino","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cassino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/cassino\/#organization","name":"Comune di Cassino","url":"https:\/\/comunicacity.net\/cassino\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","width":300,"height":300,"caption":"Comune di Cassino"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CassinoComunica\/"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/comments?post=1978"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1978\/revisions"}],"predecessor-version":[{"id":1979,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1978\/revisions\/1979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media\/53"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media?parent=1978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/categories?post=1978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/tags?post=1978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}