{"id":1991,"date":"2015-12-10T18:41:05","date_gmt":"2015-12-10T17:41:05","guid":{"rendered":"https:\/\/comunicacity.net\/cassino\/?p=1991"},"modified":"2015-12-10T18:41:05","modified_gmt":"2015-12-10T17:41:05","slug":"santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/","title":{"rendered":"Santa Scolastica: dall&#8217;incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio"},"content":{"rendered":"<p style=\"text-align: justify;\">\u201cL\u2019incontro con il commissario dell\u2019Asl di Frosinone, dottor Luigi Macchitella, \u00e8 stato molto proficuo. Abbiamo avuto modo di tracciare un quadro completo sulle problematiche relative alla sanit\u00e0 pubblica nel nostro territorio, ma soprattutto abbiamo ricevuto quelle rassicurazioni che tutti attendavamo sia per quanto concerne il Santa Scolastica sia per dare un cambio di passo decisivo in ambito sanitario nella nostra provincia.\u201d<\/p>\n<p style=\"text-align: justify;\">A dichiararlo \u00e8 stato il sindaco Giuseppe Golini Petrarcone a margine dell\u2019incontro, richiesto da tutti i rappresentanti del Consiglio Comunale di Cassino, che si \u00e8 tenuto nel corso della mattina, alla presenza di tutti i consiglieri comunali, in Municipio. \u201cOggi \u2013 ha continuato il sindaco \u2013 abbiamo avuto quelle conferme su quanto gi\u00e0 detto dal commissario Macchitella nel corso del primo incontro che ho avuto con lui lo scorso mese di novembre.<\/p>\n<p style=\"text-align: justify;\">Anche in questa circostanza si \u00e8 partiti dal presupposto che l\u2019atto aziendale, che ricordiamo prevede il Dea di primo livello per il Santa Scolastica, \u00e8 un valido strumento che deve essere attuato. Il dottor Macchitella ha ribadito la volont\u00e0 di attuare quanto previsto dall\u2019atto aziendale e la riattivazione dell\u2019ambulatorio di Medicina Trasfusionale, insieme al potenziamento dell\u2019organico dei reparti di Anestesia e Pronto Soccorso del Santa Scolastica, sono un primo passo il tal senso.<\/p>\n<p style=\"text-align: justify;\">A questo \u2013 notizia che \u00e8 stata riferita nel corso dell\u2019incontro \u2013 si aggiungono gli avvisi pubblici a tempo determinato rinnovabili fino al 2018 per 18 medici (uno per cardiologia, due per anestesiologia, 5 per chirurgia di urgenza, 5 per ostetricia e ginecologia e 5 per pediatria) che la Asl di Frosinone ha gi\u00e0 bandito in questi giorni. Questo per quanto concerne le soluzioni a stretto giro di posta.<\/p>\n<p style=\"text-align: justify;\">Ma l\u2019incontro di oggi \u00e8 servito anche a fare il punto della situazione per il futuro. In tal senso il dottor Macchitella ci ha riferito che sta lavorando per portare a conclusione l\u2019iter per l\u2019assunzione a tempo indeterminato di medici ed infermieri. Nello specifico, risparmiando risorse per finanziare le Pes e le Pea (il cui costo \u00e8 di 700 euro a turno) per le quali solo nel 2014 sono stati spesi 4 milioni e 600 mila euro, \u00e8 possibile con una spesa equivalente se non addirittura inferiore \u2013 se si considera che nella provincia di Frosinone si va avanti con Pes e Pea dal 2010 \u2013 assumere altri 64 medici e 30 infermieri a tempo indeterminato.<\/p>\n<p style=\"text-align: justify;\">A questi bisogna aggiungere altri 28 medici che sar\u00e0 possibile assumere, rimanendo nei parametri previsti dal piano di riequilibrio finanziario cui \u00e8 sottoposta la Asl di Frosinone, grazie al lavoro portato avanti dal dottor Macchitella che \u00e8 riuscito a recuperare nel bilancio dell\u2019azienda un altro milione di euro. Tutti elementi decisamente rassicuranti che per il futuro, stando a quanto ci \u00e8 stato riferito, dovrebbero portare in tutta la provincia all\u2019assunzione di oltre 100 medici.<\/p>\n<p style=\"text-align: justify;\">Tornando al presente gli avvisi pubblici per i 22 medici sono un passo importante che conferma la volont\u00e0 di dare quel cambio di passo alla sanit\u00e0 nel nostro territorio, applicando un atto aziendale valido e figlio anche dell\u2019opera di mediazione effettuata dalla nostra Amministrazione. Ovviamente le rassicurazioni hanno riguardato anche l\u2019ospedale Santa Scolastica di Cassino, una struttura all\u2019avanguardia che va riempita innanzitutto con il personale medico per avere quei servizi indispensabili per un Dea di primo livello.<\/p>\n<p style=\"text-align: justify;\">Alle figure professionali che sono arrivate in questi giorni e a quelle che arriveranno a breve grazie agli avvisi pubblici se ne dovranno aggiungere altre per i reparti di Ortopedia, Cardiologia, Ginecologia e Pediatria. Anche su questo aspetto il dottor Macchitella ha confermato il suo impegno per fare in modo che questo avvenga il prima possibile.<\/p>\n<p style=\"text-align: justify;\">Dal canto nostro, nell\u2019ottica di una sanit\u00e0 efficiente per il nostro territorio che passa inevitabilmente attraverso i servizi del Santa Scolastica, abbiamo chiesto anche la riattivazione del reparto di Gastroenterologia con il ritorno delle figure professionali necessarie allo scopo, oltre che l\u2019attivazione del day hospital di oncologia.<\/p>\n<p style=\"text-align: justify;\">Un esigenza quest\u2019ultima che si \u00e8 manifestata soprattutto negli ultimi mesi e che riteniamo indispensabile onde evitare a chi purtroppo deve sottoporsi a chemioterapia lo stress di dover raggiungere Sora, unendo al sacrificio fisico anche quello economico. Infine, il dottor Macchitella, ci ha comunicato che \u00e8 sua intenzione anche indire concorsi pubblici per i primari soprattutto nelle aree chirurgiche.<\/p>\n<p style=\"text-align: justify;\">L\u2019incontro si \u00e8 concluso con la volont\u00e0 di fare comunque un Consiglio Comunale sulla sanit\u00e0 al quale far partecipare il presidente della Regione Zingaretti o un suo delegato. Un Consiglio Comunale che riguardi non solo il Santa Scolastica, ma anche le problematiche del territorio e della Medicina di base. Questo perch\u00e9, in considerazione del fatto che sono in programma a livello nazionale e quindi anche regionale tagli sulla sanit\u00e0 territoriale che si ripercuoteranno inevitabilmente sull\u2019assistenza ai cittadini , vogliamo chiarimenti e rassicurazioni in merito.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cL\u2019incontro con il commissario dell\u2019Asl di Frosinone, dottor Luigi Macchitella, \u00e8 stato molto proficuo. Abbiamo avuto modo di tracciare un quadro completo sulle problematiche relative alla sanit\u00e0 pubblica nel nostro [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sanita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santa Scolastica: dall&#039;incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio - Cassino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santa Scolastica: dall&#039;incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio - Cassino\" \/>\n<meta property=\"og:description\" content=\"\u201cL\u2019incontro con il commissario dell\u2019Asl di Frosinone, dottor Luigi Macchitella, \u00e8 stato molto proficuo. Abbiamo avuto modo di tracciare un quadro completo sulle problematiche relative alla sanit\u00e0 pubblica nel nostro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"Cassino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CassinoComunica\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-10T17:41:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/12\/Cassino-Ospedale-S-Scolastica-3570.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"585\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Santa Scolastica: dall&#8217;incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio\",\"datePublished\":\"2015-12-10T17:41:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/\"},\"wordCount\":787,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/12\\\/Cassino-Ospedale-S-Scolastica-3570.jpg\",\"articleSection\":[\"Sanit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/\",\"name\":\"Santa Scolastica: dall'incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio - Cassino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/12\\\/Cassino-Ospedale-S-Scolastica-3570.jpg\",\"datePublished\":\"2015-12-10T17:41:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/12\\\/Cassino-Ospedale-S-Scolastica-3570.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/12\\\/Cassino-Ospedale-S-Scolastica-3570.jpg\",\"width\":585,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2015\\\/12\\\/10\\\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santa Scolastica: dall&#8217;incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"name\":\"Cassino\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\",\"name\":\"Comune di Cassino\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"width\":300,\"height\":300,\"caption\":\"Comune di Cassino\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CassinoComunica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santa Scolastica: dall'incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio - Cassino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/","og_locale":"it_IT","og_type":"article","og_title":"Santa Scolastica: dall'incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio - Cassino","og_description":"\u201cL\u2019incontro con il commissario dell\u2019Asl di Frosinone, dottor Luigi Macchitella, \u00e8 stato molto proficuo. Abbiamo avuto modo di tracciare un quadro completo sulle problematiche relative alla sanit\u00e0 pubblica nel nostro [&hellip;]","og_url":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/","og_site_name":"Cassino","article_publisher":"https:\/\/www.facebook.com\/CassinoComunica\/","article_published_time":"2015-12-10T17:41:05+00:00","og_image":[{"width":585,"height":400,"url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/12\/Cassino-Ospedale-S-Scolastica-3570.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Santa Scolastica: dall&#8217;incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio","datePublished":"2015-12-10T17:41:05+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/"},"wordCount":787,"publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/12\/Cassino-Ospedale-S-Scolastica-3570.jpg","articleSection":["Sanit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/","url":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/","name":"Santa Scolastica: dall'incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio - Cassino","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/12\/Cassino-Ospedale-S-Scolastica-3570.jpg","datePublished":"2015-12-10T17:41:05+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/#primaryimage","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/12\/Cassino-Ospedale-S-Scolastica-3570.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/12\/Cassino-Ospedale-S-Scolastica-3570.jpg","width":585,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cassino\/2015\/12\/10\/santa-scolastica-dallincontro-con-il-commissario-macchitella-rassicurazioni-importanti-per-la-sanita-del-nostro-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cassino\/"},{"@type":"ListItem","position":2,"name":"Santa Scolastica: dall&#8217;incontro con il commissario Macchitella rassicurazioni importanti per la sanit\u00e0 del nostro territorio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cassino\/#website","url":"https:\/\/comunicacity.net\/cassino\/","name":"Cassino","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cassino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/cassino\/#organization","name":"Comune di Cassino","url":"https:\/\/comunicacity.net\/cassino\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","width":300,"height":300,"caption":"Comune di Cassino"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CassinoComunica\/"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/comments?post=1991"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1991\/revisions"}],"predecessor-version":[{"id":1993,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/1991\/revisions\/1993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media\/1992"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media?parent=1991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/categories?post=1991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/tags?post=1991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}