{"id":2048,"date":"2016-01-12T15:22:07","date_gmt":"2016-01-12T14:22:07","guid":{"rendered":"https:\/\/comunicacity.net\/cassino\/?p=2048"},"modified":"2016-01-12T16:23:49","modified_gmt":"2016-01-12T15:23:49","slug":"ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/","title":{"rendered":"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco"},"content":{"rendered":"<p style=\"text-align: left;\">\u201cDopo aver installato l\u2019attraversamento pedonale al Colosseo ed in corrispondenza dell\u2019ingresso del cimitero di San Bartolomeo e aver realizzato <strong>dissuasori rialzati in gomma<\/strong> a Caira, prima della rotatoria di accesso all&#8217;ospedale su via San Pasquale e su via Di Biasio, in questi giorni analoghi interventi stanno interessando tratti stradali in prossimit\u00e0 di alcuni edifici scolastici della citt\u00e0.<\/p>\n<p style=\"text-align: left;\">Pi\u00f9 precisamente nella giornata di ieri si \u00e8 provveduto all\u2019installazione di un dosso in corrispondenza della <strong>scuola di via Arigni<\/strong>, mentre oggi gli operai del servizio manutenzione stanno provvedendo alla realizzazione di altri <strong>due dissuasori al Colosseo<\/strong>.<\/p>\n<p style=\"text-align: left;\">Pi\u00f9 precisamente a piazza Piave dove \u00e8 gi\u00e0 stato installato e su via Mondello, strada di accesso alla citata piazza dove si trova la scuola Don Bosco. \u00a0Interventi necessari soprattutto in luoghi, via Arigni e piazza Piave appunto, in cui ogni mattina transitato centinaia di bambini per recarsi a scuola accompagnati dai genitori.<\/p>\n<p style=\"text-align: left;\">I dissuasori di velocit\u00e0 svolgono un ruolo importante in tal senso, perch\u00e9 rappresentano un <strong>deterrente alla velocit\u00e0<\/strong> e garantiscono ai pedoni una <span style=\"text-decoration: underline;\"><strong>maggiore sicurezza<\/strong><\/span>. La messa in sicurezza delle strade, oltre che dalla cura e dal rifacimento del manto stradale che si sta facendo in diverse zone della citt\u00e0, viene assicurata anche con questo tipo di provvedimenti.<\/p>\n<p style=\"text-align: left;\">La sicurezza stradale \u00e8 una priorit\u00e0 e compito dell\u2019Amministrazione \u00e8 quello di vigilare e porre in atto tutti quei provvedimenti tesi a disciplinare la viabilit\u00e0 sulle strade comunali al fine di <strong>garantire la sicurezza sia ai pedoni che agli automobilisti<\/strong>.<\/p>\n<p style=\"text-align: left;\">A tal proposito, infatti, sempre sulle strade oggetto di interventi in questi giorni si sta provvedendo alla realizzazione di nuova segnaletica sia orizzontale che verticale oltre che all&#8217;installazione sul manto stradale di apposite bande rumorose. I dissuasori sono un provvedimento molto apprezzato dai cittadini tanto \u00e8 vero che ci sono giunte altre richieste per realizzare analoghi interventi anche su altre strade cittadine.<\/p>\n<p style=\"text-align: left;\">Su tutte il ponte di San Pasquale sul quale nei prossimi giorni si interverr\u00e0 per realizzare un dissuasore sempre con l\u2019obiettivo di garantire la necessaria sicurezza anche ad altre zone della citt\u00e0.\u201d\u00a0\u00c8 quanto emerge in una nota a firma dell\u2019assessore alla manutenzione Gino Ranaldi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cDopo aver installato l\u2019attraversamento pedonale al Colosseo ed in corrispondenza dell\u2019ingresso del cimitero di San Bartolomeo e aver realizzato dissuasori rialzati in gomma a Caira, prima della rotatoria di accesso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-2048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mobilita"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco - Cassino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco - Cassino\" \/>\n<meta property=\"og:description\" content=\"\u201cDopo aver installato l\u2019attraversamento pedonale al Colosseo ed in corrispondenza dell\u2019ingresso del cimitero di San Bartolomeo e aver realizzato dissuasori rialzati in gomma a Caira, prima della rotatoria di accesso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/\" \/>\n<meta property=\"og:site_name\" content=\"Cassino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CassinoComunica\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-12T14:22:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-12T15:23:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/01\/dosso2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"389\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco\",\"datePublished\":\"2016-01-12T14:22:07+00:00\",\"dateModified\":\"2016-01-12T15:23:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/\"},\"wordCount\":365,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/01\\\/dosso2.jpg\",\"articleSection\":[\"Mobilit\u00e0\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/\",\"name\":\"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco - Cassino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/01\\\/dosso2.jpg\",\"datePublished\":\"2016-01-12T14:22:07+00:00\",\"dateModified\":\"2016-01-12T15:23:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/01\\\/dosso2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/01\\\/dosso2.jpg\",\"width\":600,\"height\":389},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/01\\\/12\\\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"name\":\"Cassino\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\",\"name\":\"Comune di Cassino\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"width\":300,\"height\":300,\"caption\":\"Comune di Cassino\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CassinoComunica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco - Cassino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/","og_locale":"it_IT","og_type":"article","og_title":"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco - Cassino","og_description":"\u201cDopo aver installato l\u2019attraversamento pedonale al Colosseo ed in corrispondenza dell\u2019ingresso del cimitero di San Bartolomeo e aver realizzato dissuasori rialzati in gomma a Caira, prima della rotatoria di accesso [&hellip;]","og_url":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/","og_site_name":"Cassino","article_publisher":"https:\/\/www.facebook.com\/CassinoComunica\/","article_published_time":"2016-01-12T14:22:07+00:00","article_modified_time":"2016-01-12T15:23:49+00:00","og_image":[{"width":600,"height":389,"url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/01\/dosso2.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco","datePublished":"2016-01-12T14:22:07+00:00","dateModified":"2016-01-12T15:23:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/"},"wordCount":365,"publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/01\/dosso2.jpg","articleSection":["Mobilit\u00e0"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/","url":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/","name":"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco - Cassino","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/01\/dosso2.jpg","datePublished":"2016-01-12T14:22:07+00:00","dateModified":"2016-01-12T15:23:49+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/#primaryimage","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/01\/dosso2.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/01\/dosso2.jpg","width":600,"height":389},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cassino\/2016\/01\/12\/ranaldi-dissuasori-di-velocita-in-prossimita-della-scuola-di-via-arigni-e-della-don-bosco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cassino\/"},{"@type":"ListItem","position":2,"name":"Dissuasori di velocit\u00e0 nei pressi della scuola di via Arigni e della Don Bosco"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cassino\/#website","url":"https:\/\/comunicacity.net\/cassino\/","name":"Cassino","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cassino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/cassino\/#organization","name":"Comune di Cassino","url":"https:\/\/comunicacity.net\/cassino\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","width":300,"height":300,"caption":"Comune di Cassino"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CassinoComunica\/"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/2048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/comments?post=2048"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/2048\/revisions"}],"predecessor-version":[{"id":2054,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/2048\/revisions\/2054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media\/2049"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media?parent=2048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/categories?post=2048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/tags?post=2048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}