{"id":2737,"date":"2016-11-11T16:00:42","date_gmt":"2016-11-11T15:00:42","guid":{"rendered":"https:\/\/comunicacity.net\/cassino\/?p=2737"},"modified":"2016-11-11T13:43:22","modified_gmt":"2016-11-11T12:43:22","slug":"il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/","title":{"rendered":"Il maestro Rotelli in mostra al Chiostro di Montecassino"},"content":{"rendered":"<p>Sar\u00e0 inaugurata domani, 12 Novembre, presso il Chiostro dell&#8217;Abbazia di Montecassino, alle ore 15,00 la Mostra &#8220;L&#8217;et\u00e0 dell&#8217;oro&#8221;, tele ed acciai del Maestro Marco Nereo Rotelli alla presenza dell&#8217;Abate Dom Donato Ogliari, del Sindaco di Cassino, Carlo Maria D&#8217;Alessandro, dell\u2019assessore alla Cultura, Nora Noury, del consigliere regionale Mario Abbruzzese, del Presidente di Confimpresa Italia, Guido D&#8217;Amico e di altre autorit\u00e0 civili e militari.<\/p>\n<p>L&#8217;opera di Rotelli rappresenta un modello visivo dedicato alle antiche conoscenze, una tela mnemonica, come l&#8217;ha definita il direttore dell&#8217;international traditional knowledge institute USA, Giuseppe Biagini. Si tratta in sostanza di usuali teloni mimetici sui quali Rotelli definisce un ordine formale e riporta simbologie degli indiani, con la sua cifra stilistica ed il suo sentimento poetico .Il Maestro Rotelli sar\u00e0 presto in Cina allo Shin Kong Place Department di Chongqing, una citt\u00e0 di 20 milioni di abitanti per un intervento sulla luce.<\/p>\n<p>\u201cSono eventi come questo che danno lustro alla nostra citt\u00e0. &#8211; ha detto il sindaco D\u2019Alessandro &#8211; La cultura, l\u2019arte la storia rappresentano un valore inestimabile e una chiave di volta per i processi di sviluppo della citt\u00e0 di Cassino e del suo comprensorio\u201d.<\/p>\n<p>\u201cL&#8217;evento, fortemente voluto da Antonio Evangelista, presidente dell&#8217;associazione culturale Ars Interamna e dal curatore d&#8217;arte Cristiano Tomassi, &#8211; ha detto l\u2019Assessore alla Cultura Nora Noury &#8211; rappresenta un grandissimo momento culturale per la citt\u00e0 di Cassino. Ricordiamo che Rotelli \u00e8 reduce da importanti eventi internazionali, di cui gli ultimi a Roma presso la Galleria di Arte Moderna ed a Tucson in Arizona, negli Stati Uniti\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 inaugurata domani, 12 Novembre, presso il Chiostro dell&#8217;Abbazia di Montecassino, alle ore 15,00 la Mostra &#8220;L&#8217;et\u00e0 dell&#8217;oro&#8221;, tele ed acciai del Maestro Marco Nereo Rotelli alla presenza dell&#8217;Abate Dom [&hellip;]<\/p>\n","protected":false},"author":127,"featured_media":2738,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il maestro Rotelli in mostra al Chiostro di Montecassino - Cassino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il maestro Rotelli in mostra al Chiostro di Montecassino - Cassino\" \/>\n<meta property=\"og:description\" content=\"Sar\u00e0 inaugurata domani, 12 Novembre, presso il Chiostro dell&#8217;Abbazia di Montecassino, alle ore 15,00 la Mostra &#8220;L&#8217;et\u00e0 dell&#8217;oro&#8221;, tele ed acciai del Maestro Marco Nereo Rotelli alla presenza dell&#8217;Abate Dom [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/\" \/>\n<meta property=\"og:site_name\" content=\"Cassino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CassinoComunica\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-11T15:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/11\/marco-nereo-rotelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Aletto\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Aletto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/\"},\"author\":{\"name\":\"Christian Aletto\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/4988faf41d1bdf107544edd6b9ccd196\"},\"headline\":\"Il maestro Rotelli in mostra al Chiostro di Montecassino\",\"datePublished\":\"2016-11-11T15:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/\"},\"wordCount\":263,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/11\\\/marco-nereo-rotelli.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/\",\"name\":\"Il maestro Rotelli in mostra al Chiostro di Montecassino - Cassino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/11\\\/marco-nereo-rotelli.jpg\",\"datePublished\":\"2016-11-11T15:00:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/11\\\/marco-nereo-rotelli.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2016\\\/11\\\/marco-nereo-rotelli.jpg\",\"width\":600,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2016\\\/11\\\/11\\\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il maestro Rotelli in mostra al Chiostro di Montecassino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"name\":\"Cassino\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\",\"name\":\"Comune di Cassino\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"width\":300,\"height\":300,\"caption\":\"Comune di Cassino\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CassinoComunica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/4988faf41d1bdf107544edd6b9ccd196\",\"name\":\"Christian Aletto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a097988ed7a3293342b3b792ea72459f204c66ab4ceed14c0232a95962ca48d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a097988ed7a3293342b3b792ea72459f204c66ab4ceed14c0232a95962ca48d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a097988ed7a3293342b3b792ea72459f204c66ab4ceed14c0232a95962ca48d?s=96&d=mm&r=g\",\"caption\":\"Christian Aletto\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il maestro Rotelli in mostra al Chiostro di Montecassino - Cassino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/","og_locale":"it_IT","og_type":"article","og_title":"Il maestro Rotelli in mostra al Chiostro di Montecassino - Cassino","og_description":"Sar\u00e0 inaugurata domani, 12 Novembre, presso il Chiostro dell&#8217;Abbazia di Montecassino, alle ore 15,00 la Mostra &#8220;L&#8217;et\u00e0 dell&#8217;oro&#8221;, tele ed acciai del Maestro Marco Nereo Rotelli alla presenza dell&#8217;Abate Dom [&hellip;]","og_url":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/","og_site_name":"Cassino","article_publisher":"https:\/\/www.facebook.com\/CassinoComunica\/","article_published_time":"2016-11-11T15:00:42+00:00","og_image":[{"width":600,"height":300,"url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/11\/marco-nereo-rotelli.jpg","type":"image\/jpeg"}],"author":"Christian Aletto","twitter_misc":{"Scritto da":"Christian Aletto","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/"},"author":{"name":"Christian Aletto","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/4988faf41d1bdf107544edd6b9ccd196"},"headline":"Il maestro Rotelli in mostra al Chiostro di Montecassino","datePublished":"2016-11-11T15:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/"},"wordCount":263,"publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/11\/marco-nereo-rotelli.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/","url":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/","name":"Il maestro Rotelli in mostra al Chiostro di Montecassino - Cassino","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/11\/marco-nereo-rotelli.jpg","datePublished":"2016-11-11T15:00:42+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/#primaryimage","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/11\/marco-nereo-rotelli.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2016\/11\/marco-nereo-rotelli.jpg","width":600,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cassino\/2016\/11\/11\/il-maestro-rotelli-in-mostra-al-chiostro-di-montecassino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cassino\/"},{"@type":"ListItem","position":2,"name":"Il maestro Rotelli in mostra al Chiostro di Montecassino"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cassino\/#website","url":"https:\/\/comunicacity.net\/cassino\/","name":"Cassino","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cassino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/cassino\/#organization","name":"Comune di Cassino","url":"https:\/\/comunicacity.net\/cassino\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","width":300,"height":300,"caption":"Comune di Cassino"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CassinoComunica\/"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/4988faf41d1bdf107544edd6b9ccd196","name":"Christian Aletto","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2a097988ed7a3293342b3b792ea72459f204c66ab4ceed14c0232a95962ca48d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a097988ed7a3293342b3b792ea72459f204c66ab4ceed14c0232a95962ca48d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a097988ed7a3293342b3b792ea72459f204c66ab4ceed14c0232a95962ca48d?s=96&d=mm&r=g","caption":"Christian Aletto"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/2737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/comments?post=2737"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/2737\/revisions"}],"predecessor-version":[{"id":2739,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/2737\/revisions\/2739"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media\/2738"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media?parent=2737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/categories?post=2737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/tags?post=2737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}