{"id":3562,"date":"2020-06-04T16:30:04","date_gmt":"2020-06-04T14:30:04","guid":{"rendered":"https:\/\/comunicacity.net\/cassino\/?p=3562"},"modified":"2020-06-04T16:30:04","modified_gmt":"2020-06-04T14:30:04","slug":"applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/","title":{"rendered":"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi"},"content":{"rendered":"<p>Si comunica che \u00e8 affissa all&#8217;Albo Pretorio del Comune di Cassino l\u2019ordinanza n.66, del 29 maggio scorso, a firma del sindaco Enzo Salera, avente ad oggetto l\u2019applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per gli incendi.<\/p>\n<p>Constatato che, in particolare nella stagione estiva il fenomeno degli incendi boschivi provocano gravi ed ingenti danni al patrimonio forestale, al paesaggio, alla fauna e all&#8217;assetto idrogeologico del territorio comunale, oltre a rappresentare un pericolo per l\u2019incolumit\u00e0 sia pubblica che privata, il Sindaco, nella sua qualit\u00e0 di ufficiale del Governo, al fine di prevenire ed eliminare gravi pericoli per l\u2019incolumit\u00e0 pubblica e la sicurezza urbana, nelle aree a rischio di incendio di vegetazione o di incendio boschivo, e nelle aree ad esse adiacenti,<\/p>\n<p style=\"text-align: center\">ordina<\/p>\n<p>di non accendere fuochi di ogni genere; di non far brillare mine o esplosivi; di non usare apparecchi a fiamma od elettrici per tagliare metalli; di non usare motori, fornelli o inceneritori che producano faville o brace; di non fumare, gettare fiammiferi, sigari o sigarette accese o compiere ogni altra operazione che possa creare comunque pericolo immediato o mediato di incendio; di non esercitare attivit\u00e0 pirotecnica, accendere fuochi d\u2019artificio, lanciare razzi di qualsiasi tipo e\/o mongolfiere di carta meglio note come lanterne volanti dotate di fiamme libere, nonch\u00e9 altri articoli pirotecnici; di non transitare o sostare con autoveicoli su viabilit\u00e0 non asfaltata all&#8217;interno di aree boscate, fatta eccezione per i mezzi di servizio e per le attivit\u00e0 agro &#8211; silvo pastorali nel rispetto delle norme e dei regolamenti vigenti.<\/p>\n<p>Per quanto riguarda i proprietari, gli affittuari e i conduttori dei campi a coltura cerealicola e foraggera, a conclusione delle operazioni di mietitrebbiatura o sfalcio, si fa loro obbligo di realizzare, perimetralmente e all&#8217;interno della superficie coltivata, una precisa fascia protettiva sgombra da ogni residuo di vegetazione, per una larghezza continua di almeno 10 metri. Che si riducono a 5 metri per i proprietari o conduttori di terreni situati nelle aree urbane periferiche.<\/p>\n<p>Si fa inoltre obbligo di pulizia e manutenzione dei terreni incolti o a riposo. Prescrizioni riguardano anche le attivit\u00e0 turistiche e ricettive, le aziende di stoccaggio e trattamento dei rifiuti nonch\u00e9 gli Enti di gestione di infrastrutture e servizi, quali le Ferrovie, l\u2019Anas, la Societ\u00e0 Autostrade, la Provincia, il Consorzio di Bonifica.<\/p>\n<p>L\u2019ordinanza \u00e8 esecutiva dal 29 maggio scorso ed \u00e8 in pubblicazione oltre che Albo Pretorio anche sul sito internet istituzionale del Comune.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\">Comune di Cassino<\/p>\n<p style=\"text-align: center\">\u00a0 Ufficio Stampa<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_3564\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2020\/06\/Ordinanza-n.-66-del-29.05.2020-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2020\/06\/Ordinanza-n.-66-del-29.05.2020-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Ordinanza n. 66 del 29.05.2020<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che \u00e8 affissa all&#8217;Albo Pretorio del Comune di Cassino l\u2019ordinanza n.66, del 29 maggio scorso, a firma del sindaco Enzo Salera, avente ad oggetto l\u2019applicazione delle misure di [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":1622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-3562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi - Cassino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi - Cassino\" \/>\n<meta property=\"og:description\" content=\"Si comunica che \u00e8 affissa all&#8217;Albo Pretorio del Comune di Cassino l\u2019ordinanza n.66, del 29 maggio scorso, a firma del sindaco Enzo Salera, avente ad oggetto l\u2019applicazione delle misure di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/\" \/>\n<meta property=\"og:site_name\" content=\"Cassino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CassinoComunica\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-04T14:30:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/06\/incendio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"341\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"riccardoconsales\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"riccardoconsales\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/\"},\"author\":{\"name\":\"riccardoconsales\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/15e3d680eeddd4e276fba96fb95e5736\"},\"headline\":\"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi\",\"datePublished\":\"2020-06-04T14:30:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/\"},\"wordCount\":429,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/incendio.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/\",\"name\":\"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi - Cassino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/incendio.jpg\",\"datePublished\":\"2020-06-04T14:30:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/incendio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2015\\\/06\\\/incendio.jpg\",\"width\":600,\"height\":341},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/06\\\/04\\\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"name\":\"Cassino\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\",\"name\":\"Comune di Cassino\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"width\":300,\"height\":300,\"caption\":\"Comune di Cassino\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CassinoComunica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/15e3d680eeddd4e276fba96fb95e5736\",\"name\":\"riccardoconsales\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87e40b01cc5832f80851f831ee79ac56a9af76e2a4b74582080b560254f3c620?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87e40b01cc5832f80851f831ee79ac56a9af76e2a4b74582080b560254f3c620?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87e40b01cc5832f80851f831ee79ac56a9af76e2a4b74582080b560254f3c620?s=96&d=mm&r=g\",\"caption\":\"riccardoconsales\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi - Cassino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/","og_locale":"it_IT","og_type":"article","og_title":"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi - Cassino","og_description":"Si comunica che \u00e8 affissa all&#8217;Albo Pretorio del Comune di Cassino l\u2019ordinanza n.66, del 29 maggio scorso, a firma del sindaco Enzo Salera, avente ad oggetto l\u2019applicazione delle misure di [&hellip;]","og_url":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/","og_site_name":"Cassino","article_publisher":"https:\/\/www.facebook.com\/CassinoComunica\/","article_published_time":"2020-06-04T14:30:04+00:00","og_image":[{"width":600,"height":341,"url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/06\/incendio.jpg","type":"image\/jpeg"}],"author":"riccardoconsales","twitter_misc":{"Scritto da":"riccardoconsales","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/"},"author":{"name":"riccardoconsales","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/15e3d680eeddd4e276fba96fb95e5736"},"headline":"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi","datePublished":"2020-06-04T14:30:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/"},"wordCount":429,"publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/06\/incendio.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/","url":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/","name":"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi - Cassino","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/06\/incendio.jpg","datePublished":"2020-06-04T14:30:04+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/#primaryimage","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/06\/incendio.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2015\/06\/incendio.jpg","width":600,"height":341},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cassino\/2020\/06\/04\/applicazione-delle-misure-di-prevenzione-rischio-incendi-boschivi-in-vista-del-periodo-di-massima-pericolosita-per-incendi-boschivi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cassino\/"},{"@type":"ListItem","position":2,"name":"Applicazione delle misure di prevenzione rischio incendi boschivi in vista del periodo di massima pericolosit\u00e0 per incendi boschivi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cassino\/#website","url":"https:\/\/comunicacity.net\/cassino\/","name":"Cassino","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cassino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/cassino\/#organization","name":"Comune di Cassino","url":"https:\/\/comunicacity.net\/cassino\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","width":300,"height":300,"caption":"Comune di Cassino"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CassinoComunica\/"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/15e3d680eeddd4e276fba96fb95e5736","name":"riccardoconsales","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/87e40b01cc5832f80851f831ee79ac56a9af76e2a4b74582080b560254f3c620?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/87e40b01cc5832f80851f831ee79ac56a9af76e2a4b74582080b560254f3c620?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87e40b01cc5832f80851f831ee79ac56a9af76e2a4b74582080b560254f3c620?s=96&d=mm&r=g","caption":"riccardoconsales"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/3562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/comments?post=3562"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/3562\/revisions"}],"predecessor-version":[{"id":3565,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/3562\/revisions\/3565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media\/1622"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media?parent=3562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/categories?post=3562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/tags?post=3562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}