{"id":3590,"date":"2020-07-10T11:16:21","date_gmt":"2020-07-10T09:16:21","guid":{"rendered":"https:\/\/comunicacity.net\/cassino\/?p=3590"},"modified":"2020-07-10T11:17:39","modified_gmt":"2020-07-10T09:17:39","slug":"da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/","title":{"rendered":"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare."},"content":{"rendered":"<p>Da luned\u00ec prossimo, 13 luglio, in tutto il territorio del nostro Comune partiranno la derattizzazione e la disinfestazione contro le zanzare. L\u2019intervento, affidato alla Cesan (Compagnia Europea Sanificazione), societ\u00e0 specializzata che opera a livello nazionale con sede generale a Cassino, proseguir\u00e0 poi nei giorni a seguire, sempre in orario diurno.<\/p>\n<p>Nella lotta sia ai roditori che alle zanzare la societ\u00e0 adotta una nuova tecnologia agendo direttamente nelle griglie e nelle caditoie, ove, con una attrezzatura specifica, un granulatore, viene immesso un prodotto a \u201cgranuli\u201d che ha un rilascio lento del principio attivo ed \u00e8 anche un regolatore di crescita che inibisce lo sviluppo delle larve.<\/p>\n<p>Il servizio di derattizzazione, invece, verr\u00e0 effettuato inserendo esche rodenticida che una volta ingerite, vanno ad interferire con la vitamina K, distruggendola. Si riduce cos\u00ec la coagulazione nel sistema circolatorio dei topi e dei ratti, provocandone la morte.<\/p>\n<p>L\u2019intervento partir\u00e0 dal centro urbano per arrivare man mano nelle zone periferiche che saranno raggiunte dagli operatori con l\u2019utilizzo di bici elettriche.<\/p>\n<p>In una seconda fase sono previsti interventi mirati, in particolare in alcuni quartieri, utilizzando contro le zanzare la classica \u201cspruzzata\u201d sparata sul terreno con il cannone.<\/p>\n<p>Un opuscolo illustrativo della Cesan contiene alcuni consigli utili a limitare la diffusione delle zanzare, cominciando dall\u2019eliminazione di piccoli ristagni d\u2019acqua, focolai della riproduzione, dai giardini, dai terrazzi e dai balconi. Vengono elencati poi i maggiori focolai di riproduzione di questo fastidiosissimo insetto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da luned\u00ec prossimo, 13 luglio, in tutto il territorio del nostro Comune partiranno la derattizzazione e la disinfestazione contro le zanzare. L\u2019intervento, affidato alla Cesan (Compagnia Europea Sanificazione), societ\u00e0 specializzata [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3592,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-3590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare. - Cassino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare. - Cassino\" \/>\n<meta property=\"og:description\" content=\"Da luned\u00ec prossimo, 13 luglio, in tutto il territorio del nostro Comune partiranno la derattizzazione e la disinfestazione contro le zanzare. L\u2019intervento, affidato alla Cesan (Compagnia Europea Sanificazione), societ\u00e0 specializzata [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/\" \/>\n<meta property=\"og:site_name\" content=\"Cassino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CassinoComunica\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T09:16:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-10T09:17:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2020\/07\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"751\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare.\",\"datePublished\":\"2020-07-10T09:16:21+00:00\",\"dateModified\":\"2020-07-10T09:17:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/\"},\"wordCount\":249,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg\",\"articleSection\":[\"Ambiente\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/\",\"name\":\"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare. - Cassino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg\",\"datePublished\":\"2020-07-10T09:16:21+00:00\",\"dateModified\":\"2020-07-10T09:17:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg\",\"width\":1000,\"height\":751},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/2020\\\/07\\\/10\\\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"name\":\"Cassino\",\"description\":\"Il Tuo Comune che Comunica\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#organization\",\"name\":\"Comune di Cassino\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/cassino\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2014\\\/11\\\/cassino.jpg\",\"width\":300,\"height\":300,\"caption\":\"Comune di Cassino\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CassinoComunica\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cassino\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare. - Cassino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/","og_locale":"it_IT","og_type":"article","og_title":"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare. - Cassino","og_description":"Da luned\u00ec prossimo, 13 luglio, in tutto il territorio del nostro Comune partiranno la derattizzazione e la disinfestazione contro le zanzare. L\u2019intervento, affidato alla Cesan (Compagnia Europea Sanificazione), societ\u00e0 specializzata [&hellip;]","og_url":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/","og_site_name":"Cassino","article_publisher":"https:\/\/www.facebook.com\/CassinoComunica\/","article_published_time":"2020-07-10T09:16:21+00:00","article_modified_time":"2020-07-10T09:17:39+00:00","og_image":[{"width":1000,"height":751,"url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2020\/07\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare.","datePublished":"2020-07-10T09:16:21+00:00","dateModified":"2020-07-10T09:17:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/"},"wordCount":249,"publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2020\/07\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg","articleSection":["Ambiente"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/","url":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/","name":"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare. - Cassino","isPartOf":{"@id":"https:\/\/comunicacity.net\/cassino\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2020\/07\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg","datePublished":"2020-07-10T09:16:21+00:00","dateModified":"2020-07-10T09:17:39+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/#primaryimage","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2020\/07\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2020\/07\/Da-luned\u00ec-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione.jpg","width":1000,"height":751},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cassino\/2020\/07\/10\/da-lunedi-13-luglio-partiranno-la-derattizzazione-e-la-disinfestazione-contro-le-zanzare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cassino\/"},{"@type":"ListItem","position":2,"name":"Da luned\u00ec 13 luglio partiranno la derattizzazione e la disinfestazione contro le zanzare."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cassino\/#website","url":"https:\/\/comunicacity.net\/cassino\/","name":"Cassino","description":"Il Tuo Comune che Comunica","publisher":{"@id":"https:\/\/comunicacity.net\/cassino\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cassino\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/cassino\/#organization","name":"Comune di Cassino","url":"https:\/\/comunicacity.net\/cassino\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","contentUrl":"https:\/\/comunicacity.net\/cassino\/wp-content\/uploads\/sites\/2\/2014\/11\/cassino.jpg","width":300,"height":300,"caption":"Comune di Cassino"},"image":{"@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CassinoComunica\/"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cassino\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/3590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/comments?post=3590"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/3590\/revisions"}],"predecessor-version":[{"id":3593,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/posts\/3590\/revisions\/3593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media\/3592"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/media?parent=3590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/categories?post=3590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cassino\/wp-json\/wp\/v2\/tags?post=3590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}