{"id":1018,"date":"2018-10-01T09:32:44","date_gmt":"2018-10-01T07:32:44","guid":{"rendered":"https:\/\/comunicacity.net\/castelforte\/?p=1018"},"modified":"2018-10-01T09:32:44","modified_gmt":"2018-10-01T07:32:44","slug":"interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/","title":{"rendered":"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30"},"content":{"rendered":"<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Si informa l&#8217;utenza che, nell\u2019ambito dei lavori di risanamento delle reti idriche del sud pontino, \u00e8 necessario operare un\u2019Interruzione Idrica nei Comuni di Santi Cosma e Damiano e Castelforte.<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Al fine di eseguire la connessione tra la nuova rete di distribuzione idrica eseguita per Via Garibaldi (zona alta) e la rete di distribuzione in esercizio sulla zona bassa, l\u2019interruzione, per entrambi i Comuni, avverr\u00e0 gioved\u00ec 4\/10\/2018 dalle ore 10:30 alle ore 16:30.<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>L\u2019intervento consentir\u00e0 di proseguire con la sostituzione della rete idrica nella zona bassa di Via\u00a0<\/span>Garibaldi.<\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Le zone interessate sono, per il Comune di Santi Cosma e Damiano:<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Via Garibaldi<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Via delle Terme<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Via Randaccio (limitatamente ai tratti antistanti la Piazza San Lorenzo)<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Per il Comune di Castelforte:<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Via Garibaldi (tra Via Castelluccio e Via Tore Castelluccio)<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Sar\u00e0 cura di Acqualatina fornire tempestive informazioni in caso di imprevisti.<\/span><\/div>\n<\/div>\n<div class=\"\">\n<div class=\"_1mf _1mj\"><span>Unit\u00e0 Pronto Intervento Acqualatina S.p.A<\/span><\/div>\n<div class=\"_1mf _1mj\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-34\" src=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/07\/LOGO_ACQUALATINA.jpg\" alt=\"\" width=\"425\" height=\"283\" srcset=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/07\/LOGO_ACQUALATINA.jpg 425w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/07\/LOGO_ACQUALATINA-300x200.jpg 300w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si informa l&#8217;utenza che, nell\u2019ambito dei lavori di risanamento delle reti idriche del sud pontino, \u00e8 necessario operare un\u2019Interruzione Idrica nei Comuni di Santi Cosma e Damiano e Castelforte. Al [&hellip;]<\/p>\n","protected":false},"author":239,"featured_media":264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-1018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30 - Castelforte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30 - Castelforte\" \/>\n<meta property=\"og:description\" content=\"Si informa l&#8217;utenza che, nell\u2019ambito dei lavori di risanamento delle reti idriche del sud pontino, \u00e8 necessario operare un\u2019Interruzione Idrica nei Comuni di Santi Cosma e Damiano e Castelforte. Al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/\" \/>\n<meta property=\"og:site_name\" content=\"Castelforte\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-01T07:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/09\/Pannello-Informativo-Castelforte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castelforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"castelforte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/\"},\"author\":{\"name\":\"castelforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\"},\"headline\":\"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30\",\"datePublished\":\"2018-10-01T07:32:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/\"},\"wordCount\":153,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2017\\\/09\\\/Pannello-Informativo-Castelforte.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/\",\"name\":\"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30 - Castelforte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2017\\\/09\\\/Pannello-Informativo-Castelforte.jpg\",\"datePublished\":\"2018-10-01T07:32:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2017\\\/09\\\/Pannello-Informativo-Castelforte.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2017\\\/09\\\/Pannello-Informativo-Castelforte.jpg\",\"width\":240,\"height\":120},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2018\\\/10\\\/01\\\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/\",\"name\":\"Castelforte\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\",\"name\":\"castelforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"caption\":\"castelforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/author\\\/castelforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30 - Castelforte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/","og_locale":"it_IT","og_type":"article","og_title":"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30 - Castelforte","og_description":"Si informa l&#8217;utenza che, nell\u2019ambito dei lavori di risanamento delle reti idriche del sud pontino, \u00e8 necessario operare un\u2019Interruzione Idrica nei Comuni di Santi Cosma e Damiano e Castelforte. Al [&hellip;]","og_url":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/","og_site_name":"Castelforte","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-10-01T07:32:44+00:00","og_image":[{"width":240,"height":120,"url":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/09\/Pannello-Informativo-Castelforte.jpg","type":"image\/jpeg"}],"author":"castelforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"castelforte","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/"},"author":{"name":"castelforte","@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71"},"headline":"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30","datePublished":"2018-10-01T07:32:44+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/"},"wordCount":153,"image":{"@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/09\/Pannello-Informativo-Castelforte.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/","url":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/","name":"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30 - Castelforte","isPartOf":{"@id":"https:\/\/comunicacity.net\/castelforte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/09\/Pannello-Informativo-Castelforte.jpg","datePublished":"2018-10-01T07:32:44+00:00","author":{"@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/#primaryimage","url":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/09\/Pannello-Informativo-Castelforte.jpg","contentUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2017\/09\/Pannello-Informativo-Castelforte.jpg","width":240,"height":120},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/castelforte\/2018\/10\/01\/interruzione-idrica-giorno-4-ottobre-2018-dalle-1030-alle-1630\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/castelforte\/"},{"@type":"ListItem","position":2,"name":"Interruzione idrica giorno 4 ottobre 2018 dalle 10,30 alle 16,30"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/castelforte\/#website","url":"https:\/\/comunicacity.net\/castelforte\/","name":"Castelforte","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/castelforte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71","name":"castelforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","caption":"castelforte"},"url":"https:\/\/comunicacity.net\/castelforte\/author\/castelforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/1018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/users\/239"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/comments?post=1018"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/1018\/revisions"}],"predecessor-version":[{"id":1019,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/1018\/revisions\/1019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/media\/264"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/media?parent=1018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/categories?post=1018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/tags?post=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}