{"id":1188,"date":"2019-01-25T12:46:42","date_gmt":"2019-01-25T11:46:42","guid":{"rendered":"https:\/\/comunicacity.net\/castelforte\/?p=1188"},"modified":"2019-01-25T12:46:42","modified_gmt":"2019-01-25T11:46:42","slug":"giornata-della-memoria","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/","title":{"rendered":"Giornata della Memoria"},"content":{"rendered":"<p>Uno dei mali peggiori, ha detto Liliana Segre e lo ha ribadito il Presidente Sergio Mattarella, \u00e8 l&#8217;indifferenza. Abbiamo davvero bisogno di fare memoria perch\u00e9 il male, purtroppo, c&#8217;\u00e8 e \u201calberga nascosto, -ha detto il nostro Presidente della Repubblica- come un virus micidiale, nei bassi fondi della societ\u00e0 civile ed \u00e8 pronto a risvegliarsi appena se ne presentino le condizioni &#8230;\u201d.<\/p>\n<p>Per evitare che la storia possa ripetersi abbiamo necessit\u00e0 di ricordare e di puntare la barra dritta contro chi (e cito ancora il Presidente Mattarella) ripropone: \u201csimboli, linguaggi, riferimenti pseudo culturali, di vecchi e screditati falsi documenti, basati su ridicole teorie cospirazionistiche &#8230;\u201d.<\/p>\n<p>Perdere la memoria \u00e8 come avvelenare la societ\u00e0; \u00e8 una manipolazione della storia; \u00e8 come perdere, per sempre, la propria identit\u00e0 di donne e di uomini liberi di pensare e di agire, \u2026 di essere !!!<\/p>\n<p>Tutto questo e, lo dico con convinzione, nella consapevolezza che la storia non si ripete uguale, deve, per\u00f2, aiutarci a leggere con attenzione parole, gesti e atteggiamenti di singoli o di gruppi che, invece, sembrano riproporre egoismi che tanto male hanno fatto ai nostri padri. Penso alle leggi razziali ma anche a tante violenze e soprusi commessi sui deboli da un gruppo che conquist\u00f2 il potere promettendo ordine, disciplina, pane e lavoro. E&#8217; questo modo di fare che oggi potremmo ancora dover subire che deve, invece, aiutarci a mantenere alta l&#8217;attenzione e a spingere il nostro impegno nel continuare a costruire un mondo diverso.<\/p>\n<p>Un mondo che non lascia nessuno dietro;<\/p>\n<p>un mondo che non abbandona al suo destino un povero;<\/p>\n<p>un mondo che sa accogliere;<\/p>\n<p>un mondo che sa includere;<\/p>\n<p>un mondo che prende per mano un bambino solo e lo accompagna incontro alla vita.<\/p>\n<p><i><b>Un mondo che sa alzare lo sguardo, ammirare l&#8217;Infinito e immaginare il bello.<\/b><\/i><\/p>\n<p>Giancarlo Cardillo &#8211; Sindaco<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1189\" src=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg\" alt=\"\" width=\"690\" height=\"360\" srcset=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg 690w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360-300x157.jpg 300w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360-680x355.jpg 680w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360-600x313.jpg 600w\" sizes=\"auto, (max-width: 690px) 100vw, 690px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno dei mali peggiori, ha detto Liliana Segre e lo ha ribadito il Presidente Sergio Mattarella, \u00e8 l&#8217;indifferenza. Abbiamo davvero bisogno di fare memoria perch\u00e9 il male, purtroppo, c&#8217;\u00e8 e [&hellip;]<\/p>\n","protected":false},"author":239,"featured_media":1189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1188","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giornata della Memoria - Castelforte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata della Memoria - Castelforte\" \/>\n<meta property=\"og:description\" content=\"Uno dei mali peggiori, ha detto Liliana Segre e lo ha ribadito il Presidente Sergio Mattarella, \u00e8 l&#8217;indifferenza. Abbiamo davvero bisogno di fare memoria perch\u00e9 il male, purtroppo, c&#8217;\u00e8 e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Castelforte\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-25T11:46:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"690\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castelforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"castelforte\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/\"},\"author\":{\"name\":\"castelforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\"},\"headline\":\"Giornata della Memoria\",\"datePublished\":\"2019-01-25T11:46:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/\"},\"wordCount\":297,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2019\\\/01\\\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/\",\"name\":\"Giornata della Memoria - Castelforte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2019\\\/01\\\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg\",\"datePublished\":\"2019-01-25T11:46:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2019\\\/01\\\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2019\\\/01\\\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg\",\"width\":690,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2019\\\/01\\\/25\\\/giornata-della-memoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornata della Memoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/\",\"name\":\"Castelforte\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\",\"name\":\"castelforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"caption\":\"castelforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/author\\\/castelforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornata della Memoria - Castelforte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/","og_locale":"it_IT","og_type":"article","og_title":"Giornata della Memoria - Castelforte","og_description":"Uno dei mali peggiori, ha detto Liliana Segre e lo ha ribadito il Presidente Sergio Mattarella, \u00e8 l&#8217;indifferenza. Abbiamo davvero bisogno di fare memoria perch\u00e9 il male, purtroppo, c&#8217;\u00e8 e [&hellip;]","og_url":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/","og_site_name":"Castelforte","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2019-01-25T11:46:42+00:00","og_image":[{"width":690,"height":360,"url":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg","type":"image\/jpeg"}],"author":"castelforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"castelforte","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/"},"author":{"name":"castelforte","@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71"},"headline":"Giornata della Memoria","datePublished":"2019-01-25T11:46:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/"},"wordCount":297,"image":{"@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/","url":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/","name":"Giornata della Memoria - Castelforte","isPartOf":{"@id":"https:\/\/comunicacity.net\/castelforte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg","datePublished":"2019-01-25T11:46:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/#primaryimage","url":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg","contentUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2019\/01\/13-film-sullolocausto-da-vedere-giornata-della-memoria-690x360.jpg","width":690,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/castelforte\/2019\/01\/25\/giornata-della-memoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/castelforte\/"},{"@type":"ListItem","position":2,"name":"Giornata della Memoria"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/castelforte\/#website","url":"https:\/\/comunicacity.net\/castelforte\/","name":"Castelforte","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/castelforte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71","name":"castelforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","caption":"castelforte"},"url":"https:\/\/comunicacity.net\/castelforte\/author\/castelforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/1188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/users\/239"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/comments?post=1188"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/1188\/revisions"}],"predecessor-version":[{"id":1190,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/1188\/revisions\/1190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/media\/1189"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/media?parent=1188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/categories?post=1188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/tags?post=1188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}