{"id":2016,"date":"2020-03-18T15:34:29","date_gmt":"2020-03-18T14:34:29","guid":{"rendered":"https:\/\/comunicacity.net\/castelforte\/?p=2016"},"modified":"2020-03-18T19:44:12","modified_gmt":"2020-03-18T18:44:12","slug":"comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/","title":{"rendered":"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2017\" src=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0046_1.jpg\" alt=\"\" width=\"778\" height=\"991\" srcset=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0046_1.jpg 778w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0046_1-236x300.jpg 236w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0046_1-768x978.jpg 768w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0046_1-680x866.jpg 680w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2018\" src=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0047_1.jpg\" alt=\"\" width=\"778\" height=\"971\" srcset=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0047_1.jpg 778w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0047_1-240x300.jpg 240w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0047_1-768x959.jpg 768w, https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/IMG-20200318-WA0047_1-680x849.jpg 680w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":239,"featured_media":1824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-2016","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020 - Castelforte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020 - Castelforte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Castelforte\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-18T14:34:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-18T18:44:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"castelforte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"castelforte\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/\"},\"author\":{\"name\":\"castelforte\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\"},\"headline\":\"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020\",\"datePublished\":\"2020-03-18T14:34:29+00:00\",\"dateModified\":\"2020-03-18T18:44:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/\"},\"wordCount\":9,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2020\\\/03\\\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/\",\"name\":\"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020 - Castelforte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2020\\\/03\\\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg\",\"datePublished\":\"2020-03-18T14:34:29+00:00\",\"dateModified\":\"2020-03-18T18:44:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2020\\\/03\\\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/wp-content\\\/uploads\\\/sites\\\/100\\\/2020\\\/03\\\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/2020\\\/03\\\/18\\\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/\",\"name\":\"Castelforte\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/#\\\/schema\\\/person\\\/2c036caad8ec00b91b2e447f68e4df71\",\"name\":\"castelforte\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g\",\"caption\":\"castelforte\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/castelforte\\\/author\\\/castelforte\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020 - Castelforte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/","og_locale":"it_IT","og_type":"article","og_title":"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020 - Castelforte","og_url":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/","og_site_name":"Castelforte","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-03-18T14:34:29+00:00","article_modified_time":"2020-03-18T18:44:12+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg","type":"image\/jpeg"}],"author":"castelforte","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"castelforte"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/"},"author":{"name":"castelforte","@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71"},"headline":"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020","datePublished":"2020-03-18T14:34:29+00:00","dateModified":"2020-03-18T18:44:12+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/"},"wordCount":9,"image":{"@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/","url":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/","name":"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020 - Castelforte","isPartOf":{"@id":"https:\/\/comunicacity.net\/castelforte\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg","datePublished":"2020-03-18T14:34:29+00:00","dateModified":"2020-03-18T18:44:12+00:00","author":{"@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/#primaryimage","url":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg","contentUrl":"https:\/\/comunicacity.net\/castelforte\/wp-content\/uploads\/sites\/100\/2020\/03\/WhatsApp-Image-2020-03-05-at-11.57.38.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/castelforte\/2020\/03\/18\/comunicato-stampa-della-direzione-generale-asl-latina-del-28-marzo-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/castelforte\/"},{"@type":"ListItem","position":2,"name":"Comunicato stampa della Direzione Generale Asl Latina del 18 marzo 2020"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/castelforte\/#website","url":"https:\/\/comunicacity.net\/castelforte\/","name":"Castelforte","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/castelforte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/castelforte\/#\/schema\/person\/2c036caad8ec00b91b2e447f68e4df71","name":"castelforte","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ba8f99343f0a5bf8dbcf634ed523651a19ffe27713d3c7479ad12a2ab4da2d36?s=96&d=mm&r=g","caption":"castelforte"},"url":"https:\/\/comunicacity.net\/castelforte\/author\/castelforte\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/2016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/users\/239"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/comments?post=2016"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/2016\/revisions"}],"predecessor-version":[{"id":2020,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/posts\/2016\/revisions\/2020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/media\/1824"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/media?parent=2016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/categories?post=2016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/castelforte\/wp-json\/wp\/v2\/tags?post=2016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}