{"id":17980,"date":"2026-01-27T09:12:42","date_gmt":"2026-01-27T08:12:42","guid":{"rendered":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/"},"modified":"2026-01-27T09:12:42","modified_gmt":"2026-01-27T08:12:42","slug":"cessazione-validita-carta-didentita-cartacea","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/","title":{"rendered":"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea"},"content":{"rendered":"<p><em>La carta d\u2019identit\u00e0 rilasciata su modello cartaceo, indipendentemente da quanto riportato nel documento, cesser\u00e0 di essere valida il 3 agosto 2026, per effetto del Regolamento (UE) 2019\/1157 del Parlamento Europeo e del Consiglio dell&#8217;Unione Europea. <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>A partire dal 3 Agosto 2026, la Carta d\u2019Identit\u00e0 cartacea non sar\u00e0 pi\u00f9 considerata valida: a prescindere dalla data di scadenza riportata sul documento, diverr\u00e0 quindi inutilizzabile.<\/p>\n<p>Lo stabilisce il Regolamento Europeo 1157\/2019, che impone standard di sicurezza pi\u00f9 stringenti per i documenti di riconoscimento.<br \/>\nLa principale ragione della dismissione della versione cartacea \u00e8 infatti l\u2019assenza della cosiddetta Machine Readable Zone (M.R.Z.), una zona di lettura ottica composta da tre righe codificate con dati anagrafici, leggibili dai sistemi automatici di controllo.<br \/>\nDi contro, la Carta d\u2019Identit\u00e0 Elettronica (C.I.E.) \u00e8 dotata di questa tecnologia, e pertanto risponde pienamente ai requisiti fissati dall\u2019Unione Europea.<\/p>\n<p>Diviene quindi necessario sostituire il documento cartaceo con la C.I.E., entro tale data.<br \/>\nPoich\u00e8 il rilascio non \u00e8 immediato, si invita a richiedere il nuovo documento con adeguato anticipo rispetto alla scadenza della Carta d\u2019Identit\u00e0 attuale, e in ogni caso ben prima del 3 Agosto 2026.<br \/>\nLe nuove carte di identit\u00e0 (esclusivamente elettroniche, dunque), possono essere gi\u00e0 erogate recandosi in Municipio, e precisamente all\u2019uffiicio Anagrafe Stato Civile.<\/p>\n<p>I cittadini iscritti all\u2019AIRE, invece, dovranno necessariamente rivolgersi al Consolato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La carta d\u2019identit\u00e0 rilasciata su modello cartaceo, indipendentemente da quanto riportato nel documento, cesser\u00e0 di essere valida il 3 agosto 2026, per effetto del Regolamento (UE) 2019\/1157 del Parlamento Europeo [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":17981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-17980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea - Castrocielo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea - Castrocielo\" \/>\n<meta property=\"og:description\" content=\"La carta d\u2019identit\u00e0 rilasciata su modello cartaceo, indipendentemente da quanto riportato nel documento, cesser\u00e0 di essere valida il 3 agosto 2026, per effetto del Regolamento (UE) 2019\/1157 del Parlamento Europeo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/\" \/>\n<meta property=\"og:site_name\" content=\"Castrocielo\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-27T08:12:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/castrocielo\/wp-content\/uploads\/sites\/214\/2026\/01\/carta-identita-cartacea-elettronica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"660\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea\",\"datePublished\":\"2026-01-27T08:12:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/\"},\"wordCount\":226,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/wp-content\\\/uploads\\\/sites\\\/214\\\/2026\\\/01\\\/carta-identita-cartacea-elettronica.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/\",\"name\":\"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea - Castrocielo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/wp-content\\\/uploads\\\/sites\\\/214\\\/2026\\\/01\\\/carta-identita-cartacea-elettronica.jpg\",\"datePublished\":\"2026-01-27T08:12:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/wp-content\\\/uploads\\\/sites\\\/214\\\/2026\\\/01\\\/carta-identita-cartacea-elettronica.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/wp-content\\\/uploads\\\/sites\\\/214\\\/2026\\\/01\\\/carta-identita-cartacea-elettronica.jpg\",\"width\":1170,\"height\":660},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/2026\\\/01\\\/27\\\/cessazione-validita-carta-didentita-cartacea\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/castrocielo\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea - Castrocielo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/","og_locale":"it_IT","og_type":"article","og_title":"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea - Castrocielo","og_description":"La carta d\u2019identit\u00e0 rilasciata su modello cartaceo, indipendentemente da quanto riportato nel documento, cesser\u00e0 di essere valida il 3 agosto 2026, per effetto del Regolamento (UE) 2019\/1157 del Parlamento Europeo [&hellip;]","og_url":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/","og_site_name":"Castrocielo","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-27T08:12:42+00:00","og_image":[{"width":1170,"height":660,"url":"https:\/\/comunicacity.net\/castrocielo\/wp-content\/uploads\/sites\/214\/2026\/01\/carta-identita-cartacea-elettronica.jpg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/castrocielo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea","datePublished":"2026-01-27T08:12:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/"},"wordCount":226,"publisher":{"@id":"https:\/\/comunicacity.net\/castrocielo\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/castrocielo\/wp-content\/uploads\/sites\/214\/2026\/01\/carta-identita-cartacea-elettronica.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/","url":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/","name":"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea - Castrocielo","isPartOf":{"@id":"https:\/\/comunicacity.net\/castrocielo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/castrocielo\/wp-content\/uploads\/sites\/214\/2026\/01\/carta-identita-cartacea-elettronica.jpg","datePublished":"2026-01-27T08:12:42+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/#primaryimage","url":"https:\/\/comunicacity.net\/castrocielo\/wp-content\/uploads\/sites\/214\/2026\/01\/carta-identita-cartacea-elettronica.jpg","contentUrl":"https:\/\/comunicacity.net\/castrocielo\/wp-content\/uploads\/sites\/214\/2026\/01\/carta-identita-cartacea-elettronica.jpg","width":1170,"height":660},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/castrocielo\/2026\/01\/27\/cessazione-validita-carta-didentita-cartacea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/castrocielo\/"},{"@type":"ListItem","position":2,"name":"Cessazione validit\u00e0 Carta d\u2019Identit\u00e0 cartacea"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/castrocielo\/#website","url":"https:\/\/comunicacity.net\/castrocielo\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/castrocielo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/castrocielo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/castrocielo\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/castrocielo\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/castrocielo\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/castrocielo\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/castrocielo\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001914"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/posts\/17980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/comments?post=17980"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/posts\/17980\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/media\/17981"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/media?parent=17980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/categories?post=17980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/castrocielo\/wp-json\/wp\/v2\/tags?post=17980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}