{"id":197,"date":"2025-04-28T18:48:42","date_gmt":"2025-04-28T16:48:42","guid":{"rendered":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/"},"modified":"2025-11-13T12:05:35","modified_gmt":"2025-11-13T11:05:35","slug":"avviso-allutenza-chiusura-al-pubblico-utc","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/","title":{"rendered":"Avviso all\u2019utenza chiusura al pubblico utc"},"content":{"rendered":"<p><em>Avviso all\u2019utenza chiusura al pubblico utc<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>Avviso all\u2019utenza<\/strong><\/p>\n<p><strong>si comunica che, il 30\/04\/2025, l\u2019ufficio tecnico rester\u00e0 chiuso al pubblico. l\u2019apertura \u00e8 posticipata al 02\/05\/2025 dalle ore 10:00 alle ore 12:00<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avviso all\u2019utenza chiusura al pubblico utc&nbsp; Descrizione&nbsp; Avviso all\u2019utenza si comunica che, il 30\/04\/2025, l\u2019ufficio tecnico rester\u00e0 chiuso al pubblico. l\u2019apertura \u00e8 posticipata al 02\/05\/2025 dalle ore 10:00 alle ore [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-197","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso all\u2019utenza chiusura al pubblico utc - Celle di Bulgheria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso all\u2019utenza chiusura al pubblico utc - Celle di Bulgheria\" \/>\n<meta property=\"og:description\" content=\"Avviso all\u2019utenza chiusura al pubblico utc&nbsp; Descrizione&nbsp; Avviso all\u2019utenza si comunica che, il 30\/04\/2025, l\u2019ufficio tecnico rester\u00e0 chiuso al pubblico. l\u2019apertura \u00e8 posticipata al 02\/05\/2025 dalle ore 10:00 alle ore [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/\" \/>\n<meta property=\"og:site_name\" content=\"Celle di Bulgheria\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T16:48:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T11:05:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2025\\\/04\\\/28\\\/avviso-allutenza-chiusura-al-pubblico-utc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2025\\\/04\\\/28\\\/avviso-allutenza-chiusura-al-pubblico-utc\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Avviso all\u2019utenza chiusura al pubblico utc\",\"datePublished\":\"2025-04-28T16:48:42+00:00\",\"dateModified\":\"2025-11-13T11:05:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2025\\\/04\\\/28\\\/avviso-allutenza-chiusura-al-pubblico-utc\\\/\"},\"wordCount\":39,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2025\\\/04\\\/28\\\/avviso-allutenza-chiusura-al-pubblico-utc\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2025\\\/04\\\/28\\\/avviso-allutenza-chiusura-al-pubblico-utc\\\/\",\"name\":\"Avviso all\u2019utenza chiusura al pubblico utc - Celle di Bulgheria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#website\"},\"datePublished\":\"2025-04-28T16:48:42+00:00\",\"dateModified\":\"2025-11-13T11:05:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2025\\\/04\\\/28\\\/avviso-allutenza-chiusura-al-pubblico-utc\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2025\\\/04\\\/28\\\/avviso-allutenza-chiusura-al-pubblico-utc\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2025\\\/04\\\/28\\\/avviso-allutenza-chiusura-al-pubblico-utc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AVVISO ALL\u2019UTENZA CHIUSURA AL PUBBLICO UTC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso all\u2019utenza chiusura al pubblico utc - Celle di Bulgheria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso all\u2019utenza chiusura al pubblico utc - Celle di Bulgheria","og_description":"Avviso all\u2019utenza chiusura al pubblico utc&nbsp; Descrizione&nbsp; Avviso all\u2019utenza si comunica che, il 30\/04\/2025, l\u2019ufficio tecnico rester\u00e0 chiuso al pubblico. l\u2019apertura \u00e8 posticipata al 02\/05\/2025 dalle ore 10:00 alle ore [&hellip;]","og_url":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/","og_site_name":"Celle di Bulgheria","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-04-28T16:48:42+00:00","article_modified_time":"2025-11-13T11:05:35+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Avviso all\u2019utenza chiusura al pubblico utc","datePublished":"2025-04-28T16:48:42+00:00","dateModified":"2025-11-13T11:05:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/"},"wordCount":39,"publisher":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/","url":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/","name":"Avviso all\u2019utenza chiusura al pubblico utc - Celle di Bulgheria","isPartOf":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#website"},"datePublished":"2025-04-28T16:48:42+00:00","dateModified":"2025-11-13T11:05:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2025\/04\/28\/avviso-allutenza-chiusura-al-pubblico-utc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/celledibulgheria\/"},{"@type":"ListItem","position":2,"name":"AVVISO ALL\u2019UTENZA CHIUSURA AL PUBBLICO UTC"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#website","url":"https:\/\/comunicacity.net\/celledibulgheria\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/celledibulgheria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/celledibulgheria\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001134"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/comments?post=197"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts\/197\/revisions"}],"predecessor-version":[{"id":350,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts\/197\/revisions\/350"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/media?parent=197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/categories?post=197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/tags?post=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}