{"id":24,"date":"2024-02-15T11:16:57","date_gmt":"2024-02-15T10:16:57","guid":{"rendered":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/"},"modified":"2024-02-15T11:16:57","modified_gmt":"2024-02-15T10:16:57","slug":"avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/","title":{"rendered":"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana."},"content":{"rendered":"<p><em>L\u2019Avviso completo e il relativo modello di domanda pu\u00f2 essere scaricato sul sito del Piano di Zona Ambito S\/9 all\u2019indirizzo www.pianosociales9.it sezione \u201cNews\u201d.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>LA COORDINATRICE DELL\u2019UFFICIO DI PIANO rende noto che in esecuzione della D.D. n. 62 del 14\/02\/2024 \u00e8 indetto un Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana.<br \/>\nL\u2019Avviso completo e il relativo modello di domanda pu\u00f2 essere scaricato sul sito del Piano di Zona Ambito S\/9 all\u2019indirizzo<br \/>\nwww.pianosociales9.it sezione \u201cNews\u201d.<br \/>\nScadenza presentazione istanze: 15\/03\/2024 ore 13:00<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_26\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/Locandina-Turismo-sociale-e-culturale-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/Locandina-Turismo-sociale-e-culturale-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Locandina Turismo sociale e culturale<\/a><\/li>\n<li><a id=\"wpba_attachment_list_27\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/allegato-A.doc\" onclick=\"window.open('https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/allegato-A.doc', '_system'); return false;\"><i class='icon attachment'><\/i>allegato A<\/a><\/li>\n<li><a id=\"wpba_attachment_list_28\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/avviso-progetti-turismo-sociale-e-culturale-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/avviso-progetti-turismo-sociale-e-culturale-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso progetti turismo sociale e culturale<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Avviso completo e il relativo modello di domanda pu\u00f2 essere scaricato sul sito del Piano di Zona Ambito S\/9 all\u2019indirizzo www.pianosociales9.it sezione \u201cNews\u201d.&nbsp; Descrizione&nbsp; LA COORDINATRICE DELL\u2019UFFICIO DI PIANO rende [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":25,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-24","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana. - Celle di Bulgheria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana. - Celle di Bulgheria\" \/>\n<meta property=\"og:description\" content=\"L\u2019Avviso completo e il relativo modello di domanda pu\u00f2 essere scaricato sul sito del Piano di Zona Ambito S\/9 all\u2019indirizzo www.pianosociales9.it sezione \u201cNews\u201d.&nbsp; Descrizione&nbsp; LA COORDINATRICE DELL\u2019UFFICIO DI PIANO rende [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/\" \/>\n<meta property=\"og:site_name\" content=\"Celle di Bulgheria\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-15T10:16:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana.\",\"datePublished\":\"2024-02-15T10:16:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/\"},\"wordCount\":127,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/wp-content\\\/uploads\\\/sites\\\/223\\\/2024\\\/04\\\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/\",\"name\":\"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana. - Celle di Bulgheria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/wp-content\\\/uploads\\\/sites\\\/223\\\/2024\\\/04\\\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg\",\"datePublished\":\"2024-02-15T10:16:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/wp-content\\\/uploads\\\/sites\\\/223\\\/2024\\\/04\\\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/wp-content\\\/uploads\\\/sites\\\/223\\\/2024\\\/04\\\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/02\\\/15\\\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana. - Celle di Bulgheria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana. - Celle di Bulgheria","og_description":"L\u2019Avviso completo e il relativo modello di domanda pu\u00f2 essere scaricato sul sito del Piano di Zona Ambito S\/9 all\u2019indirizzo www.pianosociales9.it sezione \u201cNews\u201d.&nbsp; Descrizione&nbsp; LA COORDINATRICE DELL\u2019UFFICIO DI PIANO rende [&hellip;]","og_url":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/","og_site_name":"Celle di Bulgheria","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-02-15T10:16:57+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg","type":"image\/jpeg"}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana.","datePublished":"2024-02-15T10:16:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/"},"wordCount":127,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/","url":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/","name":"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana. - Celle di Bulgheria","isPartOf":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg","datePublished":"2024-02-15T10:16:57+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/#primaryimage","url":"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/04\/Stemma_Celle_di_Bulgheria-transformed-scaled-1.jpeg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/02\/15\/avviso-pubblico-per-la-presentazione-di-richiesta-di-partecipazione-ad-una-visita-guidata-presso-la-reggia-di-caserta-o-una-localita-della-costiera-amalfitana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/celledibulgheria\/"},{"@type":"ListItem","position":2,"name":"Avviso Pubblico per la presentazione di richiesta di partecipazione ad una visita guidata presso la Reggia di Caserta o una localit\u00e0 della Costiera Amalfitana."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#website","url":"https:\/\/comunicacity.net\/celledibulgheria\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/celledibulgheria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/celledibulgheria\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000839"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/comments?post=24"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts\/24\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/media\/25"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/media?parent=24"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/categories?post=24"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/tags?post=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}