{"id":33,"date":"2024-06-10T11:07:36","date_gmt":"2024-06-10T09:07:36","guid":{"rendered":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/"},"modified":"2024-06-10T11:07:36","modified_gmt":"2024-06-10T09:07:36","slug":"avviso-pubblico-iscrizioni-micro-nido","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/","title":{"rendered":"Avviso pubblico iscrizioni micro nido"},"content":{"rendered":"<p><em>La Coordinatrice dell\u2019Ufficio di Piano rende noto che in esecuzione della determina n. 219 del 07\/06\/2024 \u00e8 stato indetto un avviso pubblico per la presentazione delle iscrizioni ai servizi di Micronido dell\u2019Ambito Territoriale S\/9.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>L\u2019Avviso completo e il relativo modello di domanda pu\u00f2 essere scaricato sul sito del Piano di Zona Ambito S\/9 all\u2019indirizzo www.pianosociales9.it sezione \u201cNews\u201d.<\/p>\n<p>Scadenza presentazione istanze 01\/07\/2024 ore 12:00<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_34\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/06\/Locandina-Iscrizioni-nido.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/06\/Locandina-Iscrizioni-nido.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Locandina Iscrizioni nido<\/a><\/li>\n<li><a id=\"wpba_attachment_list_35\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/06\/1717863620776_avviso-micro-nido-anno-educativo-2024-2025.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/06\/1717863620776_avviso-micro-nido-anno-educativo-2024-2025.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>1717863620776_avviso micro nido anno educativo 2024-2025<\/a><\/li>\n<li><a id=\"wpba_attachment_list_36\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/06\/allegato-A-2024-2025.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/uploads\/sites\/223\/2024\/06\/allegato-A-2024-2025.docx', '_system'); return false;\"><i class='icon attachment'><\/i>allegato A 2024 2025<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Coordinatrice dell\u2019Ufficio di Piano rende noto che in esecuzione della determina n. 219 del 07\/06\/2024 \u00e8 stato indetto un avviso pubblico per la presentazione delle iscrizioni ai servizi di [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-33","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico iscrizioni micro nido - Celle di Bulgheria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico iscrizioni micro nido - Celle di Bulgheria\" \/>\n<meta property=\"og:description\" content=\"La Coordinatrice dell\u2019Ufficio di Piano rende noto che in esecuzione della determina n. 219 del 07\/06\/2024 \u00e8 stato indetto un avviso pubblico per la presentazione delle iscrizioni ai servizi di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/\" \/>\n<meta property=\"og:site_name\" content=\"Celle di Bulgheria\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T09:07:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"Gestore Yesicode\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestore Yesicode\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/06\\\/10\\\/avviso-pubblico-iscrizioni-micro-nido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/06\\\/10\\\/avviso-pubblico-iscrizioni-micro-nido\\\/\"},\"author\":{\"name\":\"Gestore Yesicode\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\"},\"headline\":\"Avviso pubblico iscrizioni micro nido\",\"datePublished\":\"2024-06-10T09:07:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/06\\\/10\\\/avviso-pubblico-iscrizioni-micro-nido\\\/\"},\"wordCount\":72,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/06\\\/10\\\/avviso-pubblico-iscrizioni-micro-nido\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/06\\\/10\\\/avviso-pubblico-iscrizioni-micro-nido\\\/\",\"name\":\"Avviso pubblico iscrizioni micro nido - Celle di Bulgheria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#website\"},\"datePublished\":\"2024-06-10T09:07:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/06\\\/10\\\/avviso-pubblico-iscrizioni-micro-nido\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/06\\\/10\\\/avviso-pubblico-iscrizioni-micro-nido\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/2024\\\/06\\\/10\\\/avviso-pubblico-iscrizioni-micro-nido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico iscrizioni micro nido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/celledibulgheria\\\/#\\\/schema\\\/person\\\/090ba36d35213b36fa8ac78b8f4a1ff0\",\"name\":\"Gestore Yesicode\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g\",\"caption\":\"Gestore Yesicode\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico iscrizioni micro nido - Celle di Bulgheria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico iscrizioni micro nido - Celle di Bulgheria","og_description":"La Coordinatrice dell\u2019Ufficio di Piano rende noto che in esecuzione della determina n. 219 del 07\/06\/2024 \u00e8 stato indetto un avviso pubblico per la presentazione delle iscrizioni ai servizi di [&hellip;]","og_url":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/","og_site_name":"Celle di Bulgheria","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-06-10T09:07:36+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/celledibulgheria\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"Gestore Yesicode","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"Gestore Yesicode"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/"},"author":{"name":"Gestore Yesicode","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0"},"headline":"Avviso pubblico iscrizioni micro nido","datePublished":"2024-06-10T09:07:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/"},"wordCount":72,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/","url":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/","name":"Avviso pubblico iscrizioni micro nido - Celle di Bulgheria","isPartOf":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#website"},"datePublished":"2024-06-10T09:07:36+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/celledibulgheria\/2024\/06\/10\/avviso-pubblico-iscrizioni-micro-nido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/celledibulgheria\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico iscrizioni micro nido"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#website","url":"https:\/\/comunicacity.net\/celledibulgheria\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/celledibulgheria\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/celledibulgheria\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/celledibulgheria\/#\/schema\/person\/090ba36d35213b36fa8ac78b8f4a1ff0","name":"Gestore Yesicode","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/17d1e47f62a89e264a6b42c225a083aad9d4c5e7916d48459fe3d846d9c56314?s=96&d=mm&r=g","caption":"Gestore Yesicode"}}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"0000924"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts\/33","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/comments?post=33"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/posts\/33\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/media?parent=33"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/categories?post=33"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/celledibulgheria\/wp-json\/wp\/v2\/tags?post=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}