{"id":18314,"date":"2021-01-28T12:33:00","date_gmt":"2021-01-28T11:33:00","guid":{"rendered":"https:\/\/comune.cervaro.fr.it\/?p=18314"},"modified":"2021-01-28T12:33:00","modified_gmt":"2021-01-28T11:33:00","slug":"sopralluogo-alloggi-ater-28-01-2021","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/","title":{"rendered":"SOPRALLUOGO ALLOGGI ATER 28.01.2021"},"content":{"rendered":"<p>Oggi, 28.01.2021, a soli 3 mesi dall&#8217;insediamento della nuova Amministrazione ed a seguito di una incessante segnalazione da parte del Comune,\u00a0 \u00e8 stato effettuato sopralluogo presso gli alloggi Ater siti in Loc. Piternis, con il Responsabile di Zona della manutenzione dell&#8217;ATER Sig. Sergio Ottaviani, l&#8217;Ing. Angelo Conte, il Geom. Giancarlo Marandola della III area tecnica\/urbanistica del Comune di Cervaro e l&#8217;Assessore Francesca Pontone, i quali hanno verificato lo status interno delle abitazioni e le loro pertinenze esterne.<br \/>\nConsapevoli della necessit\u00e0 di agire urgentemente, oggi \u00e8 stata sugellata un&#8217;importante intesa tra Comune ed Ater che, nelle rispettive competenze, si attiveranno di concerto per restituire decoro e dignit\u00e0 ad una delle localit\u00e0 pi\u00f9 vive e bisognose della nostra citt\u00e0.<\/p>\n<p>Il prossimo passo sar\u00e0 un incontro con l&#8217;Ing. Gemma, dirigente dell&#8217;Area Tecnica dell&#8217;Ater, al fine di addivenire, in tempi consoni,\u00a0 alla risoluzione delle problematiche riscontrate con immediati lavori di manutenzione.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-18317\" src=\"https:\/\/comune.cervaro.fr.it\/wp-content\/uploads\/2021\/01\/ater1-297x300.jpeg\" alt=\"\" width=\"297\" height=\"300\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-18318\" src=\"https:\/\/comune.cervaro.fr.it\/wp-content\/uploads\/2021\/01\/ater-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-18316\" src=\"https:\/\/comune.cervaro.fr.it\/wp-content\/uploads\/2021\/01\/ater3-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" \/><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-18315 alignright\" src=\"https:\/\/comune.cervaro.fr.it\/wp-content\/uploads\/2021\/01\/ater2-300x225.jpeg\" alt=\"\" width=\"363\" height=\"272\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oggi, 28.01.2021, a soli 3 mesi dall&#8217;insediamento della nuova Amministrazione ed a seguito di una incessante segnalazione da parte del Comune,\u00a0 \u00e8 stato effettuato sopralluogo presso gli alloggi Ater siti [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":12407,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-18314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SOPRALLUOGO ALLOGGI ATER 28.01.2021 - Cervaro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOPRALLUOGO ALLOGGI ATER 28.01.2021 - Cervaro\" \/>\n<meta property=\"og:description\" content=\"Oggi, 28.01.2021, a soli 3 mesi dall&#8217;insediamento della nuova Amministrazione ed a seguito di una incessante segnalazione da parte del Comune,\u00a0 \u00e8 stato effettuato sopralluogo presso gli alloggi Ater siti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Cervaro\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-28T11:33:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cervaro\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"giovannivendittelli\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"giovannivendittelli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/\"},\"author\":{\"name\":\"giovannivendittelli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/442fbda0948f2806a10c8bda578f1317\"},\"headline\":\"SOPRALLUOGO ALLOGGI ATER 28.01.2021\",\"datePublished\":\"2021-01-28T11:33:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/\"},\"wordCount\":148,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/\",\"name\":\"SOPRALLUOGO ALLOGGI ATER 28.01.2021 - Cervaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-01-28T11:33:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/442fbda0948f2806a10c8bda578f1317\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/01\\\/28\\\/sopralluogo-alloggi-ater-28-01-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOPRALLUOGO ALLOGGI ATER 28.01.2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/\",\"name\":\"Cervaro\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/442fbda0948f2806a10c8bda578f1317\",\"name\":\"giovannivendittelli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g\",\"caption\":\"giovannivendittelli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/author\\\/giovannivendittelli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SOPRALLUOGO ALLOGGI ATER 28.01.2021 - Cervaro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/","og_locale":"it_IT","og_type":"article","og_title":"SOPRALLUOGO ALLOGGI ATER 28.01.2021 - Cervaro","og_description":"Oggi, 28.01.2021, a soli 3 mesi dall&#8217;insediamento della nuova Amministrazione ed a seguito di una incessante segnalazione da parte del Comune,\u00a0 \u00e8 stato effettuato sopralluogo presso gli alloggi Ater siti [&hellip;]","og_url":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/","og_site_name":"Cervaro","article_published_time":"2021-01-28T11:33:00+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/cervaro\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"giovannivendittelli","twitter_misc":{"Scritto da":"giovannivendittelli","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/"},"author":{"name":"giovannivendittelli","@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/442fbda0948f2806a10c8bda578f1317"},"headline":"SOPRALLUOGO ALLOGGI ATER 28.01.2021","datePublished":"2021-01-28T11:33:00+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/"},"wordCount":148,"image":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/#primaryimage"},"thumbnailUrl":"","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/","url":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/","name":"SOPRALLUOGO ALLOGGI ATER 28.01.2021 - Cervaro","isPartOf":{"@id":"https:\/\/comunicacity.net\/cervaro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-01-28T11:33:00+00:00","author":{"@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/442fbda0948f2806a10c8bda578f1317"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cervaro\/2021\/01\/28\/sopralluogo-alloggi-ater-28-01-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cervaro\/"},{"@type":"ListItem","position":2,"name":"SOPRALLUOGO ALLOGGI ATER 28.01.2021"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cervaro\/#website","url":"https:\/\/comunicacity.net\/cervaro\/","name":"Cervaro","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cervaro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/442fbda0948f2806a10c8bda578f1317","name":"giovannivendittelli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g","caption":"giovannivendittelli"},"url":"https:\/\/comunicacity.net\/cervaro\/author\/giovannivendittelli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts\/18314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/comments?post=18314"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts\/18314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/media?parent=18314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/categories?post=18314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/tags?post=18314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}