{"id":18539,"date":"2021-03-26T11:27:37","date_gmt":"2021-03-26T10:27:37","guid":{"rendered":"https:\/\/comune.cervaro.fr.it\/?p=18539"},"modified":"2021-03-26T11:27:37","modified_gmt":"2021-03-26T10:27:37","slug":"pubblicata-la-graduatoria-del-progetto-del-servizio-civile","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/","title":{"rendered":"Pubblicata la graduatoria del progetto del Servizio Civile"},"content":{"rendered":"<p>Si allega graduatoria. Il progetto inizier\u00e0 il giorno 24 Giugno 2021.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si allega graduatoria. Il progetto inizier\u00e0 il giorno 24 Giugno 2021.<\/p>\n","protected":false},"author":28,"featured_media":13428,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[],"class_list":["post-18539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pubblicata la graduatoria del progetto del Servizio Civile - Cervaro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pubblicata la graduatoria del progetto del Servizio Civile - Cervaro\" \/>\n<meta property=\"og:description\" content=\"Si allega graduatoria. Il progetto inizier\u00e0 il giorno 24 Giugno 2021.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/\" \/>\n<meta property=\"og:site_name\" content=\"Cervaro\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-26T10:27:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cervaro\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/bandi-e-concorsi.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"giovannivendittelli\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"giovannivendittelli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/\"},\"author\":{\"name\":\"giovannivendittelli\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/442fbda0948f2806a10c8bda578f1317\"},\"headline\":\"Pubblicata la graduatoria del progetto del Servizio Civile\",\"datePublished\":\"2021-03-26T10:27:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/\"},\"wordCount\":17,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/\",\"name\":\"Pubblicata la graduatoria del progetto del Servizio Civile - Cervaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-03-26T10:27:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/442fbda0948f2806a10c8bda578f1317\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2021\\\/03\\\/26\\\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pubblicata la graduatoria del progetto del Servizio Civile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/\",\"name\":\"Cervaro\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/442fbda0948f2806a10c8bda578f1317\",\"name\":\"giovannivendittelli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g\",\"caption\":\"giovannivendittelli\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/author\\\/giovannivendittelli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pubblicata la graduatoria del progetto del Servizio Civile - Cervaro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/","og_locale":"it_IT","og_type":"article","og_title":"Pubblicata la graduatoria del progetto del Servizio Civile - Cervaro","og_description":"Si allega graduatoria. Il progetto inizier\u00e0 il giorno 24 Giugno 2021.","og_url":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/","og_site_name":"Cervaro","article_published_time":"2021-03-26T10:27:37+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/cervaro\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/bandi-e-concorsi.png","height":600,"width":1200,"type":""}],"author":"giovannivendittelli","twitter_misc":{"Scritto da":"giovannivendittelli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/"},"author":{"name":"giovannivendittelli","@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/442fbda0948f2806a10c8bda578f1317"},"headline":"Pubblicata la graduatoria del progetto del Servizio Civile","datePublished":"2021-03-26T10:27:37+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/"},"wordCount":17,"image":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/#primaryimage"},"thumbnailUrl":"","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/","url":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/","name":"Pubblicata la graduatoria del progetto del Servizio Civile - Cervaro","isPartOf":{"@id":"https:\/\/comunicacity.net\/cervaro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-03-26T10:27:37+00:00","author":{"@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/442fbda0948f2806a10c8bda578f1317"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cervaro\/2021\/03\/26\/pubblicata-la-graduatoria-del-progetto-del-servizio-civile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cervaro\/"},{"@type":"ListItem","position":2,"name":"Pubblicata la graduatoria del progetto del Servizio Civile"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cervaro\/#website","url":"https:\/\/comunicacity.net\/cervaro\/","name":"Cervaro","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cervaro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/442fbda0948f2806a10c8bda578f1317","name":"giovannivendittelli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ae0c3c56cb4d29ddacfd0e4e6562d0f285f80eb8e3b3ca653c93a0cf713ff64?s=96&d=mm&r=g","caption":"giovannivendittelli"},"url":"https:\/\/comunicacity.net\/cervaro\/author\/giovannivendittelli\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts\/18539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/comments?post=18539"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts\/18539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/media?parent=18539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/categories?post=18539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/tags?post=18539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}