{"id":19336,"date":"2022-07-03T19:02:26","date_gmt":"2022-07-03T17:02:26","guid":{"rendered":"https:\/\/comunicacity.net\/cervaro\/?p=19336"},"modified":"2022-07-03T19:05:48","modified_gmt":"2022-07-03T17:05:48","slug":"campagna-di-comunicazione-contro-labbandono-dei-cani","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/","title":{"rendered":"Campagna di comunicazione contro l&#8217;abbandono dei cani"},"content":{"rendered":"<p>L\u2019abbandono di cani e gatti, i cosiddetti animali d\u2019affezione, \u00e8 una piaga ancora consistente nel nostro paese.<\/p>\n<p>Purtroppo neanche le adozioni dei cani sembrano essere aumentate rispetto a qualche anno fa.<\/p>\n<p>Tuttavia, l<em>a programmazione degli interventi di cattura dei cani vaganti, sulla base delle priorit\u00e0 d&#8217;intervento \u00e8 attuata dal Comune, che si avvale a questo scopo delle informazioni derivanti dalle segnalazioni dei cittadini e dalla vigilanza sul territorio della Polizia Municipale.<\/em><\/p>\n<p><em>Infatti, una volta ravvisata l&#8217;esigenza della cattura, il Comune chiede l&#8217;intervento del servizio veterinario della ASL competente, che esegue l&#8217;intervento di cattura, assistito dalla Polizia Municipale e\/o da altro personale comunale nell&#8217;individuazione dei cani. <\/em><\/p>\n<p>Pertanto i cani vaganti, incautamente custoditi o dolosamente abbandonati, devono essere portati presso il Canile di Prima Accoglienza per il rintraccio del proprietario e l&#8217;osservazione sanitaria.<\/p>\n<p>I cani non reclamati potranno essere affidati a chi ne far\u00e0 richiesta.<\/p>\n<p>\u00c8 vietato, dalla legge, appropriarsi di un cane vagante senza effettuare i passaggi previsti dalle vigenti norme, e chi lo facesse incorrerebbe nel reato di appropriazione indebita.<\/p>\n<p>Il Comune di Cervaro resta a disposizione di tutti i cittadini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019abbandono di cani e gatti, i cosiddetti animali d\u2019affezione, \u00e8 una piaga ancora consistente nel nostro paese. Purtroppo neanche le adozioni dei cani sembrano essere aumentate rispetto a qualche anno [&hellip;]<\/p>\n","protected":false},"author":282,"featured_media":19340,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-19336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campagna di comunicazione contro l&#039;abbandono dei cani - Cervaro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campagna di comunicazione contro l&#039;abbandono dei cani - Cervaro\" \/>\n<meta property=\"og:description\" content=\"L\u2019abbandono di cani e gatti, i cosiddetti animali d\u2019affezione, \u00e8 una piaga ancora consistente nel nostro paese. Purtroppo neanche le adozioni dei cani sembrano essere aumentate rispetto a qualche anno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/\" \/>\n<meta property=\"og:site_name\" content=\"Cervaro\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-03T17:02:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-03T17:05:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/cervaro\/wp-content\/uploads\/sites\/16\/2022\/07\/RANDAGISMO-CANI-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"877\" \/>\n\t<meta property=\"og:image:height\" content=\"817\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"gestoreyic\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestoreyic\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/\"},\"author\":{\"name\":\"gestoreyic\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"headline\":\"Campagna di comunicazione contro l&#8217;abbandono dei cani\",\"datePublished\":\"2022-07-03T17:02:26+00:00\",\"dateModified\":\"2022-07-03T17:05:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/\"},\"wordCount\":188,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2022\\\/07\\\/RANDAGISMO-CANI-2.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/\",\"name\":\"Campagna di comunicazione contro l'abbandono dei cani - Cervaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2022\\\/07\\\/RANDAGISMO-CANI-2.jpg\",\"datePublished\":\"2022-07-03T17:02:26+00:00\",\"dateModified\":\"2022-07-03T17:05:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2022\\\/07\\\/RANDAGISMO-CANI-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/wp-content\\\/uploads\\\/sites\\\/16\\\/2022\\\/07\\\/RANDAGISMO-CANI-2.jpg\",\"width\":877,\"height\":817},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/2022\\\/07\\\/03\\\/campagna-di-comunicazione-contro-labbandono-dei-cani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagna di comunicazione contro l&#8217;abbandono dei cani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/\",\"name\":\"Cervaro\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/#\\\/schema\\\/person\\\/5278c46c2f94b6a18223c1e9f8964196\",\"name\":\"gestoreyic\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g\",\"caption\":\"gestoreyic\"},\"description\":\"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/cervaro\\\/author\\\/gestoreyic\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campagna di comunicazione contro l'abbandono dei cani - Cervaro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/","og_locale":"it_IT","og_type":"article","og_title":"Campagna di comunicazione contro l'abbandono dei cani - Cervaro","og_description":"L\u2019abbandono di cani e gatti, i cosiddetti animali d\u2019affezione, \u00e8 una piaga ancora consistente nel nostro paese. Purtroppo neanche le adozioni dei cani sembrano essere aumentate rispetto a qualche anno [&hellip;]","og_url":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/","og_site_name":"Cervaro","article_published_time":"2022-07-03T17:02:26+00:00","article_modified_time":"2022-07-03T17:05:48+00:00","og_image":[{"width":877,"height":817,"url":"https:\/\/comunicacity.net\/cervaro\/wp-content\/uploads\/sites\/16\/2022\/07\/RANDAGISMO-CANI-2.jpg","type":"image\/jpeg"}],"author":"gestoreyic","twitter_misc":{"Scritto da":"gestoreyic","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/"},"author":{"name":"gestoreyic","@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"headline":"Campagna di comunicazione contro l&#8217;abbandono dei cani","datePublished":"2022-07-03T17:02:26+00:00","dateModified":"2022-07-03T17:05:48+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/"},"wordCount":188,"image":{"@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cervaro\/wp-content\/uploads\/sites\/16\/2022\/07\/RANDAGISMO-CANI-2.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/","url":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/","name":"Campagna di comunicazione contro l'abbandono dei cani - Cervaro","isPartOf":{"@id":"https:\/\/comunicacity.net\/cervaro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/cervaro\/wp-content\/uploads\/sites\/16\/2022\/07\/RANDAGISMO-CANI-2.jpg","datePublished":"2022-07-03T17:02:26+00:00","dateModified":"2022-07-03T17:05:48+00:00","author":{"@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/#primaryimage","url":"https:\/\/comunicacity.net\/cervaro\/wp-content\/uploads\/sites\/16\/2022\/07\/RANDAGISMO-CANI-2.jpg","contentUrl":"https:\/\/comunicacity.net\/cervaro\/wp-content\/uploads\/sites\/16\/2022\/07\/RANDAGISMO-CANI-2.jpg","width":877,"height":817},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/cervaro\/2022\/07\/03\/campagna-di-comunicazione-contro-labbandono-dei-cani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/cervaro\/"},{"@type":"ListItem","position":2,"name":"Campagna di comunicazione contro l&#8217;abbandono dei cani"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/cervaro\/#website","url":"https:\/\/comunicacity.net\/cervaro\/","name":"Cervaro","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/cervaro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/cervaro\/#\/schema\/person\/5278c46c2f94b6a18223c1e9f8964196","name":"gestoreyic","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e228bc6274405e48b6e7c6d51b3fb4c7eb3ce6ea12a9df9fe672f35b3c3f08c?s=96&d=mm&r=g","caption":"gestoreyic"},"description":"Sede Legale: Via Pazzano 112 00118 Roma Sede Operativa: Via A. Savastano 2 03043 Cassino (FR) Telefono: +39 0776-23813 Email: info@yesicode.it","url":"https:\/\/comunicacity.net\/cervaro\/author\/gestoreyic\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"19626"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts\/19336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/users\/282"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/comments?post=19336"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts\/19336\/revisions"}],"predecessor-version":[{"id":19338,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/posts\/19336\/revisions\/19338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/media\/19340"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/media?parent=19336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/categories?post=19336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/cervaro\/wp-json\/wp\/v2\/tags?post=19336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}