{"id":1419,"date":"2025-11-11T22:17:24","date_gmt":"2025-11-11T21:17:24","guid":{"rendered":"https:\/\/comunicacity.net\/chiopris-viscone\/?p=1419"},"modified":"2025-11-11T22:17:24","modified_gmt":"2025-11-11T21:17:24","slug":"spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/","title":{"rendered":"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere"},"content":{"rendered":"<p>Si informa che, a causa di un imprevisto personale del relatore Dott. Padoan, il terzo incontro del ciclo sul contrasto della violenza del genere non avr\u00e0 luogo in data mercoled\u00ec 12 novembre 2025.<\/p>\n<p>I due laboratori riservati ai ragazzi delle medie si terranno pertanto:<\/p>\n<p>Mercoled\u00ec 19 Novembre alle 15.00\u00a0 \u00a0e<br \/>\nMercoled\u00ec 3 Dicembre alle 15.00<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-1420\" src=\"https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-768x1024.jpg\" alt=\"\" width=\"640\" height=\"853\" srcset=\"https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-768x1024.jpg 768w, https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-225x300.jpg 225w, https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-1152x1536.jpg 1152w, https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-1536x2048.jpg 1536w, https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001.jpg 1575w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si informa che, a causa di un imprevisto personale del relatore Dott. Padoan, il terzo incontro del ciclo sul contrasto della violenza del genere non avr\u00e0 luogo in data mercoled\u00ec [&hellip;]<\/p>\n","protected":false},"author":426,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1419","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere - Chiopris-Viscone<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere - Chiopris-Viscone\" \/>\n<meta property=\"og:description\" content=\"Si informa che, a causa di un imprevisto personale del relatore Dott. Padoan, il terzo incontro del ciclo sul contrasto della violenza del genere non avr\u00e0 luogo in data mercoled\u00ec [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/\" \/>\n<meta property=\"og:site_name\" content=\"Chiopris-Viscone\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-11T21:17:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-768x1024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"avescovo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"avescovo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/\"},\"author\":{\"name\":\"avescovo\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#\\\/schema\\\/person\\\/2befe4c99cd9271ae75e67ed49ef0b96\"},\"headline\":\"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere\",\"datePublished\":\"2025-11-11T21:17:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/\"},\"wordCount\":62,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/wp-content\\\/uploads\\\/sites\\\/242\\\/2025\\\/11\\\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-768x1024.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/\",\"name\":\"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere - Chiopris-Viscone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/wp-content\\\/uploads\\\/sites\\\/242\\\/2025\\\/11\\\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-768x1024.jpg\",\"datePublished\":\"2025-11-11T21:17:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/wp-content\\\/uploads\\\/sites\\\/242\\\/2025\\\/11\\\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/wp-content\\\/uploads\\\/sites\\\/242\\\/2025\\\/11\\\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001.jpg\",\"width\":1575,\"height\":2100},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/2025\\\/11\\\/11\\\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/\",\"name\":\"ComunicaCity\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/chiopris-viscone\\\/#\\\/schema\\\/person\\\/2befe4c99cd9271ae75e67ed49ef0b96\",\"name\":\"avescovo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7793cb2e90802309e68c726f06999f7c338840c7cab8cb0dc8cbf560492dd28?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7793cb2e90802309e68c726f06999f7c338840c7cab8cb0dc8cbf560492dd28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f7793cb2e90802309e68c726f06999f7c338840c7cab8cb0dc8cbf560492dd28?s=96&d=mm&r=g\",\"caption\":\"avescovo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere - Chiopris-Viscone","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/","og_locale":"it_IT","og_type":"article","og_title":"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere - Chiopris-Viscone","og_description":"Si informa che, a causa di un imprevisto personale del relatore Dott. Padoan, il terzo incontro del ciclo sul contrasto della violenza del genere non avr\u00e0 luogo in data mercoled\u00ec [&hellip;]","og_url":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/","og_site_name":"Chiopris-Viscone","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-11-11T21:17:24+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-768x1024.jpg","type":"image\/jpeg"}],"author":"avescovo","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"avescovo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/"},"author":{"name":"avescovo","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#\/schema\/person\/2befe4c99cd9271ae75e67ed49ef0b96"},"headline":"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere","datePublished":"2025-11-11T21:17:24+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/"},"wordCount":62,"publisher":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-768x1024.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/","url":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/","name":"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere - Chiopris-Viscone","isPartOf":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001-768x1024.jpg","datePublished":"2025-11-11T21:17:24+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/#primaryimage","url":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001.jpg","contentUrl":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-content\/uploads\/sites\/242\/2025\/11\/Locandina-ciclo-incontri-per-il-contrasto-della-violenza-di-genere-Chiopris-Viscone_aggiornata_page-0001.jpg","width":1575,"height":2100},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/2025\/11\/11\/spostamento-data-del-3-incontro-del-ciclo-sul-contrasto-della-violenza-di-genere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/chiopris-viscone\/"},{"@type":"ListItem","position":2,"name":"Spostamento data del 3\u00b0 incontro del ciclo sul contrasto della violenza di genere"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#website","url":"https:\/\/comunicacity.net\/chiopris-viscone\/","name":"ComunicaCity","description":"","publisher":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/chiopris-viscone\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/chiopris-viscone\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/chiopris-viscone\/#\/schema\/person\/2befe4c99cd9271ae75e67ed49ef0b96","name":"avescovo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f7793cb2e90802309e68c726f06999f7c338840c7cab8cb0dc8cbf560492dd28?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f7793cb2e90802309e68c726f06999f7c338840c7cab8cb0dc8cbf560492dd28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f7793cb2e90802309e68c726f06999f7c338840c7cab8cb0dc8cbf560492dd28?s=96&d=mm&r=g","caption":"avescovo"}}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/posts\/1419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/users\/426"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/comments?post=1419"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/posts\/1419\/revisions"}],"predecessor-version":[{"id":1421,"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/posts\/1419\/revisions\/1421"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/media?parent=1419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/categories?post=1419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/chiopris-viscone\/wp-json\/wp\/v2\/tags?post=1419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}