{"id":616,"date":"2020-07-09T15:32:37","date_gmt":"2020-07-09T13:32:37","guid":{"rendered":"https:\/\/comunicacity.net\/corenoausonio\/?post_type=rdif&#038;p=616"},"modified":"2020-07-09T15:57:56","modified_gmt":"2020-07-09T13:57:56","slug":"ingombranti-e-raee","status":"publish","type":"rdif","link":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/","title":{"rendered":"Ingombranti e RAEE"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-617\" src=\"https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito.jpg\" alt=\"\" width=\"1003\" height=\"653\" srcset=\"https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito.jpg 1003w, https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito-300x195.jpg 300w, https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito-768x500.jpg 768w\" sizes=\"auto, (max-width: 1003px) 100vw, 1003px\" \/><\/p>\n<p>Guida alla raccolta differenziata dedicata alle utenze domestiche e non domestiche.<\/p>\n<h3>Raccolta mensile<\/h3>\n<p>La raccolta degli ingombranti Raee verr\u00e0 effettuata l\u2019ultimo sabato di ogni mese attraverso prenotazione telefonica chiamando il <strong>Numero Verde 800.462.789<\/strong><br \/>\n.<\/p>\n<hr \/>\n<h1><span style=\"color: #008000\">S\u00cc<\/span><\/h1>\n<ul>\n<li>Mobili e materassi<\/li>\n<li>grandi oggetti<\/li>\n<li>tavole<\/li>\n<li>casse di legno o plastica<\/li>\n<li>poltrone<\/li>\n<li>materiale ferroso<\/li>\n<li>RAEE: cio\u00e8 apparecchiature elettriche ed elettroniche fuori uso (Computer; elettrodomestici piccoli e grandi; TV, lavatrici).<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Guida alla raccolta differenziata dedicata alle utenze domestiche e non domestiche. Raccolta mensile La raccolta degli ingombranti Raee verr\u00e0 effettuata l\u2019ultimo sabato di ogni mese attraverso prenotazione telefonica chiamando il [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":607,"menu_order":0,"template":"","meta":[],"class_list":["post-616","rdif","type-rdif","status-publish","hentry","plugin_rdif-biglist"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ingombranti e RAEE - Coreno Ausonio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ingombranti e RAEE - Coreno Ausonio\" \/>\n<meta property=\"og:description\" content=\"Guida alla raccolta differenziata dedicata alle utenze domestiche e non domestiche. Raccolta mensile La raccolta degli ingombranti Raee verr\u00e0 effettuata l\u2019ultimo sabato di ogni mese attraverso prenotazione telefonica chiamando il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/\" \/>\n<meta property=\"og:site_name\" content=\"Coreno Ausonio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-09T13:57:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/ingombranti-e-raee\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/ingombranti-e-raee\\\/\",\"name\":\"Ingombranti e RAEE - Coreno Ausonio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/ingombranti-e-raee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/ingombranti-e-raee\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2020\\\/07\\\/Elettrodomestici-sito.jpg\",\"datePublished\":\"2020-07-09T13:32:37+00:00\",\"dateModified\":\"2020-07-09T13:57:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/ingombranti-e-raee\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/ingombranti-e-raee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/ingombranti-e-raee\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2020\\\/07\\\/Elettrodomestici-sito.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/wp-content\\\/uploads\\\/sites\\\/99\\\/2020\\\/07\\\/Elettrodomestici-sito.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/ingombranti-e-raee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipologia rifiuto\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/rdif\\\/tipologia-rifiuto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ingombranti e RAEE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/\",\"name\":\"Coreno Ausonio\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/corenoausonio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ingombranti e RAEE - Coreno Ausonio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/","og_locale":"it_IT","og_type":"article","og_title":"Ingombranti e RAEE - Coreno Ausonio","og_description":"Guida alla raccolta differenziata dedicata alle utenze domestiche e non domestiche. Raccolta mensile La raccolta degli ingombranti Raee verr\u00e0 effettuata l\u2019ultimo sabato di ogni mese attraverso prenotazione telefonica chiamando il [&hellip;]","og_url":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/","og_site_name":"Coreno Ausonio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2020-07-09T13:57:56+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/","url":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/","name":"Ingombranti e RAEE - Coreno Ausonio","isPartOf":{"@id":"https:\/\/comunicacity.net\/corenoausonio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito.jpg","datePublished":"2020-07-09T13:32:37+00:00","dateModified":"2020-07-09T13:57:56+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/#primaryimage","url":"https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito.jpg","contentUrl":"https:\/\/comunicacity.net\/corenoausonio\/wp-content\/uploads\/sites\/99\/2020\/07\/Elettrodomestici-sito.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/ingombranti-e-raee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/corenoausonio\/"},{"@type":"ListItem","position":2,"name":"Tipologia rifiuto","item":"https:\/\/comunicacity.net\/corenoausonio\/rdif\/tipologia-rifiuto\/"},{"@type":"ListItem","position":3,"name":"Ingombranti e RAEE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/corenoausonio\/#website","url":"https:\/\/comunicacity.net\/corenoausonio\/","name":"Coreno Ausonio","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/corenoausonio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/corenoausonio\/wp-json\/wp\/v2\/rdif\/616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/corenoausonio\/wp-json\/wp\/v2\/rdif"}],"about":[{"href":"https:\/\/comunicacity.net\/corenoausonio\/wp-json\/wp\/v2\/types\/rdif"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/corenoausonio\/wp-json\/wp\/v2\/rdif\/607"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/corenoausonio\/wp-json\/wp\/v2\/media?parent=616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}