{"id":1080,"date":"2022-03-18T12:47:04","date_gmt":"2022-03-18T11:47:04","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=1080"},"modified":"2022-03-18T12:47:04","modified_gmt":"2022-03-18T11:47:04","slug":"il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/","title":{"rendered":"&#8220;Il territorio la chiave del nostro futuro&#8221;: Video concorso destinato ai giovani"},"content":{"rendered":"<p>Valorizzare il nostro territorio grazie allo sguardo dei giovani \u00e8 l&#8217;obiettivo del <strong>Video concorso a tema &#8220;Il territorio la chiave del nostro futuro&#8221;<\/strong> che l&#8217;Associazione Legambiente FVG con il Gruppo Territorio dell&#8217;Osservatorio Sociale di Fagagna propone alle ragazze e ai ragazzi di et\u00e0 compresa tra i 15 e i 28 anni.<\/p>\n<p>L&#8217;iniziativa offre la possibilit\u00e0 ai giovani di mostrare, attraverso brevi video, non solo ci\u00f2 che amano del proprio territorio, ma anche di raccontare quali migliorie potrebbero essere realizzate per viverlo al meglio.<\/p>\n<p>I video selezionati dalla Giuria del concorso troveranno visibilit\u00e0 nel contesto delle iniziative legate alla Mostra &#8220;Fagagna &#8211; il territorio e le sue trasformazioni&#8221; di prossimo allestimento presso la Sala Mostre del Comune di Fagagna.<\/p>\n<p>I video realizzati vanno inviati entro il 30 aprile 2022 all&#8217;indirizzo mail\u00a0 videoconcorso.territoriofagagna@gmail.com<\/p>\n<p>Per ulteriori informazioni si rimanda al sito www.osservatoriosocialefagagna.wordpress.com<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1081\" src=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014-721x1024.jpg\" alt=\"\" width=\"640\" height=\"909\" srcset=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014-721x1024.jpg 721w, https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014-211x300.jpg 211w, https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014-768x1091.jpg 768w, https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014.jpg 845w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valorizzare il nostro territorio grazie allo sguardo dei giovani \u00e8 l&#8217;obiettivo del Video concorso a tema &#8220;Il territorio la chiave del nostro futuro&#8221; che l&#8217;Associazione Legambiente FVG con il Gruppo [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1080","post","type-post","status-publish","format-standard","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Il territorio la chiave del nostro futuro&quot;: Video concorso destinato ai giovani - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Il territorio la chiave del nostro futuro&quot;: Video concorso destinato ai giovani - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Valorizzare il nostro territorio grazie allo sguardo dei giovani \u00e8 l&#8217;obiettivo del Video concorso a tema &#8220;Il territorio la chiave del nostro futuro&#8221; che l&#8217;Associazione Legambiente FVG con il Gruppo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-18T11:47:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014-721x1024.jpg\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"&#8220;Il territorio la chiave del nostro futuro&#8221;: Video concorso destinato ai giovani\",\"datePublished\":\"2022-03-18T11:47:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/\"},\"wordCount\":154,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2022\\\/03\\\/IMG-20220317-WA0014-721x1024.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/\",\"name\":\"\\\"Il territorio la chiave del nostro futuro\\\": Video concorso destinato ai giovani - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2022\\\/03\\\/IMG-20220317-WA0014-721x1024.jpg\",\"datePublished\":\"2022-03-18T11:47:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2022\\\/03\\\/IMG-20220317-WA0014.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2022\\\/03\\\/IMG-20220317-WA0014.jpg\",\"width\":845,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2022\\\/03\\\/18\\\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Il territorio la chiave del nostro futuro&#8221;: Video concorso destinato ai giovani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Il territorio la chiave del nostro futuro\": Video concorso destinato ai giovani - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/","og_locale":"it_IT","og_type":"article","og_title":"\"Il territorio la chiave del nostro futuro\": Video concorso destinato ai giovani - Fagagna","og_description":"Valorizzare il nostro territorio grazie allo sguardo dei giovani \u00e8 l&#8217;obiettivo del Video concorso a tema &#8220;Il territorio la chiave del nostro futuro&#8221; che l&#8217;Associazione Legambiente FVG con il Gruppo [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-03-18T11:47:04+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014-721x1024.jpg","type":"","width":"","height":""}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"&#8220;Il territorio la chiave del nostro futuro&#8221;: Video concorso destinato ai giovani","datePublished":"2022-03-18T11:47:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/"},"wordCount":154,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014-721x1024.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/","url":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/","name":"\"Il territorio la chiave del nostro futuro\": Video concorso destinato ai giovani - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014-721x1024.jpg","datePublished":"2022-03-18T11:47:04+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2022\/03\/IMG-20220317-WA0014.jpg","width":845,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2022\/03\/18\/il-territorio-la-chiave-del-nostro-futuro-video-concorso-destinato-ai-giovani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"&#8220;Il territorio la chiave del nostro futuro&#8221;: Video concorso destinato ai giovani"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/1080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=1080"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/1080\/revisions"}],"predecessor-version":[{"id":1082,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/1080\/revisions\/1082"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=1080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=1080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=1080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}