{"id":2011,"date":"2024-01-23T14:59:57","date_gmt":"2024-01-23T13:59:57","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=2011"},"modified":"2024-01-23T14:59:57","modified_gmt":"2024-01-23T13:59:57","slug":"prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/","title":{"rendered":"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze &#8211; 27 gennaio &#8211; ore 10.30"},"content":{"rendered":"<p>Sabato 27 gennaio, alle ore 10.30, in Sala Consiliare \u00e8 convocata la prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze di Fagagna.<\/p>\n<p>Buon lavoro a tutti i Consiglieri e Consigliere eletti!<\/p>\n<p>In allegato, convocazione e ordine del giorno.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2012\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/01\/Covocazione-2024_01_27-signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/01\/Covocazione-2024_01_27-signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Covocazione 2024_01_27-signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 27 gennaio, alle ore 10.30, in Sala Consiliare \u00e8 convocata la prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze di Fagagna. Buon lavoro a tutti i Consiglieri [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2011","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze - 27 gennaio - ore 10.30 - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze - 27 gennaio - ore 10.30 - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Sabato 27 gennaio, alle ore 10.30, in Sala Consiliare \u00e8 convocata la prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze di Fagagna. Buon lavoro a tutti i Consiglieri [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T13:59:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/01\\\/23\\\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/01\\\/23\\\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze &#8211; 27 gennaio &#8211; ore 10.30\",\"datePublished\":\"2024-01-23T13:59:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/01\\\/23\\\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\\\/\"},\"wordCount\":51,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/01\\\/23\\\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/01\\\/23\\\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\\\/\",\"name\":\"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze - 27 gennaio - ore 10.30 - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"datePublished\":\"2024-01-23T13:59:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/01\\\/23\\\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/01\\\/23\\\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/01\\\/23\\\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze &#8211; 27 gennaio &#8211; ore 10.30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze - 27 gennaio - ore 10.30 - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/","og_locale":"it_IT","og_type":"article","og_title":"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze - 27 gennaio - ore 10.30 - Fagagna","og_description":"Sabato 27 gennaio, alle ore 10.30, in Sala Consiliare \u00e8 convocata la prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze di Fagagna. Buon lavoro a tutti i Consiglieri [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-01-23T13:59:57+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze &#8211; 27 gennaio &#8211; ore 10.30","datePublished":"2024-01-23T13:59:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/"},"wordCount":51,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/","url":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/","name":"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze - 27 gennaio - ore 10.30 - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"datePublished":"2024-01-23T13:59:57+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/01\/23\/prima-seduta-del-consiglio-comunale-dei-ragazzi-e-delle-ragazze-27-gennaio-ore-10-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Prima seduta del Consiglio Comunale dei Ragazzi e delle Ragazze &#8211; 27 gennaio &#8211; ore 10.30"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=2011"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2011\/revisions"}],"predecessor-version":[{"id":2013,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2011\/revisions\/2013"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=2011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=2011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=2011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}