{"id":2023,"date":"2024-02-19T14:55:18","date_gmt":"2024-02-19T13:55:18","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=2023"},"modified":"2024-02-19T14:55:18","modified_gmt":"2024-02-19T13:55:18","slug":"incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/","title":{"rendered":"Incontro pubblico per le Associazioni &#8211; mercoled\u00ec 21 febbraio &#8211; ore 18.45 &#8211; Sala Consiliare"},"content":{"rendered":"<p>Presso la Sala Consiliare, si terr\u00e0, mercoled\u00ec 21 febbraio alle ore 18.45 un incontro rivolto alle Associazioni per conoscere le linee contributive della Regione Fvg!<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Presso la Sala Consiliare, si terr\u00e0, mercoled\u00ec 21 febbraio alle ore 18.45 un incontro rivolto alle Associazioni per conoscere le linee contributive della Regione Fvg!<\/p>\n","protected":false},"author":357,"featured_media":2024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-2023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incontro pubblico per le Associazioni - mercoled\u00ec 21 febbraio - ore 18.45 - Sala Consiliare - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incontro pubblico per le Associazioni - mercoled\u00ec 21 febbraio - ore 18.45 - Sala Consiliare - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Presso la Sala Consiliare, si terr\u00e0, mercoled\u00ec 21 febbraio alle ore 18.45 un incontro rivolto alle Associazioni per conoscere le linee contributive della Regione Fvg!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-19T13:55:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/02\/IMG-20240219-WA0001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"1036\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Incontro pubblico per le Associazioni &#8211; mercoled\u00ec 21 febbraio &#8211; ore 18.45 &#8211; Sala Consiliare\",\"datePublished\":\"2024-02-19T13:55:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/\"},\"wordCount\":36,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2024\\\/02\\\/IMG-20240219-WA0001.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/\",\"name\":\"Incontro pubblico per le Associazioni - mercoled\u00ec 21 febbraio - ore 18.45 - Sala Consiliare - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2024\\\/02\\\/IMG-20240219-WA0001.jpg\",\"datePublished\":\"2024-02-19T13:55:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2024\\\/02\\\/IMG-20240219-WA0001.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2024\\\/02\\\/IMG-20240219-WA0001.jpg\",\"width\":724,\"height\":1036},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/02\\\/19\\\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incontro pubblico per le Associazioni &#8211; mercoled\u00ec 21 febbraio &#8211; ore 18.45 &#8211; Sala Consiliare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incontro pubblico per le Associazioni - mercoled\u00ec 21 febbraio - ore 18.45 - Sala Consiliare - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/","og_locale":"it_IT","og_type":"article","og_title":"Incontro pubblico per le Associazioni - mercoled\u00ec 21 febbraio - ore 18.45 - Sala Consiliare - Fagagna","og_description":"Presso la Sala Consiliare, si terr\u00e0, mercoled\u00ec 21 febbraio alle ore 18.45 un incontro rivolto alle Associazioni per conoscere le linee contributive della Regione Fvg!","og_url":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-02-19T13:55:18+00:00","og_image":[{"width":724,"height":1036,"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/02\/IMG-20240219-WA0001.jpg","type":"image\/jpeg"}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Incontro pubblico per le Associazioni &#8211; mercoled\u00ec 21 febbraio &#8211; ore 18.45 &#8211; Sala Consiliare","datePublished":"2024-02-19T13:55:18+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/"},"wordCount":36,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/02\/IMG-20240219-WA0001.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/","url":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/","name":"Incontro pubblico per le Associazioni - mercoled\u00ec 21 febbraio - ore 18.45 - Sala Consiliare - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/02\/IMG-20240219-WA0001.jpg","datePublished":"2024-02-19T13:55:18+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/02\/IMG-20240219-WA0001.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/02\/IMG-20240219-WA0001.jpg","width":724,"height":1036},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/02\/19\/incontro-pubblico-per-le-associazioni-mercoledi-21-febbraio-ore-18-45-sala-consiliare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Incontro pubblico per le Associazioni &#8211; mercoled\u00ec 21 febbraio &#8211; ore 18.45 &#8211; Sala Consiliare"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=2023"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2023\/revisions"}],"predecessor-version":[{"id":2025,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2023\/revisions\/2025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media\/2024"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=2023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=2023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=2023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}