{"id":2333,"date":"2024-10-28T18:20:57","date_gmt":"2024-10-28T17:20:57","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=2333"},"modified":"2024-10-28T18:20:57","modified_gmt":"2024-10-28T17:20:57","slug":"celebrazione-del-4-novembre-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/","title":{"rendered":"Celebrazione del 4 Novembre"},"content":{"rendered":"<p>Si ricordano le celebrazioni per il 4 Novembre 2024 secondo la Locandina allegata (3 e 4 Novembre) e pubblicata anche sul sito internet del Comune al seguente link\u00a0<a href=\"https:\/\/www.comune.fagagna.ud.it\/it\/novita-29550\/avvisi-29553\/celebrazione-del-4-novembre-3-e-4-novembre-133392\">https:\/\/www.comune.fagagna.ud.it\/it\/novita-29550\/avvisi-29553\/celebrazione-del-4-novembre-3-e-4-novembre-133392<\/a><\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_2334\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/10\/Celebrazione-4-Novembre-2024-locandina.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/10\/Celebrazione-4-Novembre-2024-locandina.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Celebrazione 4 Novembre 2024 locandina<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si ricordano le celebrazioni per il 4 Novembre 2024 secondo la Locandina allegata (3 e 4 Novembre) e pubblicata anche sul sito internet del Comune al seguente link\u00a0https:\/\/www.comune.fagagna.ud.it\/it\/novita-29550\/avvisi-29553\/celebrazione-del-4-novembre-3-e-4-novembre-133392 &nbsp; \ud83d\udcce [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":2335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-2333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebrazione del 4 Novembre - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrazione del 4 Novembre - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Si ricordano le celebrazioni per il 4 Novembre 2024 secondo la Locandina allegata (3 e 4 Novembre) e pubblicata anche sul sito internet del Comune al seguente link\u00a0https:\/\/www.comune.fagagna.ud.it\/it\/novita-29550\/avvisi-29553\/celebrazione-del-4-novembre-3-e-4-novembre-133392 &nbsp; \ud83d\udcce [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-28T17:20:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/10\/Cattura4nov.png\" \/>\n\t<meta property=\"og:image:width\" content=\"531\" \/>\n\t<meta property=\"og:image:height\" content=\"755\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Celebrazione del 4 Novembre\",\"datePublished\":\"2024-10-28T17:20:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/\"},\"wordCount\":41,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2024\\\/10\\\/Cattura4nov.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/\",\"name\":\"Celebrazione del 4 Novembre - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2024\\\/10\\\/Cattura4nov.png\",\"datePublished\":\"2024-10-28T17:20:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2024\\\/10\\\/Cattura4nov.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2024\\\/10\\\/Cattura4nov.png\",\"width\":531,\"height\":755},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2024\\\/10\\\/28\\\/celebrazione-del-4-novembre-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrazione del 4 Novembre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Celebrazione del 4 Novembre - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/","og_locale":"it_IT","og_type":"article","og_title":"Celebrazione del 4 Novembre - Fagagna","og_description":"Si ricordano le celebrazioni per il 4 Novembre 2024 secondo la Locandina allegata (3 e 4 Novembre) e pubblicata anche sul sito internet del Comune al seguente link\u00a0https:\/\/www.comune.fagagna.ud.it\/it\/novita-29550\/avvisi-29553\/celebrazione-del-4-novembre-3-e-4-novembre-133392 &nbsp; \ud83d\udcce [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-10-28T17:20:57+00:00","og_image":[{"width":531,"height":755,"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/10\/Cattura4nov.png","type":"image\/png"}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Celebrazione del 4 Novembre","datePublished":"2024-10-28T17:20:57+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/"},"wordCount":41,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/10\/Cattura4nov.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/","url":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/","name":"Celebrazione del 4 Novembre - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/10\/Cattura4nov.png","datePublished":"2024-10-28T17:20:57+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/10\/Cattura4nov.png","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2024\/10\/Cattura4nov.png","width":531,"height":755},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2024\/10\/28\/celebrazione-del-4-novembre-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Celebrazione del 4 Novembre"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=2333"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2333\/revisions"}],"predecessor-version":[{"id":2336,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2333\/revisions\/2336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media\/2335"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=2333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=2333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=2333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}