{"id":2969,"date":"2026-02-04T13:28:19","date_gmt":"2026-02-04T12:28:19","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=2969"},"modified":"2026-02-04T13:28:19","modified_gmt":"2026-02-04T12:28:19","slug":"un-viaggio-per-laldila-07-febbraio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/","title":{"rendered":"Un viaggio per l&#8217;aldil\u00e0 &#8211; 07 febbraio"},"content":{"rendered":"<p>Un viaggio per l&#8217;aldil\u00e0: spettacolo\u00a0teatrale in sala Vittoria sabato 07 febbraio 2026 con inizio 20.30 a scopo benefico con Vanni Rugo e Misiot.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un viaggio per l&#8217;aldil\u00e0: spettacolo\u00a0teatrale in sala Vittoria sabato 07 febbraio 2026 con inizio 20.30 a scopo benefico con Vanni Rugo e Misiot.<\/p>\n","protected":false},"author":357,"featured_media":2970,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un viaggio per l&#039;aldil\u00e0 - 07 febbraio - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un viaggio per l&#039;aldil\u00e0 - 07 febbraio - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Un viaggio per l&#8217;aldil\u00e0: spettacolo\u00a0teatrale in sala Vittoria sabato 07 febbraio 2026 con inizio 20.30 a scopo benefico con Vanni Rugo e Misiot.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-04T12:28:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2026\/02\/20260207-teatro-benefico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"762\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Un viaggio per l&#8217;aldil\u00e0 &#8211; 07 febbraio\",\"datePublished\":\"2026-02-04T12:28:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/\"},\"wordCount\":27,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2026\\\/02\\\/20260207-teatro-benefico.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/\",\"name\":\"Un viaggio per l'aldil\u00e0 - 07 febbraio - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2026\\\/02\\\/20260207-teatro-benefico.jpg\",\"datePublished\":\"2026-02-04T12:28:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2026\\\/02\\\/20260207-teatro-benefico.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2026\\\/02\\\/20260207-teatro-benefico.jpg\",\"width\":762,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2026\\\/02\\\/04\\\/un-viaggio-per-laldila-07-febbraio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un viaggio per l&#8217;aldil\u00e0 &#8211; 07 febbraio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un viaggio per l'aldil\u00e0 - 07 febbraio - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/","og_locale":"it_IT","og_type":"article","og_title":"Un viaggio per l'aldil\u00e0 - 07 febbraio - Fagagna","og_description":"Un viaggio per l&#8217;aldil\u00e0: spettacolo\u00a0teatrale in sala Vittoria sabato 07 febbraio 2026 con inizio 20.30 a scopo benefico con Vanni Rugo e Misiot.","og_url":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-02-04T12:28:19+00:00","og_image":[{"width":762,"height":1600,"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2026\/02\/20260207-teatro-benefico.jpg","type":"image\/jpeg"}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Un viaggio per l&#8217;aldil\u00e0 &#8211; 07 febbraio","datePublished":"2026-02-04T12:28:19+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/"},"wordCount":27,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2026\/02\/20260207-teatro-benefico.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/","url":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/","name":"Un viaggio per l'aldil\u00e0 - 07 febbraio - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2026\/02\/20260207-teatro-benefico.jpg","datePublished":"2026-02-04T12:28:19+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2026\/02\/20260207-teatro-benefico.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2026\/02\/20260207-teatro-benefico.jpg","width":762,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2026\/02\/04\/un-viaggio-per-laldila-07-febbraio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Un viaggio per l&#8217;aldil\u00e0 &#8211; 07 febbraio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=2969"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2969\/revisions"}],"predecessor-version":[{"id":2971,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/2969\/revisions\/2971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media\/2970"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=2969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=2969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=2969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}