{"id":501,"date":"2020-11-18T08:25:10","date_gmt":"2020-11-18T07:25:10","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=501"},"modified":"2020-11-18T08:25:10","modified_gmt":"2020-11-18T07:25:10","slug":"emergenza-covid-19-comune-e-servizi-sociali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/","title":{"rendered":"Emergenza Covid-19 &#8211; Comune e servizi sociali"},"content":{"rendered":"<p style=\"margin-bottom: 5.95pt;background: white\"><span style=\"font-family: 'Arial',sans-serif;color: #222222\">Alla luce del riverbero dell&#8217;epidemia Covid-19 in questa seconda parte dell&#8217;anno, l&#8217;amministrazione Comunale di Fagagna intende rassicurare i propri concittadini in merito alla solidit\u00e0 del raccordo tra il Comune e i servizi sociali del territorio. La preziosa sinergia tra i due enti, che negli scorsi mesi ha permesso a molte famiglie di subire in maniera molto minore gli effetti negativi del lockdown diffuso continuer\u00e0 ad essere fattiva nel monitoraggio e nell&#8217;assistenza delle situazioni di disagio sociale generato dall\u2019emergenza epidemiologica che stiamo tuttora attraversando, con una seconda ondata che per certi aspetti si sta dimostrando pi\u00f9 dirompente della prima. L&#8217;erogazione di buoni spesa per circa \u20ac 30.000, la collaborazione con supermercati e vari esercizi di commercio al dettaglio di vicinato, la locale colletta alimentare gestita assieme a Protezione Civile e alle associazioni del territorio, nonch\u00e9 il raccordo con la parrocchia retta da Monsignor Caneva e la Caritas fagagnese e san danielese per la distribuzione di derrate alimentari hanno permesso di dare sostentamento a circa un&#8217;ottantina di nuclei familiari in difficolt\u00e0. Oltre alla consegna di borse spesa tuttora in atto con cadenza quindicinale, le altre misure sono tutte riattivabili a seconda dei bisogni che verranno intercettati tra la popolazione. L&#8217;Amministrazione Comunale, pertanto, invita coloro che si trovano in difficolt\u00e0 a segnalare al Comune la propria situazione, anche se momentanea, e promette di adoperarsi in collaborazione con il Servizio Sociale per calibrare l\u2019intervento pi\u00f9 opportuno da mettere in atto. Nel frattempo la giunta sta gi\u00e0 lavorando per reperire i fondi, un tempo regionali, per alimentare il capitolo di spesa per la Carta Famiglia, strumento che anche in epoca pre-Covid era un valido aiuto per le famiglie della fascia pi\u00f9 debole.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alla luce del riverbero dell&#8217;epidemia Covid-19 in questa seconda parte dell&#8217;anno, l&#8217;amministrazione Comunale di Fagagna intende rassicurare i propri concittadini in merito alla solidit\u00e0 del raccordo tra il Comune e [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":455,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emergenza Covid-19 - Comune e servizi sociali - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emergenza Covid-19 - Comune e servizi sociali - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Alla luce del riverbero dell&#8217;epidemia Covid-19 in questa seconda parte dell&#8217;anno, l&#8217;amministrazione Comunale di Fagagna intende rassicurare i propri concittadini in merito alla solidit\u00e0 del raccordo tra il Comune e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-18T07:25:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2020\/11\/covid-coronavirus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"420\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Emergenza Covid-19 &#8211; Comune e servizi sociali\",\"datePublished\":\"2020-11-18T07:25:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/\"},\"wordCount\":284,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2020\\\/11\\\/covid-coronavirus.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/\",\"name\":\"Emergenza Covid-19 - Comune e servizi sociali - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2020\\\/11\\\/covid-coronavirus.jpg\",\"datePublished\":\"2020-11-18T07:25:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2020\\\/11\\\/covid-coronavirus.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2020\\\/11\\\/covid-coronavirus.jpg\",\"width\":800,\"height\":420,\"caption\":\"Covid Corona Virus in Real 3D Illustration concept to Describe about Corona Virus anatomy and type.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2020\\\/11\\\/18\\\/emergenza-covid-19-comune-e-servizi-sociali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emergenza Covid-19 &#8211; Comune e servizi sociali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emergenza Covid-19 - Comune e servizi sociali - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/","og_locale":"it_IT","og_type":"article","og_title":"Emergenza Covid-19 - Comune e servizi sociali - Fagagna","og_description":"Alla luce del riverbero dell&#8217;epidemia Covid-19 in questa seconda parte dell&#8217;anno, l&#8217;amministrazione Comunale di Fagagna intende rassicurare i propri concittadini in merito alla solidit\u00e0 del raccordo tra il Comune e [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-11-18T07:25:10+00:00","og_image":[{"width":800,"height":420,"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2020\/11\/covid-coronavirus.jpg","type":"image\/jpeg"}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Emergenza Covid-19 &#8211; Comune e servizi sociali","datePublished":"2020-11-18T07:25:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/"},"wordCount":284,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2020\/11\/covid-coronavirus.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/","url":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/","name":"Emergenza Covid-19 - Comune e servizi sociali - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2020\/11\/covid-coronavirus.jpg","datePublished":"2020-11-18T07:25:10+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2020\/11\/covid-coronavirus.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2020\/11\/covid-coronavirus.jpg","width":800,"height":420,"caption":"Covid Corona Virus in Real 3D Illustration concept to Describe about Corona Virus anatomy and type."},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2020\/11\/18\/emergenza-covid-19-comune-e-servizi-sociali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Emergenza Covid-19 &#8211; Comune e servizi sociali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"predecessor-version":[{"id":517,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/501\/revisions\/517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media\/455"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}