{"id":717,"date":"2021-05-28T08:42:11","date_gmt":"2021-05-28T06:42:11","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=717"},"modified":"2021-06-03T08:31:35","modified_gmt":"2021-06-03T06:31:35","slug":"convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/","title":{"rendered":"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna &#8211; sabato 5 giugno ore 18 Sala Vittoria"},"content":{"rendered":"<p>Il Consiglio Comunale \u00e8 stato convocato in seduta straordinaria per <strong>sabato 5 giugno<\/strong> alle <strong>ore 18:00<\/strong> e si terr\u00e0 <strong>c\/o Sala Vittoria<\/strong> in P.zza Marconi per il conferimento della cittadinanza onoraria al milite ignoto. Saranno presenti anche tutti i rappresentanti delle associazioni d&#8217;arma.<\/p>\n<p>Al termine della seduta si terr\u00e0 la presentazione del volume Alpini a Fagagna, redatto in collaborazione con l&#8217;Ecomuseo della gente di collina in occasione del novantesimo anniversario dell&#8217;ass. Alpini di Fagagna.<\/p>\n<p>La cittadinanza \u00e8 invitata, l&#8217;ingresso in sala sar\u00e0 consentito fino alla capienza massima consentita dalle regole Covid-19.<\/p>\n<p>In allegato l&#8217;ordine del giorno del Consiglio Comunale e la locandina dell&#8217;evento.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_718\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/05\/CONVOCAZIONE-CONSIGLIO.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/05\/CONVOCAZIONE-CONSIGLIO.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>CONVOCAZIONE CONSIGLIO<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Consiglio Comunale \u00e8 stato convocato in seduta straordinaria per sabato 5 giugno alle ore 18:00 e si terr\u00e0 c\/o Sala Vittoria in P.zza Marconi per il conferimento della cittadinanza [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":719,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna - sabato 5 giugno ore 18 Sala Vittoria - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna - sabato 5 giugno ore 18 Sala Vittoria - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Il Consiglio Comunale \u00e8 stato convocato in seduta straordinaria per sabato 5 giugno alle ore 18:00 e si terr\u00e0 c\/o Sala Vittoria in P.zza Marconi per il conferimento della cittadinanza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-28T06:42:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-03T06:31:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/05\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"1072\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna &#8211; sabato 5 giugno ore 18 Sala Vittoria\",\"datePublished\":\"2021-05-28T06:42:11+00:00\",\"dateModified\":\"2021-06-03T06:31:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/05\\\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/\",\"name\":\"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna - sabato 5 giugno ore 18 Sala Vittoria - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/05\\\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg\",\"datePublished\":\"2021-05-28T06:42:11+00:00\",\"dateModified\":\"2021-06-03T06:31:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/05\\\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/05\\\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg\",\"width\":750,\"height\":1072},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/05\\\/28\\\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna &#8211; sabato 5 giugno ore 18 Sala Vittoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna - sabato 5 giugno ore 18 Sala Vittoria - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna - sabato 5 giugno ore 18 Sala Vittoria - Fagagna","og_description":"Il Consiglio Comunale \u00e8 stato convocato in seduta straordinaria per sabato 5 giugno alle ore 18:00 e si terr\u00e0 c\/o Sala Vittoria in P.zza Marconi per il conferimento della cittadinanza [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-05-28T06:42:11+00:00","article_modified_time":"2021-06-03T06:31:35+00:00","og_image":[{"width":750,"height":1072,"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/05\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg","type":"image\/jpeg"}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna &#8211; sabato 5 giugno ore 18 Sala Vittoria","datePublished":"2021-05-28T06:42:11+00:00","dateModified":"2021-06-03T06:31:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/"},"wordCount":121,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/05\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/","url":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/","name":"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna - sabato 5 giugno ore 18 Sala Vittoria - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/05\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg","datePublished":"2021-05-28T06:42:11+00:00","dateModified":"2021-06-03T06:31:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/05\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/05\/007e836e-0fae-46b0-960f-bb0b4045d8d7.jpg","width":750,"height":1072},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/05\/28\/convocazione-cons-comunale-per-cittadinanza-al-milite-ignoto-e-presentazione-volume-alpini-a-fagagna-sabato-5-giugno-ore-18-sala-vittoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Convocazione Cons. Comunale per cittadinanza al milite ignoto e presentazione volume Alpini a Fagagna &#8211; sabato 5 giugno ore 18 Sala Vittoria"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"53.346881","longitude":"-6.25886","zoom":"16"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=717"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/717\/revisions"}],"predecessor-version":[{"id":720,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/717\/revisions\/720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media\/719"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}