{"id":891,"date":"2021-07-29T09:52:14","date_gmt":"2021-07-29T07:52:14","guid":{"rendered":"https:\/\/comunicacity.net\/fagagna\/?p=891"},"modified":"2021-07-29T09:52:14","modified_gmt":"2021-07-29T07:52:14","slug":"art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/","title":{"rendered":"Art Tal Ort 2021 &#8211; 31 luglio-1 agosto colline di Fagagna"},"content":{"rendered":"<p><strong>Sabato 31 luglio e domenica 1 agosto<\/strong> le colline di Fagagna ospiteranno anche quest&#8217;anno la 12a edizione del festival d&#8217;arte per strada Art Tal Ort, a cura di Felici ma Furlans con il sostegno dell&#8217;Amministrazione Comunale.<\/p>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"vc_column-inner \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_right-to-left h5nonupper wpb_start_animation\">\n<div class=\"wpb_wrapper\">\n<p>Anche quest\u2019anno, per poter rispettare le norme dovute all\u2019emergenza sanitaria, il festival sar\u00e0 collocato su due colline. La collina del Castello, dedicata a spettacoli teatrali ed alle arti visive, vedr\u00e0 lo stesso programma replicato per quattro volte: sabato e domenica, pomeriggio e sera, in modo da poter accontentare il vasto pubblico. <span class=\"color01\" style=\"font-size: 16px\"><span lang=\"it-IT\">La \u201cMont dai Pins\u201d (Collina dei pini), sar\u00e0 invece dedicata ad una programmazione multidisciplinare il sabato (danza, musica, teatro, illustrazione) e musicale la domenica.<\/span><\/span><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"wpb_column vc_column_container vc_col-sm-6\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element wpb_animate_when_almost_visible wpb_right-to-left h5nonupper wpb_start_animation\">\n<div class=\"wpb_wrapper\">\n<p>Per l&#8217;acquisto dei biglietti \u00e8 consigliato l&#8217;acquisto online (per facilitare il contingentamento degli spettatori), ma sar\u00e0 possibile farlo anche all&#8217;ingresso con un sovrapprezzo di 2\u20ac, fino ad esaurimento posti.<\/p>\n<p>Su www.arttalort.it trovate tutte le informazioni su programma e biglietti.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Sabato 31 luglio e domenica 1 agosto le colline di Fagagna ospiteranno anche quest&#8217;anno la 12a edizione del festival d&#8217;arte per strada Art Tal Ort, a cura di Felici ma [&hellip;]<\/p>\n","protected":false},"author":357,"featured_media":892,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-891","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Art Tal Ort 2021 - 31 luglio-1 agosto colline di Fagagna - Fagagna<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Art Tal Ort 2021 - 31 luglio-1 agosto colline di Fagagna - Fagagna\" \/>\n<meta property=\"og:description\" content=\"Sabato 31 luglio e domenica 1 agosto le colline di Fagagna ospiteranno anche quest&#8217;anno la 12a edizione del festival d&#8217;arte per strada Art Tal Ort, a cura di Felici ma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/\" \/>\n<meta property=\"og:site_name\" content=\"Fagagna\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-29T07:52:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/cover-SITO-tagliataok-1536x864-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"864\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cpecile\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"cpecile\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/\"},\"author\":{\"name\":\"cpecile\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\"},\"headline\":\"Art Tal Ort 2021 &#8211; 31 luglio-1 agosto colline di Fagagna\",\"datePublished\":\"2021-07-29T07:52:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/07\\\/cover-SITO-tagliataok-1536x864-1.png\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/\",\"name\":\"Art Tal Ort 2021 - 31 luglio-1 agosto colline di Fagagna - Fagagna\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/07\\\/cover-SITO-tagliataok-1536x864-1.png\",\"datePublished\":\"2021-07-29T07:52:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/07\\\/cover-SITO-tagliataok-1536x864-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2021\\\/07\\\/cover-SITO-tagliataok-1536x864-1.png\",\"width\":1536,\"height\":864},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/2021\\\/07\\\/29\\\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art Tal Ort 2021 &#8211; 31 luglio-1 agosto colline di Fagagna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"name\":\"Fagagna\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/fagagna\\\/wp-content\\\/uploads\\\/sites\\\/171\\\/2019\\\/12\\\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg\",\"width\":1600,\"height\":900,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/#\\\/schema\\\/person\\\/7bdca9633819067f7042c8477a953b32\",\"name\":\"cpecile\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g\",\"caption\":\"cpecile\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/fagagna\\\/author\\\/cpecile\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Art Tal Ort 2021 - 31 luglio-1 agosto colline di Fagagna - Fagagna","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/","og_locale":"it_IT","og_type":"article","og_title":"Art Tal Ort 2021 - 31 luglio-1 agosto colline di Fagagna - Fagagna","og_description":"Sabato 31 luglio e domenica 1 agosto le colline di Fagagna ospiteranno anche quest&#8217;anno la 12a edizione del festival d&#8217;arte per strada Art Tal Ort, a cura di Felici ma [&hellip;]","og_url":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/","og_site_name":"Fagagna","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-07-29T07:52:14+00:00","og_image":[{"width":1536,"height":864,"url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/cover-SITO-tagliataok-1536x864-1.png","type":"image\/png"}],"author":"cpecile","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"cpecile","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/"},"author":{"name":"cpecile","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32"},"headline":"Art Tal Ort 2021 &#8211; 31 luglio-1 agosto colline di Fagagna","datePublished":"2021-07-29T07:52:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/"},"wordCount":159,"publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/cover-SITO-tagliataok-1536x864-1.png","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/","url":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/","name":"Art Tal Ort 2021 - 31 luglio-1 agosto colline di Fagagna - Fagagna","isPartOf":{"@id":"https:\/\/comunicacity.net\/fagagna\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/cover-SITO-tagliataok-1536x864-1.png","datePublished":"2021-07-29T07:52:14+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/#primaryimage","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/cover-SITO-tagliataok-1536x864-1.png","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2021\/07\/cover-SITO-tagliataok-1536x864-1.png","width":1536,"height":864},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/fagagna\/2021\/07\/29\/art-tal-ort-2021-31-luglio-1-agosto-colline-di-fagagna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/fagagna\/"},{"@type":"ListItem","position":2,"name":"Art Tal Ort 2021 &#8211; 31 luglio-1 agosto colline di Fagagna"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/fagagna\/#website","url":"https:\/\/comunicacity.net\/fagagna\/","name":"Fagagna","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/fagagna\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/fagagna\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/fagagna\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/fagagna\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","contentUrl":"https:\/\/comunicacity.net\/fagagna\/wp-content\/uploads\/sites\/171\/2019\/12\/Il-Museo-Cjase-Coc\u00e8l-interno.jpg","width":1600,"height":900,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/fagagna\/#\/schema\/person\/7bdca9633819067f7042c8477a953b32","name":"cpecile","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/893c2ebc0eb2fff2e9e31e55f9bad3244e44f08e8ea9d12fa95db6943b36c8b0?s=96&d=mm&r=g","caption":"cpecile"},"url":"https:\/\/comunicacity.net\/fagagna\/author\/cpecile\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/users\/357"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/comments?post=891"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/891\/revisions"}],"predecessor-version":[{"id":893,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/posts\/891\/revisions\/893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media\/892"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/media?parent=891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/categories?post=891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/fagagna\/wp-json\/wp\/v2\/tags?post=891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}